{"id":31850,"date":"2020-07-09T11:30:14","date_gmt":"2020-07-09T14:30:14","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=31850"},"modified":"2020-07-09T11:30:14","modified_gmt":"2020-07-09T14:30:14","slug":"pavilhao-luterano-no-bairro-bom-pastor-de-igrejinha-recebe-doacoes","status":"publish","type":"post","link":"http:\/\/sol.fm.br\/radio\/pavilhao-luterano-no-bairro-bom-pastor-de-igrejinha-recebe-doacoes\/","title":{"rendered":"Pavilh\u00e3o Luterano no Bairro Bom Pastor de Igrejinha recebe doa\u00e7\u00f5es"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>Novamente a comunidade de Igrejinha est\u00e1 dando uma verdadeira li\u00e7\u00e3o de amor ao pr\u00f3ximo. Devido \u00e0s cheias do Rio Paranhana, dezenas de fam\u00edlias tiveram suas casas invadidas pela \u00e1gua e uma corrente de solidariedade se formou com doa\u00e7\u00f5es de colch\u00f5es, cobertores, travesseiros, agasalhos. alimentos e produtos de limpeza. Cada um doando aquilo que pode, com o \u00fanico objetivo de amenizar o sofrimento dos atingidos.<\/p>\n<p>O Pavilh\u00e3o Luterano no Bairro Bom Pastor come\u00e7ou a receber as doa\u00e7\u00f5es, ainda na madrugada de ontem, enquanto o Paranhana ainda subia, e assim continuou durante todo o dia. No final da tarde equipes da Assist\u00eancia Social e volunt\u00e1rios coordenados pelo Prefeito Joel Wilhelm come\u00e7aram a distribuir as doa\u00e7\u00f5es para amenizar e levar um pouco de alento \u00e0s fam\u00edlias que necessitam de aux\u00edlio.<\/p>\n<p>Para o Prefeito Joel, a solidariedade est\u00e1 no DNA dos igrejinhenses. \"S\u00f3 temos a agradecer, como poder p\u00fablico, o empenho de todos que se mobilizaram e que ainda est\u00e3o se mobilizando para ajudar nesse momento dif\u00edcil.\"<\/p>\n<hr \/>\n<h6><strong>Prefeitura Municipal de Igrejinha<\/strong><\/h6>\n<p><center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Novamente a comunidade de Igrejinha est\u00e1 dando uma verdadeira li\u00e7\u00e3o de amor ao pr\u00f3ximo. Devido \u00e0s cheias do Rio Paranhana, dezenas de fam\u00edlias tiveram suas casas invadidas pela \u00e1gua e uma corrente de solidariedade se formou com doa\u00e7\u00f5es de colch\u00f5es, cobertores, travesseiros, agasalhos. alimentos e produtos de limpeza. Cada um doando aquilo que pode, com [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31853,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=31850"}],"version-history":[{"count":1,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31850\/revisions"}],"predecessor-version":[{"id":31854,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31850\/revisions\/31854"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/31853"}],"wp:attachment":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=31850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=31850"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=31850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}