{"id":31885,"date":"2020-07-10T12:16:26","date_gmt":"2020-07-10T15:16:26","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=31885"},"modified":"2020-07-10T12:16:26","modified_gmt":"2020-07-10T15:16:26","slug":"rolante-participa-de-concurso-internacional-de-sustentabilidade","status":"publish","type":"post","link":"http:\/\/sol.fm.br\/radio\/rolante-participa-de-concurso-internacional-de-sustentabilidade\/","title":{"rendered":"Rolante participa de Concurso Internacional de Sustentabilidade"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>O munic\u00edpio de Rolante, atrav\u00e9s do Departamento de Turismo, est\u00e1 participando do concurso SUSTAINABLE TOP 100 DESTINATIONS, que, como o nome j\u00e1 diz, selecionar\u00e1 os 100 melhores destinos sustent\u00e1veis do mundo!<\/p>\n<p>A participa\u00e7\u00e3o no concurso foi incentivada pelo Programa Rede DEL Turismo, como forma de elucidar os munic\u00edpios sobre as dimens\u00f5es da sustentabilidade e incentivar a ado\u00e7\u00e3o de pr\u00e1ticas sustent\u00e1veis tanto pelo destino, quanto pelos turistas. O processo de inscri\u00e7\u00e3o foi elaborado Coordenadora de Turismo, Diuly M\u00e4hler e pelo Secret\u00e1rio Municipal de Gest\u00e3o Administrativa e Financeira Evandro Lembi, integrantes da equipe do DEL Rolante.<\/p>\n<p>Para participar, munic\u00edpios estreantes como Rolante, tiveram que preencher 15 crit\u00e9rios e elaborar um \u201crelato de boas pr\u00e1ticas\u201d sobre a\u00e7\u00f5es sustent\u00e1veis empreendidas no munic\u00edpio. Rolante se cadastrou com dois projetos: o do Cicloturismo e Ambientistas Mirins. \u201cO concurso iniciou em 2015 at\u00e9 o ano passado somente duas cidades brasileiras participaram, uma delas, Fernando de Noronha. Este ano, por conta do DEL Turismo, 10 munic\u00edpios brasileiros concorrem entre si, entre eles, Rolante\u201d, explica Diuly.<\/p>\n<p>Para o Secret\u00e1rio Evandro Lembi, a oportunidade de participar j\u00e1 \u00e9 uma vit\u00f3ria. \u201c\u00c9 importante para o munic\u00edpio estar concorrendo com grandes destinos do mundo, claro, e vamos torcer para ficar entre os 100 destinos, mas vale muito tamb\u00e9m pelo aprendizado, para ver os pontos em que j\u00e1 estamos no caminho certo e avaliar os que precisamos melhorar\u201d, considerou.<\/p>\n<p>Al\u00e9m do privil\u00e9gio da participa\u00e7\u00e3o \u2013 que neste ano, em fun\u00e7\u00e3o da pandemia teve inscri\u00e7\u00e3o gratuita \u2013 a turism\u00f3loga destaca os aprendizados adquiridos na troca de informa\u00e7\u00f5es e na elabora\u00e7\u00e3o dos relatos de boas pr\u00e1ticas. \u201cCom os dados que inserimos na plataforma, temos hoje um relat\u00f3rio da sustentabilidade, que serviu pra gente entender melhor o que podemos fazer e melhorar em termos de sustentabilidade no munic\u00edpio. Al\u00e9m da grande visibilidade, sendo um concurso internacional. Foi bacana tamb\u00e9m o trabalho em equipe durante a elabora\u00e7\u00e3o e troca de informa\u00e7\u00f5es com integrantes do DEL de outras cidades e Estados, um ajudou o outro, teve muita parceria, troca de ideias e o principal objetivo \u00e9 fazer com que todos os munic\u00edpios cres\u00e7am\u201d, contou Diuly.<\/p>\n<p>O resultado da premia\u00e7\u00e3o ser\u00e1 divulgado no m\u00eas de outubro. At\u00e9 l\u00e1, vamos torcer pela nossa cidade!<\/p>\n<hr \/>\n<h6><strong>C\u00e1ssia Souza<\/strong><br \/>\n<strong>Jornalista DRT 011663<\/strong><br \/>\n<strong>Assessora de Comunica\u00e7\u00e3o<\/strong><br \/>\n<strong>Prefeitura Municipal de Rolante<\/strong><\/h6>\n<p><center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Rolante, atrav\u00e9s do Departamento de Turismo, est\u00e1 participando do concurso SUSTAINABLE TOP 100 DESTINATIONS, que, como o nome j\u00e1 diz, selecionar\u00e1 os 100 melhores destinos sustent\u00e1veis do mundo! A participa\u00e7\u00e3o no concurso foi incentivada pelo Programa Rede DEL Turismo, como forma de elucidar os munic\u00edpios sobre as dimens\u00f5es da sustentabilidade e incentivar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=31885"}],"version-history":[{"count":1,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31885\/revisions"}],"predecessor-version":[{"id":31888,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/31885\/revisions\/31888"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/31887"}],"wp:attachment":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=31885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=31885"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=31885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}