{"id":37605,"date":"2021-03-02T11:54:26","date_gmt":"2021-03-02T14:54:26","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=37605"},"modified":"2021-03-02T11:54:26","modified_gmt":"2021-03-02T14:54:26","slug":"secretaria-de-saude-de-taquara-alerta-para-possivel-falta-de-atendimento-medico-em-ubss","status":"publish","type":"post","link":"http:\/\/sol.fm.br\/radio\/secretaria-de-saude-de-taquara-alerta-para-possivel-falta-de-atendimento-medico-em-ubss\/","title":{"rendered":"Secretaria de Sa\u00fade de Taquara alerta para poss\u00edvel falta de atendimento m\u00e9dico em UBSs"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p><em>Profissionais est\u00e3o sendo remanejados para linha de frente da Covid ou pedindo afastamento em raz\u00e3o de sintomas da doen\u00e7a<\/em><\/p>\n<p>A superlota\u00e7\u00e3o do Hospital Bom Jesus e do Centro Covid com casos de infectados pelo novo coronav\u00edrus est\u00e1 gerando reflexos no atendimento na rede b\u00e1sica. Com a falta de m\u00e9dicos, que acabam tamb\u00e9m se contaminando com o v\u00edrus, a Secretaria da Sa\u00fade de Taquara alerta para poss\u00edveis remanejamentos destes profissionais das Unidades B\u00e1sicas de Sa\u00fade (UBSs) para atuar na linha de frente da pandemia.<\/p>\n<p>\u201cPode ser que numa determinada UBS, durante algum turno, a popula\u00e7\u00e3o fique desassistida de consulta m\u00e9dica. Estamos trabalhando ao m\u00e1ximo para fechar todos os hor\u00e1rios, em conversa direta com a Ga\u00fachaMed, terceirizada que nos oferece profissionais, para n\u00e3o deixar nossos moradores desassistidos. Por\u00e9m, pedimos a coopera\u00e7\u00e3o de todos para situa\u00e7\u00f5es pontuais\", explicou a secret\u00e1ria Ana Maria Rodrigues.<\/p>\n<p>Nesta segunda, seis leitos de UTI Covid foram instalados no HBJ e est\u00e3o em opera\u00e7\u00e3o. Ana explica que este incremento far\u00e1 parte do mapa de leitos do Estado. \u201cNo entanto, assim que ficam dispon\u00edveis os mesmos j\u00e1 v\u00e3o sendo ocupados, pois temos muitos pacientes na emerg\u00eancia que poder\u00e3o precisar dos referidos leitos. A situa\u00e7\u00e3o \u00e9 muito cr\u00edtica, por isso refor\u00e7amos que todos fa\u00e7am a sua parte e evitar aglomera\u00e7\u00e3o, ficar em suas casas o m\u00e1ximo poss\u00edvel, para fazermos o v\u00edrus parar de circular\u201d, destacou.<\/p>\n<hr \/>\n<h6><strong>Prefeitura Municipal de Taquara<\/strong><\/h6>\n<p><center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Profissionais est\u00e3o sendo remanejados para linha de frente da Covid ou pedindo afastamento em raz\u00e3o de sintomas da doen\u00e7a A superlota\u00e7\u00e3o do Hospital Bom Jesus e do Centro Covid com casos de infectados pelo novo coronav\u00edrus est\u00e1 gerando reflexos no atendimento na rede b\u00e1sica. Com a falta de m\u00e9dicos, que acabam tamb\u00e9m se contaminando com [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":37606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-37605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/37605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=37605"}],"version-history":[{"count":1,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/37605\/revisions"}],"predecessor-version":[{"id":37608,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/37605\/revisions\/37608"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/37606"}],"wp:attachment":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=37605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=37605"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=37605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}