{"id":78737,"date":"2025-10-02T09:44:57","date_gmt":"2025-10-02T12:44:57","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=78737"},"modified":"2025-10-02T09:45:02","modified_gmt":"2025-10-02T12:45:02","slug":"4o-seminario-estadual-de-prendas-mirins-e-pias-do-rs-sera-realizado-em-parobe","status":"publish","type":"post","link":"http:\/\/sol.fm.br\/radio\/4o-seminario-estadual-de-prendas-mirins-e-pias-do-rs-sera-realizado-em-parobe\/","title":{"rendered":"4\u00ba Semin\u00e1rio Estadual de Prendas Mirins e Pi\u00e1s do RS ser\u00e1 realizado em Parob\u00e9"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>O munic\u00edpio de Parob\u00e9 ser\u00e1 sede do 4\u00ba Semin\u00e1rio Estadual de Prendas Mirins e Pi\u00e1s do Rio Grande do Sul, que acontecer\u00e1 no pr\u00f3ximo 11 de outubro, no Barrac\u00e3o Cat\u00f3lico, localizado no Centro da cidade. O encontro reunir\u00e1 crian\u00e7as e jovens das 30 regi\u00f5es tradicionalistas do Estado, em um dia de integra\u00e7\u00e3o, aprendizado e valoriza\u00e7\u00e3o da cultura ga\u00facha. O evento \u00e9 uma realiza\u00e7\u00e3o da 22\u00aa Regi\u00e3o Tradicionalista, com apoio da Prefeitura de Parob\u00e9, e promo\u00e7\u00e3o do Movimento Tradicionalista Ga\u00facho (MTG) e da Funda\u00e7\u00e3o Cultural Ga\u00facha (FCG). A anfitri\u00e3 do encontro \u00e9 a 1\u00aa Prenda Mirim do RS, Isabeli de Lima, moradora de Parob\u00e9.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Programa\u00e7\u00e3o<\/strong><\/p>\n<p>A programa\u00e7\u00e3o inicia \u00e0s 8h, com credenciamento, seguido pela solenidade de abertura \u00e0s 8h30, com a presen\u00e7a de autoridades civis e tradicionalistas. Logo em seguida, \u00e0s 9h15, a tradicionalista Vania In\u00eas \u00c1vila Priano ministrar\u00e1 a palestra \u201cColoniza\u00e7\u00e3o Alem\u00e3\u201d, trazendo reflex\u00f5es sobre a contribui\u00e7\u00e3o cultural desse povo para o Rio Grande do Sul.<\/p>\n<p>Durante todo o dia, as prendas mirins e pi\u00e1s apresentar\u00e3o seus projetos inspirados na tem\u00e1tica: \u201cDe cada povo, uma heran\u00e7a! De cada brincadeira, uma lembran\u00e7a\u201d.O evento tamb\u00e9m contar\u00e1 com apresenta\u00e7\u00f5es culturais e atividades de integra\u00e7\u00e3o, encerrando \u00e0s 18h.<\/p>\n<p>A 1\u00aa Prenda Mirim do RS, Isabeli de Lima, destaca a alegria de sediar a quarta edi\u00e7\u00e3o em sua cidade. <em>\u201cPara mim, ser anfitri\u00e3 deste grande evento \u00e9 uma alegria e tamb\u00e9m uma honra. Vai al\u00e9m de organizar, \u00e9 cuidar de cada detalhe para que todos se sintam acolhidos e felizes. Os mirins podem esperar um encontro cheio de divers\u00e3o, aprendizado e momentos de integra\u00e7\u00e3o\u201d<\/em>, afirma Isabeli.<\/p>\n<p>J\u00e1 o coordenador da 22\u00aa RT, Jo\u00e3o Machado, destaca a relev\u00e2ncia cultural do Semin\u00e1rio para as tradi\u00e7\u00f5es ga\u00fachas. Segundo ele, o evento promove um verdadeiro resgate dos brinquedos e brincadeiras que marcaram gera\u00e7\u00f5es. <em>\u201cTeremos a participa\u00e7\u00e3o de integrantes das 30 Regi\u00f5es Tradicionalistas, o que refor\u00e7a o car\u00e1ter regional e de integra\u00e7\u00e3o. Al\u00e9m disso, \u00e9 um espa\u00e7o onde as crian\u00e7as vivenciam a cultura de forma l\u00fadica, preservando valores e tradi\u00e7\u00f5es de diferentes povos do Rio Grande do Sul. O Semin\u00e1rio Mirim tem esse dom de unir e, ao mesmo tempo, resgatar as nossas ra\u00edzes por meio das brincadeiras e dos brinquedos.<\/em>\u201d<\/p>\n<p>\u00a0<\/p>\n<p><strong>A\u00e7\u00e3o social<\/strong><\/p>\n<p>Al\u00e9m da programa\u00e7\u00e3o cultural e formativa, o semin\u00e1rio ter\u00e1 uma campanha solid\u00e1ria: \u201cDoe um brinquedo\u201d. As doa\u00e7\u00f5es arrecadadas ser\u00e3o destinadas \u00e0 Secretaria Municipal de Assist\u00eancia Social de Parob\u00e9, beneficiando crian\u00e7as do munic\u00edpio.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Origem do Semin\u00e1rio Estadual de Prendas Mirins e Pi\u00e1s do RS<\/strong><\/p>\n<p>O Semin\u00e1rio Estadual de Prendas Mirins e Pi\u00e1s do Rio Grande do Sul teve sua primeira edi\u00e7\u00e3o em 15 de outubro de 2022, na cidade de Iju\u00ed, durante a Expofest \u2013 Festa Internacional das Etnias.<\/p>\n<p>A iniciativa partiu da gest\u00e3o estadual de prendas mirins composta por Katarine Peripolli Dias (1\u00aa Prenda Mirim do RS), Dara Netto (2\u00aa Prenda Mirim do RS) e Ana L\u00edvia Pol\u00f4nia Fr\u00f6hlich (3\u00aa Prenda Mirim do RS).<\/p>\n<p>Desde ent\u00e3o, o semin\u00e1rio \u00e9 um espa\u00e7o para que os pequenos tradicionalistas aprofundem seus conhecimentos, valorizem a cultura ga\u00facha e compartilhem experi\u00eancias. E, de prefer\u00eancia, ocorre na cidade da 1\u00aa Prenda Mirim do RS do ano vigente.\u00a0(Fonte: MTG)<\/p>\n<hr \/>\n<h6><strong>Faculdades Integradas de Taquara - Faccat |\u00a0Texto: Jornalista Claucia F da Silva \u2013 Assessora de Imprensa da 22\u00aaRT | Foto: SPGG RS - Secretaria de Planejamento, Governan\u00e7a e Gest\u00e3o do RS<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Parob\u00e9 ser\u00e1 sede do 4\u00ba Semin\u00e1rio Estadual de Prendas Mirins e Pi\u00e1s do Rio Grande do Sul, que acontecer\u00e1 no pr\u00f3ximo 11 de outubro, no Barrac\u00e3o Cat\u00f3lico, localizado no Centro da cidade. O encontro reunir\u00e1 crian\u00e7as e jovens das 30 regi\u00f5es tradicionalistas do Estado, em um dia de integra\u00e7\u00e3o, aprendizado e valoriza\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":78739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-78737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=78737"}],"version-history":[{"count":1,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78737\/revisions"}],"predecessor-version":[{"id":78740,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78737\/revisions\/78740"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/78739"}],"wp:attachment":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=78737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=78737"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=78737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}