{"id":78754,"date":"2025-10-02T11:15:41","date_gmt":"2025-10-02T14:15:41","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=78754"},"modified":"2025-10-02T11:15:43","modified_gmt":"2025-10-02T14:15:43","slug":"governo-do-brasil-lanca-campanha-para-vacinar-criancas-e-adolescentes-de-ate-15-anos","status":"publish","type":"post","link":"http:\/\/sol.fm.br\/radio\/governo-do-brasil-lanca-campanha-para-vacinar-criancas-e-adolescentes-de-ate-15-anos\/","title":{"rendered":"Governo do Brasil lan\u00e7a campanha para vacinar crian\u00e7as e adolescentes de at\u00e9 15 anos"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><div class=\"documentDescription\" style=\"text-align: center;\"><em>Imuniza\u00e7\u00e3o ser\u00e1 realizada de 6 a 31 de outubro em todo o pa\u00eds. Foram distribu\u00eddas mais de 6,8 milh\u00f5es de doses para a a\u00e7\u00e3o<\/em><\/div>\n<div>\u00a0<\/div>\n<div id=\"viewlet-above-content-body\">\n<div id=\"content-core\">\n<div id=\"parent-fieldname-text\" class=\"\">\n<div>\n<p>O Governo do Brasil lan\u00e7ou, nesta quarta-feira, 1\u00ba de outubro, uma Campanha Nacional de Multivacina\u00e7\u00e3o voltada para o p\u00fablico de at\u00e9 15 anos de idade. Mais de 6,8 milh\u00f5es de doses foram distribu\u00eddas para a a\u00e7\u00e3o que ser\u00e1 realizada entre os dias 6 e 31 de outubro. O Dia D de mobiliza\u00e7\u00e3o est\u00e1 marcado para o dia 18\/10 \u2014 ser\u00e1 um s\u00e1bado em que os postos de sa\u00fade ficar\u00e3o abertos para proteger todas as fam\u00edlias.<\/p>\n<p>O ministro da Sa\u00fade, Alexandre Padilha, destacou que todos os dias s\u00e3o dias de vacina\u00e7\u00e3o nas Unidades B\u00e1sicas de Sa\u00fade, mas o 18 de outubro ser\u00e1 \u201c<em>uma oportunidade estrat\u00e9gica para mobilizarmos, juntamente com estados e munic\u00edpios, as localidades com maior concentra\u00e7\u00e3o de crian\u00e7as, garantindo que todas sejam protegidas durante o Dia D\u201d.<\/em><\/p>\n<p class=\"callout\"><strong>R$ 150 MILH\u00d5ES<\/strong>\u00a0\u2014 A vacina\u00e7\u00e3o seguir\u00e1 a estrat\u00e9gia de microplanejamento, que permite organizar a\u00e7\u00f5es de acordo com a realidade de cada territ\u00f3rio, identificando \u00e1reas de risco, locais com baixa ades\u00e3o e espa\u00e7os estrat\u00e9gicos para a vacina\u00e7\u00e3o. O Minist\u00e9rio da Sa\u00fade repassou R$ 150 milh\u00f5es em apoio \u00e0s gest\u00f5es locais.<br \/><br \/>A campanha ocorre em um momento de aten\u00e7\u00e3o redobrada para a sa\u00fade p\u00fablica. Embora o Brasil tenha eliminado doen\u00e7as como poliomielite e sarampo, \u00e9 fundamental manter altas coberturas vacinais para evitar que esses v\u00edrus voltem a circular.<\/p>\n<p><strong>SUS DIGITAL<\/strong>\u00a0\u2014 Al\u00e9m da divulga\u00e7\u00e3o das pe\u00e7as da campanha e mobiliza\u00e7\u00e3o nos estados e munic\u00edpios, o Minist\u00e9rio da Sa\u00fade far\u00e1 chamamento pelo Meu SUS Digital. Ser\u00e3o enviados alertas a todos os usu\u00e1rios do aplicativo, com expectativa de chegar a 40 milh\u00f5es de pessoas. A ferramenta est\u00e1 dispon\u00edvel nas vers\u00f5es Web e em aplicativos iOS e Android. Para acessar o Meu SUS Digital, \u00e9 necess\u00e1rio instalar o aplicativo no dispositivo m\u00f3vel ou acessar pelo site. O login \u00e9 realizado por meio da conta pessoal do Gov.br.<\/p>\n<p class=\"callout\"><strong>CADERNETA<\/strong>\u00a0\u2014 A Caderneta Digital de Sa\u00fade da Crian\u00e7a est\u00e1 dispon\u00edvel pelo aplicativo. Pelo Meu SUS Digital, pais e respons\u00e1veis podem acompanhar a situa\u00e7\u00e3o vacinal de crian\u00e7as e adolescentes, com a previs\u00e3o de pr\u00f3ximas doses, receber e alertas e lembretes, al\u00e9m de atualizar informa\u00e7\u00f5es em tempo real pela Rede Nacional de Dados em Sa\u00fade (RNDS). Desde o lan\u00e7amento, em abril deste ano, j\u00e1 foram registrados 1,8 milh\u00e3o de acessos.<\/p>\n<p><strong>VACINAS<\/strong>\u00a0\u2014 Durante a campanha, todas as vacinas previstas no Calend\u00e1rio Nacional de Vacina\u00e7\u00e3o 2025 estar\u00e3o dispon\u00edveis, incluindo imunizantes contra poliomielite e covid-19, contemplando os esquemas vacinais de crian\u00e7as e adolescentes. Entre as prioridades, est\u00e3o o resgate de n\u00e3o vacinados contra HPV, febre amarela e sarampo.<\/p>\n<p class=\"callout\"><strong>SARAMPO<\/strong>\u00a0\u2014 A campanha vai refor\u00e7ar a vacina\u00e7\u00e3o contra o sarampo, diante da escalada de casos na Am\u00e9rica do Norte, que concentra 99% dos casos no continente, que somam 7 mil. Toda a popula\u00e7\u00e3o de 12 meses a 59 anos poder\u00e1 se vacinar contra a doen\u00e7a no pa\u00eds, refor\u00e7ando a prote\u00e7\u00e3o e prevenindo a reintrodu\u00e7\u00e3o da doen\u00e7a no Brasil.<br \/><br \/>As a\u00e7\u00f5es adotadas pelo Minist\u00e9rio da Sa\u00fade, em parceria com os estados e munic\u00edpios, t\u00eam mantido o Brasil livre da circula\u00e7\u00e3o do sarampo. Entre as preocupa\u00e7\u00f5es est\u00e3o as pessoas que viajam para o exterior, em pa\u00edses com elevado registro de casos, e quem vive em regi\u00e3o de fronteira, principalmente com a Bol\u00edvia. Em 2025, at\u00e9 o momento, foram confirmados 31 casos importados, quando a infec\u00e7\u00e3o ocorre fora do pa\u00eds.<\/p>\n<p><strong>HPV<\/strong>\u00a0\u2014 Al\u00e9m disso, haver\u00e1 resgate de n\u00e3o vacinados contra o HPV na faixa et\u00e1ria de 15 a 19 anos. O Brasil avan\u00e7ou na vacina\u00e7\u00e3o contra o HPV, atingindo 82% de cobertura em em 2024 considerando meninas de 9 a 14 anos - \u00e9 quase sete vezes maior que a m\u00e9dia global de 12% divulgada pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS). Entre os meninos da mesma faixa et\u00e1ria, a cobertura chegou a 67%.<\/p>\n<p>A vacina, que protege contra diversos tipos de c\u00e2ncer \u2014 como colo do \u00fatero, \u00e2nus, p\u00eanis, garganta e pesco\u00e7o \u2014 al\u00e9m de verrugas genitais, apresentou avan\u00e7o expressivo: entre meninas, a cobertura passou de 78,42% em 2022 para 82,83% em 2024; j\u00e1 entre os meninos, saltou de 45,46% para 67,26%, representando crescimento de 22% em apenas dois anos.<\/p>\n<p class=\"callout\"><strong>FEBRE AMARELA<\/strong>\u00a0\u2014 Nos estados de S\u00e3o Paulo, Rio de Janeiro, Minas Gerais e Paran\u00e1, o Minist\u00e9rio da Sa\u00fade recomenda a intensifica\u00e7\u00e3o da vacina\u00e7\u00e3o contra a febre amarela, ofertando a atualiza\u00e7\u00e3o da situa\u00e7\u00e3o vacinal de pessoas de 9 meses a 59 anos, conforme as diretrizes do PNI.<\/p>\n<p><strong>AVAN\u00c7O NA COBERTURA<\/strong>\u00a0\u2014 Desde 2023, o Governo do Brasil tem promovido um esfor\u00e7o nacional de recupera\u00e7\u00e3o vacinal. Entre os principais progressos alcan\u00e7ados est\u00e3o a eleva\u00e7\u00e3o das coberturas de vacinas e a garantia do abastecimento de doses a estados e munic\u00edpios.<\/p>\n<p>Entre 2022 e 2024, o Brasil avan\u00e7ou na prote\u00e7\u00e3o de crian\u00e7as menores de 2 anos. A vacina\u00e7\u00e3o contra a p\u00f3lio cresceu 17% no per\u00edodo, enquanto a da tr\u00edplice viral (sarampo, caxumba e rub\u00e9ola) aumentou quase 40%. A vacina Penta, que protege contra cinco doen\u00e7as em uma s\u00f3 aplica\u00e7\u00e3o, tamb\u00e9m registrou crescimento expressivo, de 17%.<\/p>\n<p>A cobertura vacinal contra o sarampo tamb\u00e9m aumentou: a aplica\u00e7\u00e3o da primeira dose da tr\u00edplice viral passou de 80,7% em 2022 para 95,7% em 2024. J\u00e1 a segunda dose subiu de 57,6% em 2022 para 80,1% em 2024.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<hr \/>\n<h6 id=\"formfield-form-widgets-categoria\" class=\"field z3cformInlineValidation\"><strong>GOV BR | Secretaria de Comunica\u00e7\u00e3o Social | Foto: Walterson Rosa\/MS<\/strong><\/h6>\n<\/div>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Imuniza\u00e7\u00e3o ser\u00e1 realizada de 6 a 31 de outubro em todo o pa\u00eds. Foram distribu\u00eddas mais de 6,8 milh\u00f5es de doses para a a\u00e7\u00e3o \u00a0 O Governo do Brasil lan\u00e7ou, nesta quarta-feira, 1\u00ba de outubro, uma Campanha Nacional de Multivacina\u00e7\u00e3o voltada para o p\u00fablico de at\u00e9 15 anos de idade. Mais de 6,8 milh\u00f5es de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":78755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-78754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=78754"}],"version-history":[{"count":1,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78754\/revisions"}],"predecessor-version":[{"id":78756,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/78754\/revisions\/78756"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/78755"}],"wp:attachment":[{"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=78754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=78754"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=78754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}