{"id":61002,"date":"2023-12-08T14:31:51","date_gmt":"2023-12-08T17:31:51","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=61002"},"modified":"2023-12-08T14:31:53","modified_gmt":"2023-12-08T17:31:53","slug":"estado-realiza-audiencia-publica-na-fronteira-oeste-para-a-construcao-do-plano-estadual-pela-primeira-infancia","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/estado-realiza-audiencia-publica-na-fronteira-oeste-para-a-construcao-do-plano-estadual-pela-primeira-infancia\/","title":{"rendered":"Estado realiza audi\u00eancia p\u00fablica na Fronteira Oeste para a constru\u00e7\u00e3o do Plano Estadual pela Primeira Inf\u00e2ncia"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Quarto encontro ocorreu em Santana do Livramento, na quarta-feira (6\/12)<\/em><\/p>\n<p>O Comit\u00ea Intersetorial pela Primeira Inf\u00e2ncia (Ceipi), coordenado pelo Gabinete do Vice-Governador, promoveu, na quarta-feira (6\/12), a quarta audi\u00eancia p\u00fablica para a constru\u00e7\u00e3o do Plano Estadual pela Primeira Inf\u00e2ncia (Pepi). Desta vez, o evento ocorreu na Fronteira Oeste do Estado, em Santana do Livramento. Cerca de 90 pessoas, entre gestores municipais, educadores e comunidade, participaram do di\u00e1logo realizado no\u00a0Centro Universit\u00e1rio da Regi\u00e3o da Campanha (Urcamp), para entender as necessidades da primeira inf\u00e2ncia na regi\u00e3o.<\/p>\n<p>Essa edi\u00e7\u00e3o concentrou especialmente o debate sobre as inf\u00e2ncias nas regi\u00f5es de fronteira e assentamentos. <em>\u201cA audi\u00eancia p\u00fablica \u00e9 um espa\u00e7o para ouvirmos as demandas de cada regi\u00e3o, de forma a contemplar as especificidades locais no Pepi. \u00c9 o caso da fronteira, que tem caracter\u00edsticas particulares, dado o contexto geogr\u00e1fico e a rela\u00e7\u00e3o com os pa\u00edses vizinhos\u201d<\/em>, destacou o vice-governador Gabriel Souza.<\/p>\n<p>O ciclo de audi\u00eancias j\u00e1 foi realizado em Tenente Portela, Pelotas e Bento Gon\u00e7alves. A \u00faltima edi\u00e7\u00e3o est\u00e1 prevista para janeiro, em Porto Alegre. As atividades representam o compromisso do governo do Estado com essa fase da vida dos indiv\u00edduos. <em>\u201cO resultado dos encontros formar\u00e1 um dos documentos mais importantes, norteador das a\u00e7\u00f5es do Executivo pelos pr\u00f3ximos dez anos\u201d<\/em>, completou Gabriel.<\/p>\n<p><strong>Encurtando dist\u00e2ncias<\/strong><\/p>\n<p>Entre os principais pontos tratados no encontro, estiveram quest\u00f5es referentes ao transporte escolar, devido \u00e0 grande extens\u00e3o dos munic\u00edpios e \u00e0s dist\u00e2ncias entre comunidades e escolas. Presentes na audi\u00eancia, a professora da escola do assentamento de Hulha Negra, Cenira Hann, a m\u00e3e de uma crian\u00e7a assentada, Arlete Pinto, e o representante do Movimento dos Pequenos Agricultores e Assentamentos, frei Sergio Ant\u00f4nio G\u00f6rgen, trouxeram depoimentos sobre a dificuldade de manter a frequ\u00eancia escolar nesse contexto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-61005 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2023\/12\/81-400x225.jpeg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2023\/12\/81-400x225.jpeg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2023\/12\/81-768x432.jpeg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2023\/12\/81.jpeg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><em>\u201c\u00c9 muito importante escutar a sociedade sobre a situa\u00e7\u00e3o da inf\u00e2ncia para a constru\u00e7\u00e3o das pol\u00edticas p\u00fablicas nos pr\u00f3ximos anos. Ressaltamos que, no campo, a quest\u00e3o da infraestrutura, o cuidado da primeira inf\u00e2ncia e a educa\u00e7\u00e3o infantil s\u00e3o fundamentais para uma vida saud\u00e1vel das crian\u00e7as que vivem nos assentamentos de reforma agr\u00e1ria\u201d<\/em>, ressaltou o frei G\u00f6rgen.<\/p>\n<p>As demandas de sa\u00fade tamb\u00e9m se relacionam com os pontos trazidos pela comunidade, como a dificuldade de acesso a consultas, exames m\u00e9dicos e planejamento familiar, bem como a necessidade de se discutir pol\u00edticas binacionais, principalmente para as \u00e1reas de sa\u00fade e educa\u00e7\u00e3o.<\/p>\n<p><strong>Presen\u00e7as<\/strong><\/p>\n<p>Estiveram presentes gestores, trabalhadores da rede de prote\u00e7\u00e3o, fam\u00edlias, sociedade civil e demais interessados dos munic\u00edpios. A organiza\u00e7\u00e3o do evento contou com a participa\u00e7\u00e3o das secretarias de Justi\u00e7a, Cidadania e Direitos Humanos, da Sa\u00fade, de Desenvolvimento Social, da Educa\u00e7\u00e3o e de Planejamento, Governan\u00e7a e Gest\u00e3o, al\u00e9m do Conselho Estadual da Crian\u00e7a e do Adolescente (Cedica), com apoio da prefeitura de Santana do Livramento.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Juliane Soska\/Ascom GVG | Edi\u00e7\u00e3o: Camila Cargnelutti\/Secom | Foto: Antonio Paulo Cargnin<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Quarto encontro ocorreu em Santana do Livramento, na quarta-feira (6\/12) O Comit\u00ea Intersetorial pela Primeira Inf\u00e2ncia (Ceipi), coordenado pelo Gabinete do Vice-Governador, promoveu, na quarta-feira (6\/12), a quarta audi\u00eancia p\u00fablica para a constru\u00e7\u00e3o do Plano Estadual pela Primeira Inf\u00e2ncia (Pepi). Desta vez, o evento ocorreu na Fronteira Oeste do Estado, em Santana do Livramento. Cerca [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=61002"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61002\/revisions"}],"predecessor-version":[{"id":61006,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61002\/revisions\/61006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/61003"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=61002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=61002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=61002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}