{"id":61721,"date":"2024-01-29T13:52:20","date_gmt":"2024-01-29T16:52:20","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=61721"},"modified":"2024-01-29T13:52:21","modified_gmt":"2024-01-29T16:52:21","slug":"inscricoes-abertas-para-o-18o-congresso-brasileiro-de-pneumologia-pediatrica","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/inscricoes-abertas-para-o-18o-congresso-brasileiro-de-pneumologia-pediatrica\/","title":{"rendered":"Inscri\u00e7\u00f5es Abertas para o 18\u00ba Congresso Brasileiro de Pneumologia Pedi\u00e1trica"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i>Evento proporcionar\u00e1 atualiza\u00e7\u00e3o m\u00e9dica, discuss\u00f5es de casos cl\u00ednicos e a oportunidade de intera\u00e7\u00e3o com renomados profissionais da \u00e1rea<\/i><\/p>\n<div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>Se voc\u00ea \u00e9 profissional da \u00e1rea de sa\u00fade ou estudante interessado em participar do 18\u00ba Congresso Brasileiro de Pneumologia Pedi\u00e1trica, promovido pela Sociedade de Pediatria do Rio Grande do Sul (SPRS) em parceria com a Sociedade Brasileira de Pediatria (SBP), fique atento aos prazos de inscri\u00e7\u00e3o por lotes.\u00a0<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>At\u00e9 07\/02: Associados isentos da SBP t\u00eam a oportunidade de garantir a inscri\u00e7\u00e3o gratuita, enquanto outras categorias variam de R$ 300,00 a R$1.210,00.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>At\u00e9 14\/03: Os prazos continuam vantajosos, com valores variando entre R$ 300,00 e R$ 1.270,00.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>At\u00e9 30\/04: Ainda \u00e9 poss\u00edvel se inscrever com pre\u00e7os diferenciados, que v\u00e3o de R$ 320,00 a R$1.330,00.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>Ap\u00f3s 30\/04: Para aqueles que deixaram para \u00faltima hora, as inscri\u00e7\u00f5es permanecem abertas, mas com valores ajustados entre R$ 320,00 e R$ 1.500,00.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>Al\u00e9m disso, \u00e9 importante ressaltar que associados isentos da SBP devem estar em dia com suas contribui\u00e7\u00f5es anuais, conforme normativas descritas no Estatuto Social da SBP.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>A inscri\u00e7\u00e3o pode ser feita pelo site https:\/\/www.sbp.com.br\/index.php?id=5363 , e o pagamento pode ser efetuado por cart\u00e3o de cr\u00e9dito, dep\u00f3sito banc\u00e1rio ou transfer\u00eancia eletr\u00f4nica. Certifique-se de preencher um endere\u00e7o de e-mail v\u00e1lido para garantir todas as informa\u00e7\u00f5es pertinentes.<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div>Participe desse importante evento da pneumologia pedi\u00e1trica e esteja por dentro das \u00faltimas novidades da \u00e1rea!<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<div aria-hidden=\"true\">\u00a0<\/div>\n<\/div>\n<div><strong>Sobre a Sociedade de Pediatria do RS<\/strong><br aria-hidden=\"true\" \/><br aria-hidden=\"true\" \/>A Sociedade de Pediatria do Rio Grande do Sul foi fundada em 25 de junho de 1936 com o nome de Sociedade de Pediatria e Puericultura do Rio Grande do Sul pelo Prof. Raul Moreira e um grupo de m\u00e9dicos precursores da forma\u00e7\u00e3o pedi\u00e1trica no Estado. A entidade cresceu e se desenvolveu com o esp\u00edrito de seus idealizadores, que, preocupados com os avan\u00e7os da \u00e1rea m\u00e9dica e da pr\u00f3pria especialidade, uniram esfor\u00e7os na constru\u00e7\u00e3o de uma entidade que congregasse os colegas que a cada ano se multiplicavam no atendimento espec\u00edfico da popula\u00e7\u00e3o infantil. Atualmente conta com cerca de 1.750 s\u00f3cios, e se constitui em orgulho para a classe m\u00e9dica brasileira e, em especial, para a fam\u00edlia pedi\u00e1trica.<\/div>\n<hr \/>\n<h6><strong>PlayPress | SPRS - Sociedade de Pediatria do Rio Grande do Sul<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Evento proporcionar\u00e1 atualiza\u00e7\u00e3o m\u00e9dica, discuss\u00f5es de casos cl\u00ednicos e a oportunidade de intera\u00e7\u00e3o com renomados profissionais da \u00e1rea \u00a0 Se voc\u00ea \u00e9 profissional da \u00e1rea de sa\u00fade ou estudante interessado em participar do 18\u00ba Congresso Brasileiro de Pneumologia Pedi\u00e1trica, promovido pela Sociedade de Pediatria do Rio Grande do Sul (SPRS) em parceria com a Sociedade [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=61721"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61721\/revisions"}],"predecessor-version":[{"id":61723,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61721\/revisions\/61723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/61722"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=61721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=61721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=61721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}