{"id":61841,"date":"2024-02-02T22:14:12","date_gmt":"2024-02-03T01:14:12","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=61841"},"modified":"2024-02-02T22:14:13","modified_gmt":"2024-02-03T01:14:13","slug":"fiergs-define-programacao-internacional-para-2024","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/fiergs-define-programacao-internacional-para-2024\/","title":{"rendered":"FIERGS define programa\u00e7\u00e3o internacional para 2024"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\" align=\"center\"><i>Entidade realiza diferentes a\u00e7\u00f5es voltadas \u00e0s ind\u00fastrias ga\u00fachas<\/i><\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">\u00a0A Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Rio Grande do Sul (FIERGS), por meio do Centro Internacional de Neg\u00f3cios (CIN-RS), planeja o ano de 2024 com diversas a\u00e7\u00f5es voltadas \u00e0 internacionaliza\u00e7\u00e3o das ind\u00fastrias ga\u00fachas. Depois do SelectUSA 2024, com pain\u00e9is sobre as rela\u00e7\u00f5es Brasil-Estados Unidos e encontro de neg\u00f3cios, em parceria com a Embaixada dos EUA, realizado nesta quarta-feira, a programa\u00e7\u00e3o prossegue a partir de mar\u00e7o. Nesse m\u00eas, em parceria com a Apex e a C\u00e2mara \u00c1rabe, ocorre o Road show Certifica\u00e7\u00e3o Halal, incentivando a capacita\u00e7\u00e3o de ind\u00fastrias para a exporta\u00e7\u00e3o ao mercado isl\u00e2mico, global.<\/p>\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Em abril, acontece a tradicional Feira de Hannover, na Alemanha, entre 19 e 27, cujo foco \u00e9 nos setores de metalmec\u00e2nico, automa\u00e7\u00e3o, log\u00edstica, ind\u00fastria digital e sustent\u00e1vel, com a participa\u00e7\u00e3o de uma miss\u00e3o prospectiva ga\u00facha\u00a0articulada\u00a0pela FIERGS. Em seguida, no m\u00eas de junho, \u00e9 a vez da miss\u00e3o prospectiva da Ind\u00fastria Gr\u00e1fica do RS \u00e0 Drupa, feira do setor em D\u00fcsseldorf, na Alemanha, com apoio do\u00a0Sindicato da Ind\u00fastria Gr\u00e1fica no Rio Grande do Sul\u00a0(Sindigraf-RS) e Sebrae-RS. Ainda em junho, est\u00e1 planejada uma visita \u00e0 feira Alimentec, em Bogot\u00e1, Col\u00f4mbia, contemplando a Am\u00e9rica Latina.<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">Outra feira tradicional com miss\u00e3o programada \u00e9 a Sial Paris, entre 19 e 23 de outubro, um dos maiores eventos mundiais voltado para alimentos e bebidas. Ainda em outubro, em Caxias do Sul, ocorre a Feira Mercopar, entre os dias 15 e 18, quando a Ger\u00eancia de Rela\u00e7\u00f5es Internacionais e Com\u00e9rcio Exterior (Gerex) da FIERGS organizar\u00e1 rodadas de neg\u00f3cios. E para novembro, est\u00e1 prevista a miss\u00e3o prospectiva Eima Bologna, na It\u00e1lia, voltada para o setor de m\u00e1quinas e equipamentos agr\u00edcolas e jardinagem.<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">Al\u00e9m das miss\u00f5es em que a FIERGS ser\u00e1 articuladora, ocorrer\u00e3o a\u00e7\u00f5es em que a entidade atuar\u00e1 como colaboradora de federa\u00e7\u00f5es de outros estados. Nestas, est\u00e3o contemplados setores como moda, cosm\u00e9ticos, casa e decora\u00e7\u00e3o.<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">Em 2024, tamb\u00e9m ser\u00e3o realizados projetos com o objetivo de auxiliar as empresas a se internacionalizarem e fecharem neg\u00f3cios com parceiros do exterior. O primeiro deles ser\u00e1 o apoio na busca de empresas para participarem do Projeto Apex, Mulheres Globais, capacitando empresas brasileiras lideradas e\/ou geridas por mulheres a realizarem exporta\u00e7\u00f5es via e-commerce.<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">Ao longo deste ano, a Gerex organizar\u00e1 ainda capacita\u00e7\u00f5es e webinars, com foco Com\u00e9rcio Exterior e Rela\u00e7\u00f5es Internacionais. Destes, os pr\u00f3ximos ser\u00e3o Opera\u00e7\u00f5es e Conceitos do Com\u00e9rcio Exterior, Classifica\u00e7\u00e3o fiscal de mercadorias, Incoterms 2020 e Forma\u00e7\u00e3o de Pre\u00e7o na Exporta\u00e7\u00e3o.<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\">\u00a0<\/p>\n<p class=\"x_yiv4955198953ydp9b8feb15yiv7121092034MsoNormal\"><b>INTELIG\u00caNCIA COMERCIAL -\u00a0<\/b>J\u00e1 a \u00e1rea de Intelig\u00eancia Comercial da Gerex, que realiza estudos de mercado customizados e sistemas de business intelligence aplicados ao com\u00e9rcio internacional, como o Panorama do Com\u00e9rcio Internacional Brasileiro (<a href=\"https:\/\/bit.ly\/BIFIERGS\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"0\">https:\/\/bit.ly\/BIFIERGS<\/a>), se prepara para atender cerca de 20 empresas ao longo do ano. S\u00e3o projetos customizados, al\u00e9m de oferecer dias de imers\u00e3o em conte\u00fados de intelig\u00eancia comercial para empresas interessadas (boot camps) no espa\u00e7o FIERGS do Instituto Caldeira. Para informa\u00e7\u00f5es sobre os servi\u00e7os oferecidos pela Gerex, acesse:\u00a0<a href=\"https:\/\/www.fiergs.org.br\/servicos\/comercio-exterior\" target=\"_blank\" rel=\"nofollow noopener noreferrer\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"1\">https:\/\/www.fiergs.org.br\/servicos\/comercio-exterior<\/a>.<\/p>\n<hr \/>\n<h6><strong>Imprensa - FIERGS | Unicom -\u00a0Unidade de Comunica\u00e7\u00e3o do Sistema FIERGS<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Entidade realiza diferentes a\u00e7\u00f5es voltadas \u00e0s ind\u00fastrias ga\u00fachas \u00a0A Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Rio Grande do Sul (FIERGS), por meio do Centro Internacional de Neg\u00f3cios (CIN-RS), planeja o ano de 2024 com diversas a\u00e7\u00f5es voltadas \u00e0 internacionaliza\u00e7\u00e3o das ind\u00fastrias ga\u00fachas. Depois do SelectUSA 2024, com pain\u00e9is sobre as rela\u00e7\u00f5es Brasil-Estados Unidos e encontro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-61841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=61841"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61841\/revisions"}],"predecessor-version":[{"id":61843,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/61841\/revisions\/61843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/61842"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=61841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=61841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=61841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}