{"id":62119,"date":"2024-02-19T09:32:48","date_gmt":"2024-02-19T12:32:48","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=62119"},"modified":"2024-02-19T09:32:49","modified_gmt":"2024-02-19T12:32:49","slug":"varejo-e-atacado-puxam-crescimento-financeiro-das-vendas-em-2023","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/varejo-e-atacado-puxam-crescimento-financeiro-das-vendas-em-2023\/","title":{"rendered":"Varejo e atacado puxam crescimento financeiro das vendas em 2023"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Levantamento da Secretaria da Fazenda consolida dados de desempenho econ\u00f4mico do Estado no ano passado<\/em><\/p>\n<p>Impulsionados pelo bom desempenho do segundo semestre, o varejo e o atacado do Estado apresentaram crescimento no volume financeiro de vendas em 2023. Apesar do bom desempenho de alguns segmentos produtivos, a ind\u00fastria ga\u00facha experimentou um recuo de 3,8% nas transa\u00e7\u00f5es em compara\u00e7\u00e3o com o ano anterior. As informa\u00e7\u00f5es est\u00e3o consolidadas no\u00a0<a href=\"https:\/\/receitadoc.sefaz.rs.gov.br\/revista-rs360\/revista-rs360-16%C2%AA-edi%C3%A7%C3%A3o\/\" target=\"_blank\" rel=\"noopener\">Boletim Setorial<\/a>, publicado pela Secretaria da Fazenda (Sefaz) na sexta-feira (16\/2).<\/p>\n<p>No varejo, houve um aumento de 6,8% nas comercializa\u00e7\u00f5es. O avan\u00e7o foi alavancado pelos produtos dos segmentos metalomec\u00e2nico e qu\u00edmico, que registraram as maiores varia\u00e7\u00f5es, de 19,4% e 14,2%, respectivamente. Os super e hipermercados lideraram em valores absolutos, com R$ 74 bilh\u00f5es em vendas. \u00a0A movimenta\u00e7\u00e3o financeira de todo o setor varejista alcan\u00e7ou o patamar de R$ 248,7 bilh\u00f5es em 2023.<\/p>\n<p>J\u00e1 no atacado, as vendas tiveram um acr\u00e9scimo de 2,3% em rela\u00e7\u00e3o a 2022, acumulando o montante de R$ 212 bilh\u00f5es em circula\u00e7\u00e3o de mercadorias no ano passado. O destaque foi o segmento de produtos odontol\u00f3gicos e hospitalares, com um crescimento de 20,4%. Em valores absolutos, o ranking\u00a0\u00e9 encabe\u00e7ado\u00a0pelos insumos agropecu\u00e1rios, que movimentaram R$ 62 bilh\u00f5es em 2023, mesmo com um recuo de 1,2% em compara\u00e7\u00e3o com o ano anterior.<\/p>\n<p>Apesar do recuo geral na ind\u00fastria, alguns segmentos, como o de tabacos e bebidas, registraram crescimento nas vendas, com incrementos de 12% e 9%, respectivamente. A maior queda relativa, no entanto, foi verificada no segmento de insumos agropecu\u00e1rios, que teve uma redu\u00e7\u00e3o de 17% nas vendas. A ind\u00fastria metalomec\u00e2nica se manteve no topo em valores absolutos, com mais de R$ 154 bilh\u00f5es em vendas.<\/p>\n<p>Elaborado pela Central de Intelig\u00eancia Econ\u00f4mico-Tribut\u00e1ria da Receita Estadual, o Boletim Setorial integra o conte\u00fado da Revista RS360, que traz uma edi\u00e7\u00e3o com o desempenho detalhado das ind\u00fastrias coureiro-cal\u00e7adista, embalagens pl\u00e1sticas, madeira, cimento, vidro, medicamentos, m\u00f3veis, papel, produtos de limpeza, tintas, solventes, t\u00eaxtil e vestu\u00e1rio. O material conta, ainda, com uma entrevista ao economista Marcelo Portugal, que analisa o cen\u00e1rio tribut\u00e1rio brasileiro ap\u00f3s a aprova\u00e7\u00e3o da reforma dos impostos sobre o consumo, promulgada no fim do ano passado.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Rodrigo Azevedo\/Ascom Sefaz | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Levantamento da Secretaria da Fazenda consolida dados de desempenho econ\u00f4mico do Estado no ano passado Impulsionados pelo bom desempenho do segundo semestre, o varejo e o atacado do Estado apresentaram crescimento no volume financeiro de vendas em 2023. Apesar do bom desempenho de alguns segmentos produtivos, a ind\u00fastria ga\u00facha experimentou um recuo de 3,8% nas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=62119"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62119\/revisions"}],"predecessor-version":[{"id":62121,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62119\/revisions\/62121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/62120"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=62119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=62119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=62119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}