{"id":62208,"date":"2024-02-22T08:56:09","date_gmt":"2024-02-22T11:56:09","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=62208"},"modified":"2024-02-22T08:56:11","modified_gmt":"2024-02-22T11:56:11","slug":"mulheres-ainda-precisam-provar-capacidade-e-acreditar-mais-em-si-mesmas","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/mulheres-ainda-precisam-provar-capacidade-e-acreditar-mais-em-si-mesmas\/","title":{"rendered":"Mulheres ainda precisam provar capacidade e acreditar mais em si mesmas"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i>Vice-presidente do SERAC acredita que \u00e9 preciso acreditar no pr\u00f3prio potencial e entender desafios comuns<\/i><\/p>\n<div>\n<p>No pr\u00f3ximo m\u00eas se comemora o Dia Internacional das Mulheres e ainda s\u00e3o muitos os desafios a serem enfrentados por elas. Da necessidade de se provarem mais no mundo corporativo \u00e0s diferen\u00e7as salariais e quest\u00f5es enfrentadas para conciliar maternidade e trabalho, \u00e9 preciso entender que a perfei\u00e7\u00e3o n\u00e3o existe.\u00a0<\/p>\n<p>De acordo com<a href=\"https:\/\/www.instagram.com\/soucarlamartins\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"0\">\u00a0Carla Martins<\/a>, vice-presidente do<a href=\"https:\/\/www.instagram.com\/sou_serac\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"1\">\u00a0SERAC<\/a>, hub de solu\u00e7\u00f5es corporativas, sendo refer\u00eancia nas \u00e1reas cont\u00e1bil, jur\u00eddica e de tecnologia, muitas mulheres n\u00e3o acreditam no pr\u00f3prio potencial e n\u00e3o sabem onde podem chegar. <em>\u201cNo SERAC, somos quase 80% de mulheres. O mundo cont\u00e1bil \u00e9 muito feminino. E eu tento levant\u00e1-las, vibrando por elas cada vez que uma conquista acontece. Percebo que muitas mulheres n\u00e3o t\u00eam a for\u00e7a necess\u00e1ria por quest\u00f5es emocionais, por cobran\u00e7as sociais\u201d<\/em>, conta.\u00a0<\/p>\n<p>A executiva explica que participa de muitos grupos de empreendedorismo feminino e percebe que, ao contr\u00e1rio do que acontece no empreendedorismo masculino, as mulheres ainda est\u00e3o crescendo nos neg\u00f3cios e procurando ocupar melhor seu espa\u00e7o. <em>\u201cPercebo que o empreendedorismo feminino ainda est\u00e1 em crescimento. H\u00e1 muitas mulheres que tiveram que recome\u00e7ar de alguma forma na pandemia, outras mulheres com mais idade que est\u00e3o no processo de n\u00e3o depender mais de algu\u00e9m e querem seu pr\u00f3prio dinheiro, ou seja, h\u00e1 muitas mulheres come\u00e7ando, tentando se firmar\u201d<\/em>, afirma.<\/p>\n<p>Para Carla Martins, \u00e9 preciso que as mulheres entendam que nem sempre dar\u00e3o conta de tudo e est\u00e1 tudo bem. <em>\u201cPenso que independentemente da condi\u00e7\u00e3o financeira, os desafios que as mulheres enfrentam, ainda que em graus diferentes, s\u00e3o muito parecidos, assim como as cobran\u00e7as sociais que recebem. Muitas n\u00e3o sabem delegar ou acham que delegar \u00e9 errado. Foram ensinadas de uma determinada forma e precisam aprender a se desprender destas regras e ensinamentos\u201d<\/em>, reflete.\u00a0<\/p>\n<p>Segundo a vice-presidente do SERAC, que tem 50% da lideran\u00e7a do sexo feminino, \u00e9 preciso que as mulheres se coloquem, ocupem seu lugar e busquem levantar outras mulheres todas as vezes em que for poss\u00edvel. <em>\u201cComo sempre fui da \u00e1rea de RH, sempre cuidei muito da organiza\u00e7\u00e3o neste sentido. Trabalho com esta mentalidade e tento levantar outras mulheres. Vibro para que tenham for\u00e7a e gosto que me sigam para ver onde podem chegar e entendam que eu tamb\u00e9m enfrento desafios\u201d<\/em>, avalia.\u00a0<\/p>\n<p><strong>Sobre Carla Martins:<\/strong><\/p>\n<p>\u00c9 vice-presidente do SERAC, especialista em pessoas e processos, comandando a alta lideran\u00e7a da organiza\u00e7\u00e3o de quase 300 colaboradores. Acredita que a lideran\u00e7a estrat\u00e9gica \u00e9 a grande propulsora do crescimento das organiza\u00e7\u00f5es e por isso \u00e9 mentora e palestrante de gest\u00e3o de times de alta performance e criadora do M\u00e9todo 4RS de RH. Carla \u00e9 contabilista formada em Marketing pela ESPM e p\u00f3s-graduada em Big Data e Marketing.<a href=\"https:\/\/www.instagram.com\/soucarlamartins\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"2\">\u00a0@soucarlamartins<\/a><\/p>\n<p><strong>Sobre o SERAC:<\/strong><\/p>\n<p>O SERAC \u00e9 um hub de solu\u00e7\u00f5es corporativas, sendo refer\u00eancia nas \u00e1reas cont\u00e1bil, jur\u00eddica e de tecnologia. Com quase 300 colaboradores atendemos mais de 3.000 clientes recorrentes presentes em 20 estados brasileiros, independentemente do porte ou op\u00e7\u00e3o tribut\u00e1ria.<\/p>\n<p>Entre seus clientes est\u00e3o grandes marcas como XP Investimentos, G4 Educa\u00e7\u00e3o, \u00d3ticas Diniz, Mundial Cal\u00e7ados e, tamb\u00e9m, empres\u00e1rios e personalidades da m\u00eddia, como Fl\u00e1vio Augusto, Thiago Nigro e Joel Jota, contando com equipe especializada no mercado digital. Instagram:<a href=\"https:\/\/www.instagram.com\/sou_serac\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"3\">\u00a0@sou_serac<\/a><\/p>\n<hr \/>\n<h6><strong>Carolina Lara Comunica\u00e7\u00e3o | Foto: SERAC<\/strong><\/h6>\n<\/div>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Vice-presidente do SERAC acredita que \u00e9 preciso acreditar no pr\u00f3prio potencial e entender desafios comuns No pr\u00f3ximo m\u00eas se comemora o Dia Internacional das Mulheres e ainda s\u00e3o muitos os desafios a serem enfrentados por elas. Da necessidade de se provarem mais no mundo corporativo \u00e0s diferen\u00e7as salariais e quest\u00f5es enfrentadas para conciliar maternidade e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=62208"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62208\/revisions"}],"predecessor-version":[{"id":62210,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62208\/revisions\/62210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/62209"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=62208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=62208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=62208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}