{"id":62941,"date":"2024-03-25T13:46:34","date_gmt":"2024-03-25T16:46:34","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=62941"},"modified":"2024-03-25T13:46:35","modified_gmt":"2024-03-25T16:46:35","slug":"operacao-verao-total-encerra-temporada-com-queda-expressiva-em-indicadores-criminais","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/operacao-verao-total-encerra-temporada-com-queda-expressiva-em-indicadores-criminais\/","title":{"rendered":"Opera\u00e7\u00e3o Ver\u00e3o Total encerra temporada com queda expressiva em indicadores criminais"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Servi\u00e7os e a\u00e7\u00f5es integrados foram realizados durante tr\u00eas meses nas praias do Estado<\/em><\/p>\n<p>Com novidades, incluindo um novo modelo de governan\u00e7a, a cria\u00e7\u00e3o de eixos tem\u00e1ticos e a amplia\u00e7\u00e3o no n\u00famero de servidores e servi\u00e7os oferecidos, a temporada 2023-2024 da Opera\u00e7\u00e3o Ver\u00e3o Total (OVT) chegou ao fim em 15 de mar\u00e7o com uma queda expressiva em uma s\u00e9rie de indicadores criminais nas praias ga\u00fachas. Quase 40 \u00f3rg\u00e3os do governo do Estado estiveram presentes em todo o litoral do Rio Grande do Sul, al\u00e9m de \u00e1guas internas e balne\u00e1rios, levando servi\u00e7os, informa\u00e7\u00e3o e seguran\u00e7a para banhistas, moradores e turistas durante os tr\u00eas meses do veraneio.<\/p>\n<p>No balan\u00e7o final da Secretaria da Seguran\u00e7a P\u00fablica (SSP), os \u00edndices de criminalidade tiveram queda. O indicador de roubos a estabelecimentos comerciais apresentou redu\u00e7\u00e3o de 65%, e o de roubo a pedestres registrou queda de 42% \u2013 mesmo n\u00famero da diminui\u00e7\u00e3o de roubos de ve\u00edculos.<\/p>\n<p>Nos Crimes Violentos Letais Intencionais (CVLI) foi observada queda de 32%. O crime de estelionato apresentou uma redu\u00e7\u00e3o de 26%, e os indicadores de roubos a resid\u00eancia diminu\u00edram 24%. Foram realizadas ainda opera\u00e7\u00f5es relacionadas a furto de fios e cabos, bem como de desmanche. Al\u00e9m disso, de acordo com o Corpo de Bombeiros Militar do Rio Grande do Sul (CBMRS), n\u00e3o houve nenhuma morte em \u00e1reas com a presen\u00e7a de guarda-vidas durante a OVT.<\/p>\n<p>Coordenador executivo da opera\u00e7\u00e3o, o vice-governador Gabriel Souza destaca que essa \u00e9 a maior iniciativa do governo estadual, realizada de maneira transversal. <em>\u201cReunimos diferentes secretarias e setores da gest\u00e3o para que cada um levasse seus principais servi\u00e7os para as praias de norte a sul. O objetivo foi otimizar nossas entregas e dar respostas mais eficientes para as principais demandas da popula\u00e7\u00e3o nessas regi\u00f5es\u201d<\/em>, explica.<\/p>\n<p>As a\u00e7\u00f5es foram divididas em cinco eixos tem\u00e1ticos: Seguran\u00e7a P\u00fablica, Bem-Estar Social,\u00a0Desenvolvimento Econ\u00f4mico,\u00a0Mobilidade e\u00a0Comunica\u00e7\u00e3o.<\/p>\n<h3><strong>Mais n\u00fameros e entregas dos eixos tem\u00e1ticos<\/strong><\/h3>\n<ul>\n<li><strong>Seguran\u00e7a P\u00fablica<\/strong><\/li>\n<\/ul>\n<p>IGP: os servi\u00e7os de identifica\u00e7\u00e3o civil foram ampliados nos quatro postos do Instituto Geral de Per\u00edcias (IGP), resultando em uma expans\u00e3o de +175%.<\/p>\n<p>Brigada Militar: atendimento a 23.657 ocorr\u00eancias, com realiza\u00e7\u00e3o de 5.919 barreiras policiais e abordagem a 145.844 pessoas. Al\u00e9m disso, as a\u00e7\u00f5es da Escolinha de Tr\u00e2nsito proporcionaram maior aproxima\u00e7\u00e3o com a comunidade, atendendo um p\u00fablico total de 15.920 pessoas.<\/p>\n<p>Pol\u00edcia Civil: atendimento a 31.537 ocorr\u00eancias; amplia\u00e7\u00e3o do amparo a v\u00edtimas de viol\u00eancia dom\u00e9stica por meio de 2.065 medidas protetivas; realiza\u00e7\u00e3o de 286 mandados de pris\u00e3o e de 664 mandados de busca e apreens\u00e3o; al\u00e9m de diversas a\u00e7\u00f5es que compreenderam oficinas de desenho, oficinas de tr\u00e2nsito, o Papo de Responsa e a\u00e7\u00f5es sociais, entre outras atividades que alcan\u00e7aram um p\u00fablico total de 5.418 pessoas.<\/p>\n<p>Corpo de Bombeiros: realizados 879 salvamentos (aumento de 18,3% em rela\u00e7\u00e3o \u00e0 edi\u00e7\u00e3o anterior), al\u00e9m de 382.336 a\u00e7\u00f5es de preven\u00e7\u00e3o, destacando a atua\u00e7\u00e3o preventiva e socorrista efetiva da institui\u00e7\u00e3o. O Projeto Guarda-Vidas Mirim atingiu um p\u00fablico de 1.641 crian\u00e7as.<\/p>\n<p>Detran: a Balada Segura quase dobrou o n\u00famero de abordagens no litoral. Foram 16.429 motoristas fiscalizados de 16 de dezembro do ano passado a 10 de mar\u00e7o de 2024, contra 8.800 abordagens na opera\u00e7\u00e3o de 2022\/2023. Mesmo com o aumento substancial das abordagens, as infra\u00e7\u00f5es por recusa ca\u00edram 3%, os testes positivos reduziram em 70% e os registros de crime de tr\u00e2nsito de embriaguez diminu\u00edram 36%. Foram realizadas 82 blitze de fiscaliza\u00e7\u00e3o, com aproximadamente 4 mil ve\u00edculos autuados e 323 recolhidos, com efetiva\u00e7\u00e3o de 15.554 testes do etil\u00f4metro.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-62943 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/91-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/91-400x267.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/91-768x512.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/91-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/91.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li><strong>Bem-Estar Social<\/strong><\/li>\n<\/ul>\n<p>A Secretaria da Sa\u00fade (SES) realizou repasse no valor R$ 3 milh\u00f5es, que contemplou 19 bases do SAMU 192, 14 pronto-atendimentos e nove hospitais do Litoral Norte e Sul. O objetivo foi auxiliar os munic\u00edpios para minimizar o aumento de custos, assim como apoiar as a\u00e7\u00f5es em sa\u00fade decorrentes do aumento do fluxo de veranistas e turistas. Tamb\u00e9m foram realizadas a\u00e7\u00f5es de conscientiza\u00e7\u00e3o sobre a dengue, orienta\u00e7\u00f5es para os trabalhadores expostos \u00e0s ondas de calor, capacita\u00e7\u00f5es e fiscaliza\u00e7\u00f5es relacionadas \u00e0 alimenta\u00e7\u00e3o.<\/p>\n<p>A Funda\u00e7\u00e3o de Atendimento ao Deficiente e ao Superdotado do Rio Grande do Sul (Faders) expandiu a a\u00e7\u00e3o Rede Praia Acess\u00edvel com o Banho Assistido em Cadeira Anf\u00edbia. Foram realizados 608 atendimentos, contemplando pessoas domiciliadas em 76 munic\u00edpios. Entre essas, 484 foram pessoas com defici\u00eancia. O servi\u00e7o Disque Banho Assistido recebeu 130 chamadas.\u00a0<\/p>\n<p>A\u00e7\u00f5es de educa\u00e7\u00e3o ambiental tamb\u00e9m integram o eixo e foram realizadas em cinco cidades, onde cerca de 820 pessoas passaram pelos espa\u00e7os montados pela equipe da Secretaria do Meio Ambiente e Infraestrutura (Sema). Veranistas e moradores puderam realizar cinco visitas \u00e0s unidades de conserva\u00e7\u00e3o (REBIO Mato Grande e Parque Estadual de Itapeva), tr\u00eas ao Horto Florestal do Litoral Norte e uma ao Parque E\u00f3lico de Os\u00f3rio. No total, foram 72 visitantes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-62944 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/92-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/92-400x266.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/92-768x511.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/92-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/03\/92.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<ul>\n<li><strong>Desenvolvimento Econ\u00f4mico<\/strong><\/li>\n<\/ul>\n<p>O Procon RS apresentou um aumento de cerca de 350% de munic\u00edpios que receberam os servi\u00e7os da unidade m\u00f3vel, saltando de dois munic\u00edpios para dez. Neste ano, o setor ampliou em cerca de 15% as datas de agenda de servi\u00e7os prestados de forma presencial, al\u00e9m de aumentar em 60% os locais que receberam atendimento no ve\u00edculo.<\/p>\n<p>J\u00e1 as salas de autoatendimento nas unidades do Tudo F\u00e1cil foram disponibilizadas para realiza\u00e7\u00e3o de uma s\u00e9rie de atividades e solicita\u00e7\u00f5es para os cidad\u00e3os. Tamb\u00e9m foi oferecido hor\u00e1rio estendido para receber a popula\u00e7\u00e3o nas unidades. Em Pelotas foram registrados 30.803 atendimentos, com n\u00edvel de satisfa\u00e7\u00e3o geral de 99,03%. No mesmo per\u00edodo, em Rio Grande\/Cassino, foram realizados 26.625 atendimentos, com n\u00edvel de satisfa\u00e7\u00e3o de 99,16%.<\/p>\n<ul>\n<li><strong>Mobilidade<\/strong><\/li>\n<\/ul>\n<p>O Departamento Aut\u00f4nomo de Estradas de Rodagem (Daer), vinculado \u00e0 Secretaria de Log\u00edstica e Transportes (Selt), realizou, ao longo de 2023, uma s\u00e9rie de melhorias nas rodovias de acesso aos litorais Norte e Sul do Estado para proporcionar manuten\u00e7\u00e3o de forma cont\u00ednua. O Daer tamb\u00e9m realizou a ro\u00e7ada e recupera\u00e7\u00e3o de dispositivos de drenagem na malha em geral das estradas da regi\u00e3o. A autarquia liberou, ainda, R$ 9 milh\u00f5es para investimentos nas rodovias do Litoral Norte e, na temporada de veraneio, intensificou os trabalhos de manuten\u00e7\u00e3o nos pontos mais cr\u00edticos das rodovias da regi\u00e3o.<\/p>\n<p>J\u00e1 a Secretaria de Desenvolvimento Urbano e Metropolitano (Sedur) participou da opera\u00e7\u00e3o por meio da Funda\u00e7\u00e3o Estadual de Planejamento Metropolitano e Regional (Metroplan), \u00f3rg\u00e3o vinculado \u00e0 pasta, realizando fiscaliza\u00e7\u00f5es dos \u00f4nibus de passageiros em 25 munic\u00edpios. Pelo acentuado aumento do fluxo de passageiros, foram intensificadas as abordagens nas regi\u00f5es com a finalidade de apurar o cumprimento dos hor\u00e1rios oficiais das tabelas constantes nos registros da Metroplan.<\/p>\n<p>Por sua vez, a Empresa Ga\u00facha de Rodovias (EGR) implementou melhorias na sinaliza\u00e7\u00e3o na ERS-040, na ERS-784, na ERS-115 e na ERS-239, al\u00e9m de disponibilizar uma ambul\u00e2ncia extra para atendimento aos motoristas na ERS-040, em Capivari do Sul. Tamb\u00e9m ofertou servi\u00e7os de ambul\u00e2ncia, guincho e estrutura de parada e atendimento.<\/p>\n<ul>\n<li><strong>Comunica\u00e7\u00e3o<\/strong><\/li>\n<\/ul>\n<p>A partir dessa edi\u00e7\u00e3o, a popula\u00e7\u00e3o passou a contar com uma nova ferramenta para acessar as principais orienta\u00e7\u00f5es da OVT. No\u00a0<strong><a href=\"https:\/\/operacaoveraototal.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\">site<\/a>\u00a0<\/strong>da opera\u00e7\u00e3o, \u00e9 poss\u00edvel conferir indica\u00e7\u00f5es sobre balneabilidade; mapa de guarda-vidas e guaritas; atualiza\u00e7\u00f5es sobre estradas e tr\u00e2nsito; servi\u00e7os e dicas de sa\u00fade, meio ambiente e seguran\u00e7a; e programa\u00e7\u00e3o de esportes, lazer e cultura, al\u00e9m de informa\u00e7\u00f5es tur\u00edsticas.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom GVG e Ascom SSP | Edi\u00e7\u00e3o: Felipe Borges\/Secom | Fotos: Gustavo Mansur\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Servi\u00e7os e a\u00e7\u00f5es integrados foram realizados durante tr\u00eas meses nas praias do Estado Com novidades, incluindo um novo modelo de governan\u00e7a, a cria\u00e7\u00e3o de eixos tem\u00e1ticos e a amplia\u00e7\u00e3o no n\u00famero de servidores e servi\u00e7os oferecidos, a temporada 2023-2024 da Opera\u00e7\u00e3o Ver\u00e3o Total (OVT) chegou ao fim em 15 de mar\u00e7o com uma queda expressiva [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":62942,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-62941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=62941"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62941\/revisions"}],"predecessor-version":[{"id":62945,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/62941\/revisions\/62945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/62942"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=62941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=62941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=62941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}