{"id":63313,"date":"2024-04-09T11:07:54","date_gmt":"2024-04-09T14:07:54","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63313"},"modified":"2024-04-09T11:07:56","modified_gmt":"2024-04-09T14:07:56","slug":"programa-licao-de-casa-investe-r-27-milhoes-em-marco","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/programa-licao-de-casa-investe-r-27-milhoes-em-marco\/","title":{"rendered":"Programa Li\u00e7\u00e3o de Casa investe R$ 2,7 milh\u00f5es em mar\u00e7o"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>O Programa Li\u00e7\u00e3o de Casa, coordenado pelas secretarias de Obras P\u00fablicas e da Educa\u00e7\u00e3o, investiu R$ 2,7 milh\u00f5es em mar\u00e7o, beneficiando professores, funcion\u00e1rios e mais de 4,1 mil alunos. Em onze escolas as obras foram iniciadas e em quatro os servi\u00e7os foram conclu\u00eddos.<\/p>\n<p>As reformas que come\u00e7aram receberam quase R$ 1,8 milh\u00e3o e beneficiam 3.289 estudantes. O maior investimento do m\u00eas foi na Escola Estadual de Ensino Fundamental (EEEF) Nossa Senhora da Salette, em Bento Gon\u00e7alves: R$ 657 mil para reforma el\u00e9trica, estrutural e arquitet\u00f4nica dos Blocos I e II, al\u00e9m da recupera\u00e7\u00e3o da quadra de esportes. Os projetos iniciados abrangem sete regi\u00f5es do Estado: Metropolitana, Serra, Miss\u00f5es, Sul, Vale do Ca\u00ed, Fronteira Oeste e Hort\u00eansias.<\/p>\n<p>Nas obras conclu\u00eddas foram investidos mais de R$ 931 mil, valor aplicado em infraestrutura escolar nas regi\u00f5es Sul, Central, Paranhana\/Encosta da Serra e Produ\u00e7\u00e3o. A EEEF Nossa Senhora de F\u00e1tima foi a que mais recebeu recursos, com cerca da R$ 363 mil investidos na reconstru\u00e7\u00e3o de um muro.<\/p>\n<p><strong>Obras iniciadas<\/strong><\/p>\n<ul>\n<li>Bento Gon\u00e7alves: EEEF Nossa Senhora da Salette | R$ 657,4 mil | 174 alunos;<\/li>\n<li>Canela: Escola Estadual de Ensino B\u00e1scio (EEEB) Neusa Mari Pacheco \u2013 CIEP | R$ 77,6 mil | 1090 alunos;<\/li>\n<li>Caxias do Sul:\u00a0Escola Estadual de Ensino M\u00e9dio (EEEM) Irm\u00e3o Jos\u00e9 Ot\u00e3o | R$ 22,2 mil | 515 alunos;<\/li>\n<li>Caxias do Sul: Instituo Estadual de Educa\u00e7\u00e3o Crist\u00f3v\u00e3o de Mendoza | R$ 58,4 mil | 844 alunos;<\/li>\n<li>Montenegro: EEEF Jos\u00e9 Garibaldi | R$ 91,7 mil | 76 alunos;<\/li>\n<li>Pelotas: EEEF Dr. Ottoni Xavier | R$ 135,7 mil | 120 alunos;<\/li>\n<li>Santo \u00c2ngelo: N\u00facleo Estadual de Educa\u00e7\u00e3o de Jovens e Adultos e de Cultura Popular Santo \u00c2ngelo\u00a0| R$ 292,9 mil | 34 alunos;<\/li>\n<li>S\u00e3o Luiz Gonzaga: EEEM Professora Terezinha Medeiros Schneider | R$ 79,2 mil | 137 alunos;<\/li>\n<li>Triunfo: EEEF Eurico Altair da Motta | R$ 96,1 mil | 93 alunos;<\/li>\n<li>Uruguaiana: EEEF Rep\u00fablica do Uruguai | R$ 170,9 mil | 157 alunos;<\/li>\n<li>S\u00e3o Borja: EEEM Timbauva\u00a0 | R$ 106,3 mil | 49 alunos<\/li>\n<\/ul>\n<p><strong>Obras conclu\u00eddas<\/strong><\/p>\n<ul>\n<li>J\u00falio de Castilhos: EEEF Dr. Theodoro Ribas Sales | R$ 196,2 mil | 120 alunos;<\/li>\n<li>Passo Fundo: EEEF Abhramo \u00c2ngelo Zanotto | R$ 107,2 mil | 28 alunos;<\/li>\n<li>Pelotas: EEEF Nossa Senhora de F\u00e1tima | R$ 363,6 mil | 400 alunos;<\/li>\n<li>Taquara: EEEF Rodolfo Von Ihering | R$ 264 mil | 265 alunos<\/li>\n<\/ul>\n<p><strong>Sobre o Li\u00e7\u00e3o de Casa<\/strong><\/p>\n<p>O Programa Li\u00e7\u00e3o de Casa prev\u00ea investimentos de R$ 101,04 milh\u00f5es para a qualifica\u00e7\u00e3o da infraestrutura das institui\u00e7\u00f5es de ensino e a reformula\u00e7\u00e3o do ambiente escolar na Rede Estadual.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom SOP | Edi\u00e7\u00e3o: Secom | Foto: Divulga\u00e7\u00e3o SOP<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Programa Li\u00e7\u00e3o de Casa, coordenado pelas secretarias de Obras P\u00fablicas e da Educa\u00e7\u00e3o, investiu R$ 2,7 milh\u00f5es em mar\u00e7o, beneficiando professores, funcion\u00e1rios e mais de 4,1 mil alunos. Em onze escolas as obras foram iniciadas e em quatro os servi\u00e7os foram conclu\u00eddos. As reformas que come\u00e7aram receberam quase R$ 1,8 milh\u00e3o e beneficiam 3.289 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63313"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63313\/revisions"}],"predecessor-version":[{"id":63315,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63313\/revisions\/63315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63314"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}