{"id":63333,"date":"2024-04-10T09:14:17","date_gmt":"2024-04-10T12:14:17","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63333"},"modified":"2024-04-10T09:14:19","modified_gmt":"2024-04-10T12:14:19","slug":"empresas-anunciam-investimentos-de-r-420-milhoes-no-polo-carboquimico-de-candiota","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/empresas-anunciam-investimentos-de-r-420-milhoes-no-polo-carboquimico-de-candiota\/","title":{"rendered":"Empresas anunciam investimentos de R$ 420 milh\u00f5es no Polo Carboqu\u00edmico de Candiota"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Foco \u00e9 a fabrica\u00e7\u00e3o de liga met\u00e1lica para desoxidar a\u00e7o nas sider\u00fargicas<\/em><\/p>\n<p>A empresa\u00a0brasileira Vamtec e a gestora do grupo alem\u00e3o ICMD investir\u00e3o R$ 420 milh\u00f5es na constru\u00e7\u00e3o de uma ind\u00fastria no\u00a0Polo Carboqu\u00edmico de Candiota. O aporte \u00e9 para o projeto Ferroligas Candiota, que\u00a0fabricar\u00e1 a liga met\u00e1lica\u00a0FeSIAI (Ferro\u00a0Sil\u00edcio\u00a0Alum\u00ednio)\u00a0a partir do carv\u00e3o de alta cinza \u2013 produto j\u00e1 usado na\u00a0desoxida\u00e7\u00e3o do a\u00e7o pelo setor sider\u00fargico. O\u00a0an\u00fancio ocorreu nesta ter\u00e7a-feira (9\/4), no Pal\u00e1cio Piratini, na presen\u00e7a do governador Eduardo Leite e do secret\u00e1rio de Desenvolvimento Econ\u00f4mico (Sedec), Ernani Polo.\u00a0<\/p>\n<p>O projeto\u00a0Ferroliga FeSIAI \u2013 Ferro, Sil\u00edcio e Alum\u00ednio utiliza a redu\u00e7\u00e3o do carv\u00e3o com alto teor de cinzas (uma caracter\u00edstica do min\u00e9rio encontrado em Candiota) para criar um produto alternativo, mais barato e com melhor rendimento que o tradicional, para a desoxida\u00e7\u00e3o de a\u00e7o.\u00a0O grupo ICMD det\u00e9m a licen\u00e7a global deste processo, que utiliza uma tecnologia original desenvolvida no Cazaquist\u00e3o. A produ\u00e7\u00e3o estimada \u00e9 de 36 mil toneladas por ano, com um mercado potencial para 170 mil toneladas. O investimento tamb\u00e9m contempla oportunidades para programas de desenvolvimento social, educacional e de sa\u00fade, al\u00e9m de troca de experi\u00eancias nacionais com a China.<\/p>\n<p>O prazo\u00a0 para in\u00edcio das atividades \u00e9 at\u00e9 o fim de 2027. A\u00a0 expectativa de faturamento do primeiro projeto \u00e9 de\u00a0R$ 300 milh\u00f5es anuais e entrega de R$ 40 milh\u00f5es em impostos por ano. A gera\u00e7\u00e3o de empregos tamb\u00e9m est\u00e1 no planejamento, com proje\u00e7\u00e3o de 1 mil postos de trabalho diretos na etapa de constru\u00e7\u00e3o da planta e de 330 vagas diretas na\u00a0\u00a0fase de opera\u00e7\u00e3o.<\/p>\n<p>O governador ressaltou que o an\u00fancio demonstra o acerto da pol\u00edtica do governo para atra\u00e7\u00e3o de investimentos. <em>\"Estamos falando de um investimento robusto, com gera\u00e7\u00e3o de muitos empregos. Isso ocorre por conta do ambiente de neg\u00f3cios favor\u00e1vel que conseguimos estabelecer no Rio Grande do Sul. Hoje, o investidor tem seguran\u00e7a de aportar recursos no Estado, porque sabe que o governo d\u00e1 as melhores condi\u00e7\u00f5es para os empreendedores\"<\/em>, disse Leite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-63335 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/41-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/41-400x267.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/41-768x512.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/41-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/41.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>O impacto positivo do investimento, principalmente em rela\u00e7\u00e3o \u00e0 cria\u00e7\u00e3o de empregos e ao incentivo \u00e0 competitividade estadual, foi ressaltado pelo titular da Sedec.\u00a0<em>\u201cVemos este an\u00fancio como uma oportunidade de abertura de mais vagas de trabalho e renda, a partir de uma opera\u00e7\u00e3o que usar\u00e1 um ativo dispon\u00edvel na regi\u00e3o. Isso ser\u00e1 feito de forma sustent\u00e1vel, com todo o cuidado que a avalia\u00e7\u00e3o exige, em especial nas quest\u00f5es ambientais<\/em>\u201d, destacou Polo.<\/p>\n<p>O prefeito de Candiota, Luiz Carlos Folador, destacou os benef\u00edcios para o munic\u00edpio. <em>\u201cO projeto \u00e9 vi\u00e1vel e tem a participa\u00e7\u00e3o de um grupo que domina a tecnologia\u201d<\/em>, enfatizou. Ele tamb\u00e9m informou que os investidores far\u00e3o uma visita t\u00e9cnica no local nesta semana.<\/p>\n<p>Participaram do an\u00fancio de investimento as secretarias do Meio Ambiente e Infraestrutura, Marjorie Kauffmann, e de Planejamento, Governan\u00e7a e Gest\u00e3o, Danielle Calazans, o vice-presidente do Banco Regional de Desenvolvimento do Extremo Sul (BRDE), Ranolfo Vieira J\u00fanior, o presidente do Badesul, Claudio Gastal, o diretor-presidente da Funda\u00e7\u00e3o Estadual de Prote\u00e7\u00e3o Ambiental (Fepam), Renato Chagas, o diretor-presidente da Companhia Riograndense de Minera\u00e7\u00e3o (CRM), Ademir Baretta, e o prefeito de Candiota, Luiz Carlos Folador, al\u00e9m de representantes da Vamtec Group e da ICMD Holding.<\/p>\n<p><strong>Sobre a Vamtec Group<\/strong><\/p>\n<p>Trata-se de um grupo industrial de 43 anos de atividades, com v\u00e1rias plantas nos estados do Esp\u00edrito Santo, Rio de Janeiro, Minas Gerais e\u00a0Bahia. Atua especialmente no setor sider\u00fargico e de ferroligas. A empresa est\u00e1 envolvida no desenvolvimento da Regi\u00e3o da Campanha e no aproveitamento sustent\u00e1vel do carv\u00e3o de Candiota, com projeto de gaseifica\u00e7\u00e3o do carv\u00e3o e produ\u00e7\u00e3o de metanol, ideia que deve ser implementada em 2025.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ta\u00eds Teixeira\/Ascom Sedec | Edi\u00e7\u00e3o: Camila Cargnelutti\/Secom | Fotos: Gustavo Mansur\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Foco \u00e9 a fabrica\u00e7\u00e3o de liga met\u00e1lica para desoxidar a\u00e7o nas sider\u00fargicas A empresa\u00a0brasileira Vamtec e a gestora do grupo alem\u00e3o ICMD investir\u00e3o R$ 420 milh\u00f5es na constru\u00e7\u00e3o de uma ind\u00fastria no\u00a0Polo Carboqu\u00edmico de Candiota. O aporte \u00e9 para o projeto Ferroligas Candiota, que\u00a0fabricar\u00e1 a liga met\u00e1lica\u00a0FeSIAI (Ferro\u00a0Sil\u00edcio\u00a0Alum\u00ednio)\u00a0a partir do carv\u00e3o de alta cinza \u2013 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63333"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63333\/revisions"}],"predecessor-version":[{"id":63336,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63333\/revisions\/63336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63334"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}