{"id":63380,"date":"2024-04-11T09:12:06","date_gmt":"2024-04-11T12:12:06","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63380"},"modified":"2024-04-11T09:12:07","modified_gmt":"2024-04-11T12:12:07","slug":"governo-reune-empresarios-para-construir-nova-agenda-de-desenvolvimento-do-estado","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governo-reune-empresarios-para-construir-nova-agenda-de-desenvolvimento-do-estado\/","title":{"rendered":"Governo re\u00fane empres\u00e1rios para construir nova agenda de desenvolvimento do Estado"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>A primeira reuni\u00e3o de trabalho de constru\u00e7\u00e3o da nova agenda de desenvolvimento do Rio Grande do Sul foi realizada nesta quarta-feira (10\/4). Organizado pelo governo, o encontro no Pal\u00e1cio Piratini teve a participa\u00e7\u00e3o de empres\u00e1rios e presidentes de entidades de classe. Durante a tarde, houve a apresenta\u00e7\u00e3o do pr\u00e9-diagn\u00f3stico sobre competitividade do Estado, detalhamento das t\u00e9cnicas de constru\u00e7\u00e3o do futuro plano de desenvolvimento e a coleta de ideias para a elabora\u00e7\u00e3o do Plano Estadual de Desenvolvimento Econ\u00f4mico, Inovador e Sustent\u00e1vel.<\/p>\n<p>Depois de falar na abertura, o governador Eduardo Leite acompanhou as mesas-redondas no Sal\u00e3o Alberto Pasqualini, juntamente com o secret\u00e1rio-chefe da Casa Civil, Artur Lemos, e o secret\u00e1rio de Desenvolvimento Econ\u00f4mico, Ernani Polo. Deputados estaduais tamb\u00e9m participaram das discuss\u00f5es.<\/p>\n<p><em>\u201cA colabora\u00e7\u00e3o da classe empresarial ser\u00e1 fundamental. Vamos elaborar iniciativas estrat\u00e9gicas baseadas em tend\u00eancias globais para um plano de futuro que eleve o Estado a outro patamar. O Rio Grande do Sul \u00e9 vocacionado para o empreendedorismo e queremos desenvolver ainda mais esse potencial, puxando juntos na mesma dire\u00e7\u00e3o pelo desenvolvimento econ\u00f4mico dentro de uma sociedade mais inclusiva, justa e com oportunidades\u201d<\/em>, afirmou Leite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-63382 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/81-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/81-400x267.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/81-768x512.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/81-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/81.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A reuni\u00e3o foi conduzida pela McKinsey, empresa de consultoria internacional contratada pelo Estado para apoiar o projeto. O objetivo \u00e9 promover o alinhamento estrat\u00e9gico entre os diferentes integrantes que comp\u00f5em o Sistema de Desenvolvimento Econ\u00f4mico, Inovador e Sustent\u00e1vel, identificando investimentos e esfor\u00e7os que devem ser priorizados pelo Executivo estadual nos pr\u00f3ximos anos.<\/p>\n<p>Esse ecossistema \u00e9 orientado pelo Plano de Desenvolvimento e envolve governo, empresas e entidades, sociedade e universidades, al\u00e9m do Conselho de Competitividade e Futuro e a Ag\u00eancia de Desenvolvimento do RS, institu\u00eddos no fim de 2023.<\/p>\n<p><em>\"Esta gest\u00e3o, ainda no primeiro mandato, realizou as mais profundas reformas administrativas j\u00e1 feitas, tornando a m\u00e1quina p\u00fablica menos onerosa, o que tende a tornar o Estado mais atrativo para novos investimentos. As discuss\u00f5es realizadas aqui nesta tarde e a Ag\u00eancia de Desenvolvimento far\u00e3o o Rio Grande do Sul ganhar agilidade na vinda de novos neg\u00f3cios que resultar\u00e3o em benef\u00edcios para a sociedade\",<\/em> disse Artur Lemos.<\/p>\n<p><strong>Din\u00e2mica de grupos<\/strong><\/p>\n<p>Nas mesas-redondas do encontro, foi realizada uma din\u00e2mica de idea\u00e7\u00e3o com quase 120 participantes, a fim de discutir seis macrotend\u00eancias \u2013 selecionadas pela Mckinsey \u2013 que poder\u00e3o impactar a economia do Estado nos pr\u00f3ximos anos:<\/p>\n<ul>\n<li>Reconfigura\u00e7\u00e3o de cadeias produtivas<\/li>\n<li>Biorrevolu\u00e7\u00e3o<\/li>\n<li>Mudan\u00e7as clim\u00e1ticas<\/li>\n<li>Digitaliza\u00e7\u00e3o e intelig\u00eancia artificial<\/li>\n<li>Automa\u00e7\u00e3o f\u00edsica avan\u00e7ada<\/li>\n<li>Envelhecimento populacional<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-63383 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/82-400x267.jpeg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/82-400x267.jpeg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/82-768x512.jpeg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/82-600x400.jpeg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/82.jpeg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><em>\u201cEstamos fazendo um trabalho detalhado e minucioso para formatar um plano de desenvolvimento que n\u00e3o s\u00f3 destaque as potencialidades do nosso Estado, mas tamb\u00e9m revele pontos que possam ser trabalhados na busca por novos investimentos e oportunidades. Este \u00e9 um esfor\u00e7o conjunto, que envolve n\u00e3o s\u00f3 as esferas do governo estadual, mas representantes do empresariado e de entidades, al\u00e9m de especialistas. Isso garante que estamos cobrindo todas as \u00e1reas de conhecimento, n\u00e3o s\u00f3 o econ\u00f4mico, e aprofundando nas quest\u00f5es que assegurar\u00e3o um futuro promissor para o nosso Rio Grande\"<\/em>, disse Ernani Polo.<\/p>\n<p>Os presentes foram convidados a fazerem sugest\u00f5es individuais. Na sequ\u00eancia, houve divis\u00e3o em grupos de 10 a 15 pessoas. Ap\u00f3s uma apresenta\u00e7\u00e3o conceitual, eles propuseram iniciativas concretas, respondendo a perguntas orientadoras. Depois, alguns grupos foram sorteados para compartilhar os principais insights. Eles debateram, por exemplo, como governo e iniciativa privada podem trabalhar juntos para que o Estado se insira nessas tend\u00eancias globais.<\/p>\n<p>Todo o processo de constru\u00e7\u00e3o do plano contou com o aux\u00edlio e acompanhamento da Mckinsey. A consultora est\u00e1 operando junto com equipes t\u00e9cnicas do governo em uma base instalada no Centro Administrativo Fernando Ferrari (Caff). A empresa treinar\u00e1 a equipe que operar\u00e1 a Ag\u00eancia de Desenvolvimento, oferecendo mentoria e capacita\u00e7\u00e3o.<\/p>\n<p><em>\"Esta \u00e9 uma agenda de Estado e n\u00e3o de governo. N\u00e3o \u00e9 algo limitado \u00e0 atual gest\u00e3o. Os impactos deste plano ser\u00e3o de m\u00e9dio a longo prazo. O crescimento econ\u00f4mico \u00e9 um dos pilares, mas olharemos tamb\u00e9m para eixos sociais\u201d,<\/em> destacou Mariela Portz, secret\u00e1ria-executiva do Conselho de Competitividade e Futuro, que ser\u00e1 o curador do plano.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Juliana Dias\/Secom, Ta\u00eds Teixeira\/Ascom Sedec e Ascom Casa Civil | Edi\u00e7\u00e3o: Camila argnelutti\/Secom | Fotos: Maur\u00edcio Tonetto\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A primeira reuni\u00e3o de trabalho de constru\u00e7\u00e3o da nova agenda de desenvolvimento do Rio Grande do Sul foi realizada nesta quarta-feira (10\/4). Organizado pelo governo, o encontro no Pal\u00e1cio Piratini teve a participa\u00e7\u00e3o de empres\u00e1rios e presidentes de entidades de classe. Durante a tarde, houve a apresenta\u00e7\u00e3o do pr\u00e9-diagn\u00f3stico sobre competitividade do Estado, detalhamento das [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63380"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63380\/revisions"}],"predecessor-version":[{"id":63384,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63380\/revisions\/63384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63381"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}