{"id":63433,"date":"2024-04-15T08:47:49","date_gmt":"2024-04-15T11:47:49","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63433"},"modified":"2024-04-15T08:47:50","modified_gmt":"2024-04-15T11:47:50","slug":"governo-inicia-missao-oficial-na-europa-com-inauguracao-do-estande-do-rs-na-vinitaly","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governo-inicia-missao-oficial-na-europa-com-inauguracao-do-estande-do-rs-na-vinitaly\/","title":{"rendered":"Governo inicia miss\u00e3o oficial na Europa com inaugura\u00e7\u00e3o do estande do RS na Vinitaly"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>Sob lideran\u00e7a do governador Eduardo Leite, come\u00e7ou neste domingo (14\/4) a miss\u00e3o oficial do governo ga\u00facho na It\u00e1lia e na Alemanha. A primeira atividade da comitiva, formada por secret\u00e1rios de Estado, foi a inaugura\u00e7\u00e3o do estande do Rio Grande do Sul na Vinitaly, a maior exposi\u00e7\u00e3o de vinhos do mundo, que ocorre em Verona, na It\u00e1lia. O desenlace da fita do espa\u00e7o foi feito por Leite, que celebrou a presen\u00e7a das vin\u00edcolas ga\u00fachas no evento.<\/p>\n<p><em>\u201cA gente est\u00e1 colocando a produ\u00e7\u00e3o ga\u00facha em evid\u00eancia a partir do estande, e a feira tamb\u00e9m \u00e9 uma oportunidade para buscarmos refer\u00eancias. O que observarmos aqui servir\u00e1 como inspira\u00e7\u00e3o para que possamos fazer eventos que consolidem a marca do vinho ga\u00facho e, assim, ajudar no desenvolvimento do Estado. Ao ampliamos o espa\u00e7o do Rio Grande do Sul na feira, a gente vai ganhando relev\u00e2ncia para termos uma presen\u00e7a ainda mais forte ao longo das pr\u00f3ximas edi\u00e7\u00f5es\u201d<\/em>, afirmou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-63435 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/01-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/01-400x267.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/01-768x512.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/01-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/01.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>O estande do governo na Vinitaly est\u00e1 sob responsabilidade das secretarias de Desenvolvimento Econ\u00f4mico, de Turismo e de Agricultura, Pecu\u00e1ria e Irriga\u00e7\u00e3o. No local, que servir\u00e1 para promo\u00e7\u00e3o do setor vitivin\u00edcola e do enoturismo, nove vin\u00edcolas ga\u00fachas v\u00e3o expor seus r\u00f3tulos. O Rio Grande do Sul \u00e9 atualmente o maior produtor de uva, sucos de uva, vinhos e espumante do Brasil. Em 2023, o Estado foi respons\u00e1vel por 90% da produ\u00e7\u00e3o nacional de vinhos e sucos de uva, 85% da produ\u00e7\u00e3o de espumantes e mais da metade da produ\u00e7\u00e3o de uva no Brasil.<\/p>\n<p>Mais cedo, o governador e parte da comitiva se reuniram com o presidente do Grupo Veronafiere, respons\u00e1vel pela feira, Federico Bricolo. A empresa tamb\u00e9m \u00e9 respons\u00e1vel pela organiza\u00e7\u00e3o da Wine South America em Bento Gon\u00e7alves, outro importante evento do setor.<\/p>\n<p>Na segunda-feira (15\/4), a miss\u00e3o tem sequ\u00eancia com uma reuni\u00e3o do governador com o presidente da Regi\u00e3o do V\u00eaneto, Luca Zaia, para discutir poss\u00edveis parcerias com o RS. Ap\u00f3s o encontro, a comitiva seguir\u00e1 para Roma.<\/p>\n<p><strong>A miss\u00e3o internacional<\/strong><\/p>\n<p>O objetivo da miss\u00e3o \u00e9 aprofundar as rela\u00e7\u00f5es culturais e de neg\u00f3cios do Rio Grande do Sul com It\u00e1lia e Alemanha. Em 2025, ser\u00e1 celebrado o anivers\u00e1rio de 150 anos da imigra\u00e7\u00e3o italiana no RS. Nesta ano, ocorre a comemora\u00e7\u00e3o do Bicenten\u00e1rio da Imigra\u00e7\u00e3o Alem\u00e3. A comitiva do governo percorrer\u00e1 duas cidades na It\u00e1lia e quatro na Alemanha para reuni\u00f5es de neg\u00f3cios e encontros institucionais.<\/p>\n<p>Tamb\u00e9m integram a comitiva, os secret\u00e1rios Artur Lemos (Casa Civil), Fabr\u00edcio Peruchin (Justi\u00e7a, Cidadania e Direitos Humanos), Luiz Fernando Rodriguez (Turismo), T\u00e2nia Moreira (Comunica\u00e7\u00e3o) e Pedro Capeluppi (Parcerias e Concess\u00f5es), al\u00e9m do procurador-geral do Estado, Eduardo Cunha da Costa, e o diretor do BRDE e ex-governador, Ranolfo Vieira J\u00fanior. Representam a Assembleia Legislativa o presidente Adolfo Brito, o l\u00edder do governo, Frederico Antunes, e os deputados Guilherme Pasin, Nadine Anflor, Carlos B\u00farigo, Cl\u00e1udio Branchieri, Silvana Covatti e Alo\u00edsio Classmann.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Juliano Rodrigues\/Secom | Edi\u00e7\u00e3o: Marcelo Kervalt\/Secom | Fotos: Mauricio Tonetto \/ Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Sob lideran\u00e7a do governador Eduardo Leite, come\u00e7ou neste domingo (14\/4) a miss\u00e3o oficial do governo ga\u00facho na It\u00e1lia e na Alemanha. A primeira atividade da comitiva, formada por secret\u00e1rios de Estado, foi a inaugura\u00e7\u00e3o do estande do Rio Grande do Sul na Vinitaly, a maior exposi\u00e7\u00e3o de vinhos do mundo, que ocorre em Verona, na [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63433"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63433\/revisions"}],"predecessor-version":[{"id":63436,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63433\/revisions\/63436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63434"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}