{"id":63471,"date":"2024-04-16T09:58:54","date_gmt":"2024-04-16T12:58:54","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63471"},"modified":"2024-04-16T09:58:56","modified_gmt":"2024-04-16T12:58:56","slug":"problemas-vocais-podem-prejudicar-vida-pessoal-de-professores-e-aprendizado-de-alunos-dizem-especialistas","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/problemas-vocais-podem-prejudicar-vida-pessoal-de-professores-e-aprendizado-de-alunos-dizem-especialistas\/","title":{"rendered":"Problemas vocais podem prejudicar vida pessoal de professores e aprendizado de alunos, dizem especialistas"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i>Inc\u00f4modos que permane\u00e7am por mais de 15 dias podem indicar casos s\u00e9rios de les\u00f5es nas cordas vocais e exigem avalia\u00e7\u00e3o de profissional especializado<\/i><\/p>\n<div>\n<p>Os problemas vocais causados pelo uso excessivo da voz podem prejudicar a vida pessoal de professores e o aprendizado de alunos, dizem especialistas do Hospital do Servidor P\u00fablico Estadual (HSPE). O som baixo e inst\u00e1vel das cordas vocais cansadas ou lesionados dificulta a comunica\u00e7\u00e3o desses profissionais e consequentemente que os estudantes escutem e se atentem. Entre os principais sinais do problema est\u00e3o: rouquid\u00e3o, falha ao falar e voz mais grossa ou mais fraca. Dia 16 de abril, o \u201cDia Mundial da Voz\u201d marca a import\u00e2ncia da conscientiza\u00e7\u00e3o sobre os cuidados com a voz para mant\u00ea-la saud\u00e1vel.<br clear=\"none\" \/><br clear=\"none\" \/>A voz \u00e9 um dos principais instrumentos de trabalho dos professores. \u00c9 por meio dela que ensinam e instruem os alunos. Por\u00e9m, o ambiente escolar pode ser barulhento e exigir o uso intenso da voz. Por isso, em alguns momentos, precisam aumentar o volume e pot\u00eancia da fala para competir com sons externos ao da sala de aula.<br clear=\"none\" \/><br clear=\"none\" \/>Ao for\u00e7ar a voz, os professores podem lesionar e desenvolver n\u00f3dulos nas pregas vocais. Os problemas est\u00e3o relacionados a altera\u00e7\u00f5es permanente nas cordas e \u00e0 afonia, perda total da voz. Tamb\u00e9m causa danos \u00e0 vida social e \u00e0 profissional, pois a dificuldade de projetar a fala atrapalha a comunica\u00e7\u00e3o. No caso dos professores, prejudica a explica\u00e7\u00e3o do conte\u00fado e consequentemente no aprendizado dos alunos, que n\u00e3o o escutam e se dispersam com mais facilidade.<br clear=\"none\" \/><br clear=\"none\" \/>A fonoaudi\u00f3loga do HSPE Juliana Santarosa explica tamb\u00e9m que em seu consult\u00f3rio \u00e9 comum os professores relatarem h\u00e1bitos prejudiciais \u00e0 sa\u00fade da voz. <em>\u201cEles precisam falar alto e por muito tempo e, muitas vezes, ingerem pouca \u00e1gua e fazem refei\u00e7\u00f5es com intervalos longos\u201d<\/em>, comenta a especialista.<br clear=\"none\" \/><br clear=\"none\" \/>Tamb\u00e9m traz preju\u00edzos vocais o uso de pastilhas e ch\u00e1s para suavizar inc\u00f4modos causados pelo uso excessivo da voz. Apesar de trazerem al\u00edvio, as alternativas podem mascarar sintomas e facilitar o desenvolvimento de problemas s\u00e9rios nas pregas vocais. Caso os sinais n\u00e3o desapare\u00e7am em 15 dias, deve-se procurar por atendimento especializado.<br clear=\"none\" \/><br clear=\"none\" \/><strong>Confira abaixo dicas aos professores para manter a sa\u00fade da voz:<\/strong><br clear=\"none\" \/>- Tomar pequenos goles de \u00e1gua durante longos per\u00edodos de fala;<br clear=\"none\" \/>- Evitar falar enquanto escreve no quadro, pois o objeto atrapalha a propaga\u00e7\u00e3o do som, facilitando a imposi\u00e7\u00e3o intensa e desnecess\u00e1ria da voz;<br clear=\"none\" \/>\u00a0- Utilizar microfone e outras ferramentas para aumentar o volume da voz e diminuir o esfor\u00e7o das pregas vocais;<br clear=\"none\" \/>\u00a0- \u00a0Alimentar-se regularmente e manter uma dieta balanceada, uma vez que nutri\u00e7\u00e3o e hidrata\u00e7\u00e3o adequadas est\u00e3o relacionadas a boa sa\u00fade da voz;<br clear=\"none\" \/>- Ter uma boa noite de sono, pois durante o descanso o corpo se repara dos danos causados no per\u00edodo de atividades intensas.<\/p>\n<p>\u00a0<\/p>\n<\/div>\n<div>\n<p><strong>Sobre o Iamspe<\/strong><br clear=\"none\" \/>O Instituto de Assist\u00eancia M\u00e9dica ao Servidor P\u00fablico Estadual de S\u00e3o Paulo (Iamspe) \u00e9 o sistema de sa\u00fade do servidor p\u00fablico estadual. Com uma rede de assist\u00eancia pr\u00f3pria e credenciada presente em mais de 160 munic\u00edpios, o Iamspe oferece atendimento a 1,3 milh\u00e3o de pessoas, entre funcion\u00e1rios p\u00fablicos estaduais e seus dependentes.<br clear=\"none\" \/><br clear=\"none\" \/>S\u00e3o mais de duas mil op\u00e7\u00f5es de atendimento no Estado, incluindo hospitais, cl\u00ednicas de fisioterapia, m\u00e9dicos e laborat\u00f3rios de an\u00e1lises cl\u00ednicas e de imagem, al\u00e9m de postos de atendimentos pr\u00f3prios no interior, os Ceamas, e o Hospital do Servidor P\u00fablico Estadual, na Capital. O Iamspe \u00e9 um \u00f3rg\u00e3o do Governo do Estado de S\u00e3o Paulo, vinculado \u00e0 Secretaria de Gest\u00e3o e Governo Digital.<\/p>\n<hr \/>\n<h6><strong>A4&amp;holofote Comunica\u00e7\u00e3o<\/strong><\/h6>\n<\/div>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Inc\u00f4modos que permane\u00e7am por mais de 15 dias podem indicar casos s\u00e9rios de les\u00f5es nas cordas vocais e exigem avalia\u00e7\u00e3o de profissional especializado Os problemas vocais causados pelo uso excessivo da voz podem prejudicar a vida pessoal de professores e o aprendizado de alunos, dizem especialistas do Hospital do Servidor P\u00fablico Estadual (HSPE). O som [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63472,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63471"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63471\/revisions"}],"predecessor-version":[{"id":63473,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63471\/revisions\/63473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63472"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}