{"id":63477,"date":"2024-04-16T10:02:37","date_gmt":"2024-04-16T13:02:37","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63477"},"modified":"2024-04-16T10:02:38","modified_gmt":"2024-04-16T13:02:38","slug":"dinheiro-entre-casais-e-preciso-comunicacao-e-cumplicidade-para-vida-financeira-saudavel","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/dinheiro-entre-casais-e-preciso-comunicacao-e-cumplicidade-para-vida-financeira-saudavel\/","title":{"rendered":"Dinheiro entre casais: \u00e9 preciso comunica\u00e7\u00e3o e cumplicidade para vida financeira saud\u00e1vel"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i>Segundo Thiago Martello, casais precisam aprender a conversar sobre dinheiro naturalmente\u00a0<\/i><\/p>\n<div>\n<p>Dinheiro costuma ser um assunto \u201ctabu\u201d em muitas fam\u00edlias, por isso n\u00e3o \u00e9 dif\u00edcil que mesmo entre parceiros que vivem sob o mesmo teto haja muitas d\u00favidas, falta de informa\u00e7\u00f5es e pouca comunica\u00e7\u00e3o e cumplicidade relacionada ao tema.\u00a0<\/p>\n<p>Segundo Thiago Martello, fundador da\u00a0<a href=\"https:\/\/martelloef.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"0\">Martello EF<\/a>, empresa que abocanhou investidores no programa Shark Tank Brasil ao oferecer uma metodologia pr\u00f3pria, muitos parceiros n\u00e3o t\u00eam ideia de quanto o c\u00f4njuge ganha ou gasta. <em>\u201cMesmo morando juntos, muitas vezes os casais n\u00e3o sabem o que acontece na vida financeira. Podem notar que h\u00e1 algo que n\u00e3o est\u00e1 certo, mas n\u00e3o entendem o porqu\u00ea, j\u00e1 que nunca conversaram sobre o assunto\u201d<\/em>, explica.\u00a0<\/p>\n<p>Martello costuma dar mentoria a muitos casais, ajudando-os a entender mais sobre finan\u00e7as e a colocar a pr\u00f3pria vida financeira na mesa. <em>\u201cMuitas vezes \u00e9 quase uma sess\u00e3o de terapia de casal, pois eles usam o momento para conversar sobre temas que nunca foram colocados em debate antes. \u00c9 nesse momento que o homem percebe, por exemplo, que n\u00e3o est\u00e1 guardando para o futuro, ou a mulher percebe que est\u00e1 contribuindo para a falta de dinheiro da casa ao consumir de forma impulsiva\u201d<\/em>, conta.\u00a0<\/p>\n<p>O especialista acredita que o primeiro passo para um casal conquistar uma vida financeira saud\u00e1vel \u00e9 investir em di\u00e1logo. <em>\u201cSem uma conversa franca sobre receitas, despesas e objetivos comuns n\u00e3o d\u00e1 para sair do lugar. \u00c9 preciso que os dois remem para o mesmo lado para chegarem mais r\u00e1pido aonde querem\u201d<\/em>, diz.\u00a0<\/p>\n<p>Entender que em qualquer casal h\u00e1 diferen\u00e7as motivadas pela cria\u00e7\u00e3o e pelo hist\u00f3rico de vida tamb\u00e9m \u00e9 importante.<em> \u201cNingu\u00e9m \u00e9 igual e viver junto \u00e9 aprender a entender, conviver e equilibrar as diferen\u00e7as. Isso tamb\u00e9m vale para a vida financeira, j\u00e1 que nem sempre o casal ter\u00e1 a mesma forma de lidar com dinheiro. O importante \u00e9 estarem dispostos a encontrar um equil\u00edbrio para o bem do bolso e da rela\u00e7\u00e3o\u201d<\/em>, acredita.\u00a0<\/p>\n<p>Martello ressalta que a quest\u00e3o financeira \u00e9 um dos motivos que mais geram div\u00f3rcios no Pa\u00eds atualmente, por isso quanto antes o casal decidir trat\u00e1-lo como algo essencial, melhor.<em> \u201cMuitas vezes n\u00e3o conseguir\u00e3o sozinhos, por isso \u00e9 importante buscar ajuda assim que sentirem que algo n\u00e3o est\u00e1 indo bem nesse sentido ou, ainda, se desejam realizar alguns objetivos que precisam de dinheiro, como garantir a aposentadoria ou investir. Cada caso \u00e9 um caso, mas \u00e9 poss\u00edvel melhorar sempre. Busque ajuda!\u201d<\/em>, finaliza.\u00a0<\/p>\n<p><br clear=\"none\" \/><strong>Sobre Thiago Martello<\/strong><\/p>\n<p>Planejador Financeiro, fundador da Martello Educa\u00e7\u00e3o Financeira, Administrador de Empresa com P\u00f3s em Finan\u00e7as pela FGV, Assessor de Investimentos pela CVM, Especialista em Investimentos ANBIMA, Corretor de Vida e Previd\u00eancia pela Susep. Embaixador da APOEF (Associa\u00e7\u00e3o de Profissionais, Orientadores e Educadores em Finan\u00e7as).\u00a0<\/p>\n<p>Thiago come\u00e7ou a lidar com educa\u00e7\u00e3o financeira na pr\u00e1tica aos nove anos de idade, ao iniciar seu primeiro empreendimento vendendo balas em sem\u00e1foros da zona leste de S\u00e3o Paulo. De l\u00e1 para c\u00e1, venceu uma s\u00e9rie de desafios. Ele se tornou bacharel em Administra\u00e7\u00e3o e p\u00f3s-graduado em Gest\u00e3o Financeira pela FGV,\u00a0 passou a empreender atrav\u00e9s da Martello Educa\u00e7\u00e3o Financeira, atendeu mais de 1.000 pessoas com base na metodologia DESPLANILHE-SE de sua pr\u00f3pria autoria, e se tornou autor do livro que leva o mesmo nome.\u00a0<\/p>\n<p>Thiago Martello tamb\u00e9m participou da vers\u00e3o brasileira do Shark Tank Brasil, o maior programa de empreendedorismo do mundo. Atualmente, ele fala semanalmente, como especialista, para v\u00e1rios ve\u00edculos da imprensa, entre eles: O Globo, Estad\u00e3o, Folha de S\u00e3o Paulo, Jovem PAN, CNN e outros.<\/p>\n<p>Para saber mais, acesse o site:\u00a0<a href=\"https:\/\/martelloef.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"1\">https:\/\/martelloef.com.br\/<\/a><\/p>\n<hr \/>\n<h6><strong>Carolina Lara Comunica\u00e7\u00e3o<\/strong><\/h6>\n<\/div>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Segundo Thiago Martello, casais precisam aprender a conversar sobre dinheiro naturalmente\u00a0 Dinheiro costuma ser um assunto \u201ctabu\u201d em muitas fam\u00edlias, por isso n\u00e3o \u00e9 dif\u00edcil que mesmo entre parceiros que vivem sob o mesmo teto haja muitas d\u00favidas, falta de informa\u00e7\u00f5es e pouca comunica\u00e7\u00e3o e cumplicidade relacionada ao tema.\u00a0 Segundo Thiago Martello, fundador da\u00a0Martello EF, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63477"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63477\/revisions"}],"predecessor-version":[{"id":63479,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63477\/revisions\/63479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63478"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}