{"id":63572,"date":"2024-04-18T09:38:06","date_gmt":"2024-04-18T12:38:06","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63572"},"modified":"2024-04-18T09:38:07","modified_gmt":"2024-04-18T12:38:07","slug":"35o-entrevero-cultural-de-peoes-realizado-pelo-mtg-reune-25-regioes-tradicionalistas-do-rs","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/35o-entrevero-cultural-de-peoes-realizado-pelo-mtg-reune-25-regioes-tradicionalistas-do-rs\/","title":{"rendered":"35\u00ba Entrevero Cultural de Pe\u00f5es realizado pelo MTG re\u00fane 25 Regi\u00f5es Tradicionalistas do RS"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Cerca de mil participantes s\u00e3o aguardados no evento que acontece na regi\u00e3o noroeste do estado<\/em><\/p>\n<p>O Movimento Tradicionalista Ga\u00facho (MTG) se prepara para mais uma edi\u00e7\u00e3o do Entrevero Cultural de Pe\u00f5es, que celebra a cultura ga\u00facha e a juventude, ocorrendo nos dias 18, 19 e 20 de abril em Entre-Iju\u00eds e Santo \u00c2ngelo. <br \/><br \/>Com o intuito de eleger representantes jovens masculinos da tradi\u00e7\u00e3o, o Entrevero Cultural de Pe\u00f5es re\u00fane cerca de 1.000 participantes, incluindo as categorias Pi\u00e1 (mirim), Guri (juvenil) e Pe\u00e3o (adulto), abrangendo todas as entidades filiadas ao MTG. Durante o evento, os participantes s\u00e3o avaliados em conhecimentos hist\u00f3ricos e geogr\u00e1ficos, habilidades art\u00edsticas e, especialmente, conhecimento e desenvoltura nas lides campeiras.<br \/><br \/>O evento contar\u00e1 com 48 concorrentes e ir\u00e1 reunir 25 Regi\u00f5es Tradicionalistas do RS. Para Iara Vanice Rott, presidente da Comiss\u00e3o Organizadora do 35\u00ba Entrevero Cultural de Pe\u00f5es, a iniciativa \u00e9 importante para enaltecer a cultura ga\u00facha.<br \/><br \/><em>\"O Entrevero \u00e9 importante para valorizar a nossa cultura, incentivar crian\u00e7as e jovens a cada vez mais estarem inserido no meio tradicionalista, bem como a \u00e1rea tur\u00edstica da nossa regi\u00e3o missioneira, que est\u00e1 sendo amplamente divulgada'<\/em>', relata.<br \/><br \/>Para esta edi\u00e7\u00e3o, foram escolhidos como padrinhos Cesar Augusto Gallert Felipin e Lucas Dayran Vieira, que j\u00e1 se destacaram no tradicionalismo ga\u00facho. <br \/><br \/><strong>Confira abaixo a programa\u00e7\u00e3o do evento:<\/strong><br \/><br \/><strong>18\/04 - QUINTA-FEIRA<\/strong><br \/><br \/>13h - Recep\u00e7\u00e3o e Credenciamento - CTG Passo do lju\u00ed<br \/><br \/>14h - Passeio com os concorrentes - S\u00edtio Arqueol\u00f3gico S\u00e3o Jo\u00e3o Batista - Entre-lju\u00eds<br \/><br \/>18h30min - B\u00ean\u00e7\u00e3o aos participantes e Despedida<br \/><br \/>20h30min - Jantar - CTG Passo do lju\u00ed<br \/><br \/><strong>19\/04- SEXTA-FEIRA<\/strong><br \/><br \/>8h30min - Prova Escrita - CTG O Grito de Sep\u00e9<br \/><br \/>11h30min - Almo\u00e7o - CTG Passo do lju\u00ed<br \/><br \/>13h - In\u00edcio das Provas Art\u00edsticas<br \/><br \/>- Catogoria Pi\u00e1 - Associa\u00e7\u00e3o dos Servidores Municipais de Entre-jufs - ASMEI<br \/><br \/>Categoria Guri - Sal\u00e3o Paroquial Comunidade S\u00e3o Jo\u00e3o Batista<br \/><br \/>- Categoria Pe\u00e3o - Rua Coberta<br \/><br \/>20h30min - Sess\u00e3o Solene de Abertura do 35\u00b0 Entrevero Cultural de Pe\u00f5es, Guris e Pl\u00e1s Farroupilhas do Rio Grande do Sul - Sal\u00e3o paroquial comunidade S\u00e3o Jo\u00e3o Batista<br \/><br \/>21h - Jantar - CTG Passo do lju\u00ed<br \/><br \/><strong>20\/04 - S\u00c1BADO<\/strong><br \/><br \/>8h30min - Provas Campeiras - Parque de Exposi\u00e7\u00f5es Siegfried Ritter - Fenamilho - Santo \u00c2ngelo<br \/><br \/>11h30min - Almo\u00e7o- GTF Cel Apar\u00edcio Borges - Fenamilho<br \/><br \/>20h - Jantar - GTF Cel Apar\u00edcio Borges - Fenamilho<br \/><br \/>22h30min - Fandango e divulga\u00e7\u00e3o dos resultados do 35\u00b0 Entrovero Cultural de Po\u00f5es, Guris e Pl\u00e1s do Rio Grando do Sul - Sal\u00e3o da Comunidade Luterana S\u00e3o Paulo - Esquina Ga\u00facha<br \/><br \/>Anima\u00e7\u00e3o: Grupo Bem Campeiro - Valor: R$ 50,00<br \/><br \/>Traje: Pilcha Social completa<br \/><br \/>Para mais informa\u00e7\u00f5es sobre a programa\u00e7\u00e3o, acesse o site https:\/\/passodoijui.com.br\/#\/programacao.<\/p>\n<p><br \/><strong>Sobre o MTG<\/strong><\/p>\n<p>O Movimento Tradicionalista Ga\u00facho, conhecido como MTG, \u00e9 uma organiza\u00e7\u00e3o que preserva e promove a cultura e as tradi\u00e7\u00f5es do Rio Grande do Sul. Fundado em 1967, tem como objetivo principal preservar e difundir os costumes ga\u00fachos, como a m\u00fasica, a dan\u00e7a, a culin\u00e1ria e as vestimentas t\u00edpicas. \u00c9 respons\u00e1vel por coordenar os Centros de Tradi\u00e7\u00f5es Ga\u00fachas (CTGs), onde s\u00e3o realizados eventos culturais, festivais de m\u00fasica e dan\u00e7a, al\u00e9m de competi\u00e7\u00f5es de la\u00e7o e rodeios crioulos. Desempenha um papel fundamental na manuten\u00e7\u00e3o da identidade e no fortalecimento do orgulho ga\u00facho entre as gera\u00e7\u00f5es.<\/p>\n<hr \/>\n<h6><strong>PlayPress | MTG - Movimento Tradicionalista Ga\u00facho | Marcelo Roxo Matusiak<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cerca de mil participantes s\u00e3o aguardados no evento que acontece na regi\u00e3o noroeste do estado O Movimento Tradicionalista Ga\u00facho (MTG) se prepara para mais uma edi\u00e7\u00e3o do Entrevero Cultural de Pe\u00f5es, que celebra a cultura ga\u00facha e a juventude, ocorrendo nos dias 18, 19 e 20 de abril em Entre-Iju\u00eds e Santo \u00c2ngelo. Com o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63572"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63572\/revisions"}],"predecessor-version":[{"id":63574,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63572\/revisions\/63574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63573"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}