{"id":63683,"date":"2024-04-23T09:54:55","date_gmt":"2024-04-23T12:54:55","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63683"},"modified":"2024-04-23T09:54:56","modified_gmt":"2024-04-23T12:54:56","slug":"liga-gaucha-de-voleibol-de-base-rolante-sports-consegue-bons-resultados-na-1a-etapa-do-campeonato","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/liga-gaucha-de-voleibol-de-base-rolante-sports-consegue-bons-resultados-na-1a-etapa-do-campeonato\/","title":{"rendered":"LIGA GA\u00daCHA DE VOLEIBOL DE BASE: Rolante Sports consegue bons resultados na 1\u00aa etapa do campeonato"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>A Rolante Sports, com o Projeto de V\u00f4lei, participou da 1\u00aa etapa da Liga Ga\u00facha de Voleibol de Base no \u00faltimo domingo, 21, no Centro Ol\u00edmpico Canoas, nas categorias Infanto Masculino e Infanto Feminino (2006\/2007\/2008).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-63685 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/2-12-400x320.jpg\" alt=\"\" width=\"400\" height=\"320\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/2-12-400x320.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/2-12-768x614.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/04\/2-12.jpg 1440w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A categoria Infanto Masculino disputou tr\u00eas jogos, vencendo dois confrontos e perdendo apenas um. <em>\u201cA Rolante Sports enfrentou equipes muito qualificadas e, apesar de ser uma equipe muito jovem, com a base formada por atletas 2007, 2008 e contar com alguns 2009, e ter tido alguns desfalques nesta primeira etapa do campeonato, entramos em quadra e conseguimos jogar de igual para igual com as equipes advers\u00e1rias. Foi muito positivo\u201d<\/em>, avalia o coordenador do Projeto de V\u00f4lei, professor R\u00f4mulo Ara\u00fajo.<\/p>\n<p>Confira o resultado dos confrontos:<\/p>\n<p>Gua\u00edba 0 x 2 Rolante Sports<br \/>Rolante Sports 2 x 1 GNU<br \/>Rolante Sports 0 x 2 Ace Voleibol<\/p>\n<p>A equipe Infanto Feminina, formada por atletas ainda mais jovens, 2008 e 2009 e uma atleta 2011, que foi titular na maior parte dos jogos, venceu os tr\u00eas confrontos. <em>\u201cForam jogos muito disputados, com sets bem equilibrados\u201d<\/em>, comenta Ara\u00fajo.<\/p>\n<p>Confira o resultado dos confrontos:<\/p>\n<p>Rolante Sports 2 x 1 GNGa\u00facho<br \/>GNU 0 x 2 Rolante Sports<br \/>Geraldo Santana 1 x 2 Rolante Sports<br \/>A Rolante Sports disputar\u00e1 a 2\u00aa etapa da Liga Ga\u00facha de V\u00f4lei no Gr\u00eamio N\u00e1utico Uni\u00e3o, em Porto Alegre, no dia 30 de junho.<\/p>\n<p>#somostodosrolantesports<\/p>\n<hr \/>\n<h6><strong>Rolante Sports<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Rolante Sports, com o Projeto de V\u00f4lei, participou da 1\u00aa etapa da Liga Ga\u00facha de Voleibol de Base no \u00faltimo domingo, 21, no Centro Ol\u00edmpico Canoas, nas categorias Infanto Masculino e Infanto Feminino (2006\/2007\/2008). A categoria Infanto Masculino disputou tr\u00eas jogos, vencendo dois confrontos e perdendo apenas um. \u201cA Rolante Sports enfrentou equipes muito [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63683"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63683\/revisions"}],"predecessor-version":[{"id":63686,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63683\/revisions\/63686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63684"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}