{"id":63880,"date":"2024-04-30T10:24:37","date_gmt":"2024-04-30T13:24:37","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63880"},"modified":"2024-04-30T10:24:38","modified_gmt":"2024-04-30T13:24:38","slug":"terca-30-e-o-ultimo-dia-para-que-condutores-das-categorias-c-d-e-e-realizem-exame-toxicologico","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/terca-30-e-o-ultimo-dia-para-que-condutores-das-categorias-c-d-e-e-realizem-exame-toxicologico\/","title":{"rendered":"Ter\u00e7a (30) \u00e9 o \u00faltimo dia para que condutores das categorias C, D e E realizem exame toxicol\u00f3gico"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>O fim do prazo para realiza\u00e7\u00e3o do exame toxicol\u00f3gico \u00e9 na ter\u00e7a (30\/4). Mais de 3,4 milh\u00f5es de condutores das categorias C, D e E (para dirigir\u00a0\u00f4nibus e caminh\u00f5es)\u00a0ainda est\u00e3o em situa\u00e7\u00e3o irregular em todo o Brasil, sendo que 168 mil s\u00e3o do Rio Grande do Sul. O prazo para o primeiro grupo de condutores com vencimento da Carteira Nacional de Habilita\u00e7\u00e3o (CNH) entre janeiro e junho, terminou em 31 de mar\u00e7o.<\/p>\n<p>Caso esses motoristas n\u00e3o fa\u00e7am o teste at\u00e9 30 de abril, poder\u00e3o ser autuados diretamente pelos sistemas eletr\u00f4nicos a partir de 1\u00ba de maio, conforme o artigo 165-D do C\u00f3digo de Tr\u00e2nsito Brasileiro (CTB). A n\u00e3o realiza\u00e7\u00e3o do exame dentro do per\u00edodo estabelecido \u00e9 considerada infra\u00e7\u00e3o grav\u00edssima, sujeita a multa de R$ 1.467,35 e sete pontos na CNH.<\/p>\n<p>A Secretaria Nacional de Tr\u00e2nsito (Senatran) notificou os atrasados via Carteira Digital de Tr\u00e2nsito (CDT) e criou uma p\u00e1gina na qual os motoristas podem consultar se precisam ou n\u00e3o fazer o teste.<\/p>\n<ul>\n<li><strong><a href=\"https:\/\/portalservicos.senatran.serpro.gov.br\/#\/condutor\/consultar-toxicologico\" target=\"_blank\" rel=\"noopener\">Link para a p\u00e1gina de consulta<\/a><\/strong><\/li>\n<\/ul>\n<p>Motoristas que possuem a CNH nas categorias C, D ou E e n\u00e3o dirigem mais ou que moram fora do pa\u00eds podem pedir o cancelamento da CNH para evitar serem autuados pela infra\u00e7\u00e3o. O DetranRS encaminhar\u00e1 a informa\u00e7\u00e3o para a Senatran, ap\u00f3s cancelar o registro da CNH na base estadual.<\/p>\n<p>Se o condutor ainda dirige moto ou autom\u00f3vel e n\u00e3o precisa mais que a CNH esteja inclu\u00edda nas categorias C, D e E pode solicitar o rebaixamento de categoria, j\u00e1 que a as categoria A e B n\u00e3o exigem o exame toxicol\u00f3gico.\u00a0Ambos os servi\u00e7os podem ser realizados nos Centros de Forma\u00e7\u00e3o de Condutores (CFC) do RS.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.detran.rs.gov.br\/habilitacao-cnh\/servicos\/823\" target=\"_blank\" rel=\"noopener\"><strong>Link para os endere\u00e7os dos CFCs<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom DetranRS | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O fim do prazo para realiza\u00e7\u00e3o do exame toxicol\u00f3gico \u00e9 na ter\u00e7a (30\/4). Mais de 3,4 milh\u00f5es de condutores das categorias C, D e E (para dirigir\u00a0\u00f4nibus e caminh\u00f5es)\u00a0ainda est\u00e3o em situa\u00e7\u00e3o irregular em todo o Brasil, sendo que 168 mil s\u00e3o do Rio Grande do Sul. O prazo para o primeiro grupo de condutores [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63881,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63880"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63880\/revisions"}],"predecessor-version":[{"id":63882,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63880\/revisions\/63882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63881"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}