{"id":63929,"date":"2024-05-03T10:32:45","date_gmt":"2024-05-03T13:32:45","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=63929"},"modified":"2024-05-03T10:32:48","modified_gmt":"2024-05-03T13:32:48","slug":"governador-alerta-que-nivel-do-guaiba-pode-alcancar-recorde-historico-em-porto-alegre","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governador-alerta-que-nivel-do-guaiba-pode-alcancar-recorde-historico-em-porto-alegre\/","title":{"rendered":"Governador alerta que n\u00edvel do Gua\u00edba pode alcan\u00e7ar recorde hist\u00f3rico em Porto Alegre"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Previs\u00e3o indica que at\u00e9 s\u00e1bado o lago pode atingir cinco metros<\/em><\/p>\n<p>Em transmiss\u00e3o virtual realizada na noite desta quinta-feira (2\/5), o governador Eduardo Leite alertou para a r\u00e1pida eleva\u00e7\u00e3o observada nas \u00faltimas horas no Gua\u00edba, em Porto Alegre, que pode atingir quatro metros ao longo da madrugada de sexta-feira (3\/5), podendo chegar a cinco metros at\u00e9 s\u00e1bado. Caso a previs\u00e3o se confirme, essa ser\u00e1 a maior cheia da hist\u00f3ria da capital ga\u00facha, superando a enchente registrada em 1941.<\/p>\n<p>\u201c<em>Quero pedir mais uma vez que as pessoas tenham a percep\u00e7\u00e3o de urg\u00eancia em rela\u00e7\u00e3o ao que est\u00e1 ocorrendo no Estado. \u00c9 muito importante que a popula\u00e7\u00e3o leve a s\u00e9rio as recomenda\u00e7\u00f5es e busque se proteger, que atenda a esse chamado da emerg\u00eancia sem precedentes que estamos vivendo e deixe as zonas de risco<\/em>\u201d, enfatizou Leite.<\/p>\n<p>O governador ressaltou a magnitude da cat\u00e1strofe natural que vem afetando o Estado desde a madrugada de segunda-feira (29\/4). Segundo Leite, considerando as previs\u00f5es de chuva intensa dos pr\u00f3ximos dias, o evento meteorol\u00f3gico em curso ser\u00e1, possivelmente, a maior trag\u00e9dia ambiental da hist\u00f3ria do Rio Grande do Sul.<\/p>\n<p>\u201c<em>Quero dizer \u00e0 popula\u00e7\u00e3o que, como ser humano, eu estou devastado por dentro, como cada um dos ga\u00fachos est\u00e1. Mas, como governador, estou aqui firme e garanto que n\u00e3o vamos titubear. Estamos fazendo tudo com foco, aten\u00e7\u00e3o, disciplina e indigna\u00e7\u00e3o, para que tudo que esteja ao nosso alcance seja feito, para colocar todas as estruturas em campo e garantir que todas as pessoas que est\u00e3o suplicando por resgate\u00a0sejam salvas<\/em>\u201d, afirmou.<\/p>\n<p>Levantamentos hidrol\u00f3gicos apontam que os rios Ca\u00ed, Taquari e Jacu\u00ed est\u00e3o enfrentando as maiores cheias j\u00e1 registradas, com previs\u00e3o de aumento dos respectivos n\u00edveis nas pr\u00f3ximas horas. A instabilidade clim\u00e1tica persiste no Estado e,\u00a0at\u00e9 s\u00e1bado (4\/5),\u00a0deve avan\u00e7ar para as regi\u00f5es da Serra e do Litoral Norte.<\/p>\n<p><strong>Salvamentos<\/strong><\/p>\n<p>O coordenador da Defesa Civil do Estado, coronel Luciano Boeira, apresentou um balan\u00e7o do trabalho das for\u00e7as de resposta do Estado nas opera\u00e7\u00f5es de salvamento. At\u00e9 o momento, foram resgatadas mais de 4.600 pessoas. As v\u00edtimas foram acolhidas pelas equipes de seguran\u00e7a e encaminhadas para atendimento m\u00e9dico ou direcionadas para abrigos p\u00fablicos.<\/p>\n<p><strong>Barragens<\/strong><\/p>\n<p>O governador destacou a situa\u00e7\u00e3o cr\u00edtica da barragem Blang, no rio Ca\u00ed, pr\u00f3ximo de S\u00e3o Francisco de Paula, que est\u00e1 sob vigil\u00e2ncia intensa devido ao risco de rompimento. Ele mencionou conversas com a Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel), autarquia respons\u00e1vel pela fiscaliza\u00e7\u00e3o da represa, que assegurou a ado\u00e7\u00e3o imediata de medidas de emerg\u00eancia. Outra barragem em estado cr\u00edtico \u00e9 a de S\u00e3o Miguel, perto de Bento Gon\u00e7alves e Pinto Bandeira. Evacua\u00e7\u00f5es j\u00e1 est\u00e3o sendo realizadas nas localidades pr\u00f3ximas.<\/p>\n<p><strong>Bases avan\u00e7adas<\/strong><\/p>\n<p>Leite ressaltou a import\u00e2ncia dos gabinetes de crise avan\u00e7ados, instalados em Santa Cruz do Sul, Bento Gon\u00e7alves e S\u00e3o Sebasti\u00e3o do Ca\u00ed, para a coordena\u00e7\u00e3o das opera\u00e7\u00f5es de resgate e para responder de maneira eficaz \u00e0s emerg\u00eancias nas regi\u00f5es mais afetadas.<\/p>\n<p>\u201c<em>Estamos em permanente contato com os gabinetes avan\u00e7ados, ajudando a fazer todas as a\u00e7\u00f5es de campo, priorizando o resgate e o salvamento de vidas. Esses postos olham para todas as regi\u00f5es pr\u00f3ximas, em contato direto com as for\u00e7as de seguran\u00e7a e as prefeituras\u201d<\/em>, disse Leite.<\/p>\n<p>Participaram da coletiva o vice-governador Gabriel Souza, que coordena o posto avan\u00e7ado em Santa Cruz do Sul; o chefe da Casa Civil, Artur Lemos, que lidera a base de Bento Gon\u00e7alves; e o chefe de gabinete do governador, coronel Euclides Neto, que est\u00e1 \u00e0 frente do gabinete alocado em S\u00e3o Sebasti\u00e3o do Ca\u00ed.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Rodrigo Azevedo\/Secom | Edi\u00e7\u00e3o: Rodrigo Toledo Fran\u00e7a\/Secom | Foto: Lauro Alves\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n\n\n\n<p><\/p>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o indica que at\u00e9 s\u00e1bado o lago pode atingir cinco metros Em transmiss\u00e3o virtual realizada na noite desta quinta-feira (2\/5), o governador Eduardo Leite alertou para a r\u00e1pida eleva\u00e7\u00e3o observada nas \u00faltimas horas no Gua\u00edba, em Porto Alegre, que pode atingir quatro metros ao longo da madrugada de sexta-feira (3\/5), podendo chegar a cinco metros [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":63930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-63929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=63929"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63929\/revisions"}],"predecessor-version":[{"id":63931,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/63929\/revisions\/63931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/63930"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=63929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=63929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=63929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}