{"id":64070,"date":"2024-05-08T16:41:03","date_gmt":"2024-05-08T19:41:03","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=64070"},"modified":"2024-05-08T16:41:04","modified_gmt":"2024-05-08T19:41:04","slug":"arrozeiros-garantem-que-nao-faltara-arroz-mesmo-com-as-enchentes-no-rio-grande-do-sul","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/arrozeiros-garantem-que-nao-faltara-arroz-mesmo-com-as-enchentes-no-rio-grande-do-sul\/","title":{"rendered":"Arrozeiros garantem que n\u00e3o faltar\u00e1 arroz mesmo com as enchentes no Rio Grande do Sul"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Para a Federarroz, o que j\u00e1 foi colhido tem condi\u00e7\u00f5es plenas de abastecimento do mercado interno e n\u00e3o h\u00e1 necessidade de importa\u00e7\u00e3o<\/em><\/p>\n<p>\u00a0<\/p>\n<p>A colheita de arroz no Rio Grande do Sul, at\u00e9 o momento, chegou a 83% do total da \u00e1rea prevista e o que j\u00e1 foi colhido apresenta boa qualidade e produtividade, o que garante o abastecimento dos brasileiros. A informa\u00e7\u00e3o \u00e9 da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es de Arrozeiros do Rio Grande do Sul (Federarroz).<\/p>\n<p>Segundo o presidente da entidade, Alexandre Velho, dentro do espectro dos 83% j\u00e1 colhidos, se apresentam boas m\u00e9dias de produtividade. \"<em>J\u00e1 temos um bom volume de arroz e mesmo que a gente tenha dificuldades na colheita deste saldo que falta colher, certamente o Rio Grande do Sul tem plenas condi\u00e7\u00f5es de colher uma safra bem acima dos sete milh\u00f5es de toneladas. Embora tenhamos este grande problema com rela\u00e7\u00e3o \u00e0 colheita do que falta, n\u00f3s temos plenas condi\u00e7\u00f5es de afirmar que n\u00f3s n\u00e3o temos problemas com rela\u00e7\u00e3o ao abastecimento do mercado interno<\/em>\", garante.<\/p>\n<p>Conforme o dirigente, h\u00e1 um problema moment\u00e2neo de log\u00edstica, principalmente na liga\u00e7\u00e3o com o interior do Rio Grande do Sul. \"<em>Mas a liga\u00e7\u00e3o com os grandes centros atrav\u00e9s da BR-101 est\u00e1 normal, temos bastante arroz para deslocar para as regi\u00f5es centrais do Brasil. Ent\u00e3o n\u00e3o existe qualquer problema com rela\u00e7\u00e3o ao abastecimento ou uma necessidade urgente de importa\u00e7\u00e3o. O Brasil \u00e9 um grande produtor de arroz, a \u00e1rea aumentou aqui no Rio Grande do Sul, assim como em outros Estados produtores. Ent\u00e3o n\u00e3o existe motivo algum para n\u00f3s termos qualquer alerta com rela\u00e7\u00e3o a problemas de abastecimento com rela\u00e7\u00e3o ao arroz<\/em>\", avalia.<\/p>\n<p>Velho ressalta que este momento \u00e9 de auxiliar os produtores, deixar baixar as \u00e1guas para poder chegar nas lavouras e, desta forma, poder quantificar e ver realmente o tamanho do preju\u00edzo.<\/p>\n<hr \/>\n<h6><strong>AgroEffective | Assessoria de Comunica\u00e7\u00e3o da Federa\u00e7\u00e3o das Associa\u00e7\u00f5es de Arrozeiros do Rio Grande do Sul (Federarroz) | Foto: Paulo Rossi\/Divulga\u00e7\u00e3o | Texto: Nestor Tipa J\u00fanior\/AgroEffective<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Para a Federarroz, o que j\u00e1 foi colhido tem condi\u00e7\u00f5es plenas de abastecimento do mercado interno e n\u00e3o h\u00e1 necessidade de importa\u00e7\u00e3o \u00a0 A colheita de arroz no Rio Grande do Sul, at\u00e9 o momento, chegou a 83% do total da \u00e1rea prevista e o que j\u00e1 foi colhido apresenta boa qualidade e produtividade, o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=64070"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64070\/revisions"}],"predecessor-version":[{"id":64072,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64070\/revisions\/64072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/64071"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=64070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=64070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=64070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}