{"id":64079,"date":"2024-05-08T16:53:51","date_gmt":"2024-05-08T19:53:51","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=64079"},"modified":"2024-05-08T16:53:52","modified_gmt":"2024-05-08T19:53:52","slug":"concessionaria-atua-para-liberar-ers-122-entre-nova-milano-e-sao-vendelino","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/concessionaria-atua-para-liberar-ers-122-entre-nova-milano-e-sao-vendelino\/","title":{"rendered":"Concession\u00e1ria atua para liberar ERS-122, entre Nova Milano e S\u00e3o Vendelino"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>Com a estabilidade do solo e a seguran\u00e7a necess\u00e1ria para que funcion\u00e1rios e maquin\u00e1rios possam atuar na ERS-122, a concession\u00e1ria Caminhos da Serra Ga\u00facha (CSG), que administra as rodovias do Bloco 3, iniciou na manh\u00e3 desta quarta-feira (8) os reparos entre os km 39 e 51 da rodovia.<\/p>\n<p>O trecho, que liga a comunidade de Nova Milano (Farroupilha) a cidade de S\u00e3o Vendelino, est\u00e1 bloqueado desde o dia 1\u00ba de maio, devido \u00e0 queda de barreiras, deslizamento de pedras e rompimento de pista.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-64082 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/05\/1-4-400x225.jpg\" alt=\"\" width=\"400\" height=\"225\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/05\/1-4-400x225.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/05\/1-4-768x432.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/05\/1-4.jpg 1280w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Pontos liberados nas rodovias do Bloco 3, na Serra e Vale do Ca\u00ed:<\/strong><\/p>\n<p>ERS-122, entre os km 103 e 115, entre Flores da Cunha e Ant\u00f4nio Prado. Tr\u00e2nsito em pare e siga <br \/>ERS-122, dos km 0 ao 39, entre Port\u00e3o e S\u00e3o Vendelino; <br \/>ERS-446, dos km 0 ao 14, entre Carlos Barbosa e S\u00e3o Vendelino; <br \/>RSC-287, dos km 0 ao 21, entre Montenegro e S\u00e3o Leopoldo; <br \/>ERS-240, dos km 0 ao 33, entre Montenegro e S\u00e3o Leopoldo<\/p>\n<hr \/>\n<h6><strong>CSG - Caminhos da Serra Ga\u00facha | Fotos: CSG divulga\u00e7\u00e3o<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Com a estabilidade do solo e a seguran\u00e7a necess\u00e1ria para que funcion\u00e1rios e maquin\u00e1rios possam atuar na ERS-122, a concession\u00e1ria Caminhos da Serra Ga\u00facha (CSG), que administra as rodovias do Bloco 3, iniciou na manh\u00e3 desta quarta-feira (8) os reparos entre os km 39 e 51 da rodovia. O trecho, que liga a comunidade de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=64079"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64079\/revisions"}],"predecessor-version":[{"id":64083,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64079\/revisions\/64083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/64080"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=64079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=64079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=64079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}