{"id":64450,"date":"2024-05-17T09:33:50","date_gmt":"2024-05-17T12:33:50","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=64450"},"modified":"2024-05-17T09:33:51","modified_gmt":"2024-05-17T12:33:51","slug":"portos-rs-prepara-campanha-para-entrega-de-donativos-as-vitimas-das-enchentes","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/portos-rs-prepara-campanha-para-entrega-de-donativos-as-vitimas-das-enchentes\/","title":{"rendered":"Portos RS prepara campanha para entrega de donativos \u00e0s v\u00edtimas das enchentes"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>A Portos RS, administradora dos portos de Porto Alegre, Pelotas e Rio Grande, em conjunto com o Minist\u00e9rio de Portos e Aeroportos e demais autoridades portu\u00e1rias brasileiras, est\u00e1 envolvida na campanha de arrecada\u00e7\u00e3o de donativos para as v\u00edtimas das enchentes.<\/p>\n<p>A estimativa \u00e9 de que cerca de 1.480 toneladas de doa\u00e7\u00f5es sejam transportadas para o Estado com \u00e1gua mineral, vestu\u00e1rio, colch\u00f5es, cobertas, produtos de higiene pessoal e de limpeza, entre outros n\u00e3o perec\u00edveis. Al\u00e9m de estarem envolvidos na arrecada\u00e7\u00e3o de donativos, os \u00f3rg\u00e3os tamb\u00e9m atuam na entrega de todo material que chega pelos portos.<\/p>\n<p>Segundo o presidente da Portos RS, Cristiano Klinger, o objetivo \u00e9 unir for\u00e7as para salvar vidas. <em>\"Vivemos um dos epis\u00f3dios mais tristes da hist\u00f3ria do Rio Grande do Sul e sabemos que nesse momento a uni\u00e3o \u00e9 a melhor forma de superarmos tudo isso. O envio desses materiais at\u00e9 o complexo portu\u00e1rio do Rio Grande demonstra a solidariedade dos brasileiros. Como autoridade portu\u00e1ria, n\u00e3o poder\u00edamos ficar atentos apenas \u00e0 situa\u00e7\u00e3o dos portos sob a nossa administra\u00e7\u00e3o\"<\/em>, destacou o presidente.<\/p>\n<p>O Terminal de Cont\u00eaineres Wilson Sons - Tecon Rio Grande - ser\u00e1 o local de recebimento dos navios que trar\u00e3o as doa\u00e7\u00f5es das diversas regi\u00f5es do pa\u00eds. O Distrito Federal e os estados de Goi\u00e1s, S\u00e3o Paulo, Rio de Janeiro, Bahia e Pernambuco est\u00e3o encaminhando 25 cont\u00eaineres de 40 p\u00e9s carregados com doa\u00e7\u00f5es, o que equivale a aproximadamente 700 toneladas. A previs\u00e3o \u00e9 de que as primeiras duas embarca\u00e7\u00f5es atraquem no complexo portu\u00e1rio rio-grandino nos dias 19 e 26 de maio.<\/p>\n<p>O Porto do Rio Grande, \u00fanico do Estado aberto para opera\u00e7\u00f5es, j\u00e1 recebeu cerca de 460 toneladas para as v\u00edtimas das enchentes. A partir do recebimento na unidade, os donativos s\u00e3o transportados at\u00e9 o cais p\u00fablico, local onde s\u00e3o armazenados e distribu\u00eddos pela Defesa Civil, Ex\u00e9rcito, Marinha e demais entidades envolvidas.<\/p>\n<hr \/>\n<h6><strong><sub>GOV RS | Texto: Comunica\u00e7\u00e3o Portos RS | <\/sub><sub>Edi\u00e7\u00e3o: Anelize Sampaio\/Secom RS | Foto: Comunica\u00e7\u00e3o Portos RS<\/sub><\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A Portos RS, administradora dos portos de Porto Alegre, Pelotas e Rio Grande, em conjunto com o Minist\u00e9rio de Portos e Aeroportos e demais autoridades portu\u00e1rias brasileiras, est\u00e1 envolvida na campanha de arrecada\u00e7\u00e3o de donativos para as v\u00edtimas das enchentes. A estimativa \u00e9 de que cerca de 1.480 toneladas de doa\u00e7\u00f5es sejam transportadas para o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64450","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=64450"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64450\/revisions"}],"predecessor-version":[{"id":64452,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64450\/revisions\/64452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/64451"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=64450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=64450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=64450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}