{"id":64528,"date":"2024-05-20T11:11:03","date_gmt":"2024-05-20T14:11:03","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=64528"},"modified":"2024-05-20T11:11:04","modified_gmt":"2024-05-20T14:11:04","slug":"cdl-sapiranga-e-sistema-cndl-atuam-juntas-em-campanha-de-doacao-para-vitimas-das-enchentes-no-rs","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/cdl-sapiranga-e-sistema-cndl-atuam-juntas-em-campanha-de-doacao-para-vitimas-das-enchentes-no-rs\/","title":{"rendered":"CDL Sapiranga e Sistema CNDL atuam juntas em campanha de doa\u00e7\u00e3o para v\u00edtimas das enchentes no RS"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i>A\u00e7\u00e3o solid\u00e1ria liderada pela Federa\u00e7\u00e3o Varejista do Rio Grande do Sul visa auxiliar popula\u00e7\u00e3o ga\u00facha afetada pelas fortes chuvas<\/i><\/p>\n<div>\n<div>A CDL Sapiranga, integrante do sistema CNDL, une esfor\u00e7os com outras CDLs e Federa\u00e7\u00f5es de todo o pa\u00eds em uma campanha de solidariedade para ajudar as v\u00edtimas das enchentes que assolaram o Rio Grande do Sul. Em parceria com a CNDL, o Sicredi lan\u00e7ou uma iniciativa onde a cada R$ 1 doado, o Sicredi contribuir\u00e1 com mais R$ 1 para a campanha.<\/div>\n<div>\u00a0<\/div>\n<div>\"<em>Estamos unidos em uma ampla rede de solidariedade ao povo ga\u00facho. O Sistema CNDL est\u00e1 mobilizado para levar doa\u00e7\u00f5es aos necessitados. Pedimos a quem puder ajudar, que contribua com qualquer valor<\/em>\", afirmou o presidente da CNDL, Jos\u00e9 C\u00e9sar da Costa.<\/div>\n<div>\u00a0<\/div>\n<div>Roque Pellizzaro J\u00fanior, presidente do SPC Brasil, ressalta a import\u00e2ncia da parceria com o Sicredi.<\/div>\n<div>\u00a0<\/div>\n<div>\"<em>Contar com o Sicredi dobrando cada valor doado vai possibilitar que o povo ga\u00facho receba rapidamente a ajuda que tanto necessita neste momento\"<\/em>, disse.<\/div>\n<div>\u00a0<\/div>\n<div>Para contribuir com a campanha, basta fazer a doa\u00e7\u00e3o para o PIX: doacao@federacaovarejista.com.br. A cada R$ 1 doado, o Sicredi doar\u00e1 o mesmo valor.\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<div>\u00a0<\/div>\n<\/div>\n<div><strong>Sobre a CDL Sapiranga<\/strong><br \/><br \/>Fundada em 23 de maio de 1972, a C\u00e2mara de Dirigentes Lojistas de Sapiranga (CDL) \u00e9 uma entidade civil e sem fins lucrativos. Objetiva promover a uni\u00e3o entre a classe lojista da cidade, proporcionando maior seguran\u00e7a no momento da concess\u00e3o de cr\u00e9dito. A CDL Sapiranga busca solidificar-se cada vez mais no \u00e2mbito comercial do munic\u00edpio, apoiando tamb\u00e9m o crescimento cont\u00ednuo de pontos comerciais na cidade e a qualifica\u00e7\u00e3o dos profissionais que trabalham nesta \u00e1rea. A entidade oferece uma ampla variedade de servi\u00e7os aos seus associados, englobando ainda cursos e eventos direcionados \u00e0s necessidades do com\u00e9rcio em geral. A CDL Sapiranga est\u00e1 vinculada \u00e0 Confedera\u00e7\u00e3o Nacional de Dirigentes Lojistas (CNDL).<\/div>\n<hr \/>\n<h6><strong>PlayPress | CDL Sapiranga | Reda\u00e7\u00e3o: Marcelo Matusiak<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A\u00e7\u00e3o solid\u00e1ria liderada pela Federa\u00e7\u00e3o Varejista do Rio Grande do Sul visa auxiliar popula\u00e7\u00e3o ga\u00facha afetada pelas fortes chuvas A CDL Sapiranga, integrante do sistema CNDL, une esfor\u00e7os com outras CDLs e Federa\u00e7\u00f5es de todo o pa\u00eds em uma campanha de solidariedade para ajudar as v\u00edtimas das enchentes que assolaram o Rio Grande do Sul. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":64529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-64528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=64528"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64528\/revisions"}],"predecessor-version":[{"id":64530,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/64528\/revisions\/64530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/64529"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=64528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=64528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=64528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}