{"id":69750,"date":"2024-11-18T09:16:13","date_gmt":"2024-11-18T12:16:13","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=69750"},"modified":"2024-11-18T09:16:15","modified_gmt":"2024-11-18T12:16:15","slug":"em-santo-angelo-governador-em-exercicio-instala-comissao-dos-400-anos-das-missoes-jesuiticas-guaranis","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/em-santo-angelo-governador-em-exercicio-instala-comissao-dos-400-anos-das-missoes-jesuiticas-guaranis\/","title":{"rendered":"Em Santo \u00c2ngelo, governador em exerc\u00edcio instala Comiss\u00e3o dos 400 Anos das Miss\u00f5es Jesu\u00edticas Guaranis"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Gabriel Souza apresentou investimentos do governo na regi\u00e3o e sancionou lei que institui Cruz Missioneira como s\u00edmbolo oficial<\/em><\/p>\n<p>O\u00a0governador em exerc\u00edcio, Gabriel Souza, conduziu, nesta quinta-feira (14\/11),\u00a0a instala\u00e7\u00e3o da Comiss\u00e3o Oficial dos 400 Anos das\u00a0Miss\u00f5es Jesu\u00edticas Guaranis, que ocorrem em 2026. O grupo \u00e9 composto por 36 entidades, incluindo as prefeituras dos munic\u00edpios missioneiros que ir\u00e3o trabalhar em projetos para fomentar o turismo e alavancar o potencial econ\u00f4mico e cultural da regi\u00e3o. A secret\u00e1ria da Cultura, Beatriz Araujo, tamb\u00e9m participou da cerim\u00f4nia, na qual foi\u00a0sancionada ainda a lei que institui a Cruz Missioneira como s\u00edmbolo oficial das Miss\u00f5es.<\/p>\n<p>A\u00a0Comiss\u00e3o Oficial\u00a0\u2013\u00a0prevista no decreto 57.369, de 18 de dezembro de 2023\u00a0\u2013 \u00e9 coordenada pelo Gabinete de Projetos Especiais, vinculado ao Gabinete do Vice-Governador. O grupo\u00a0j\u00e1 estuda uma lista de projetos apresentados pelas prefeituras, representadas pela Associa\u00e7\u00e3o dos Munic\u00edpios das Miss\u00f5es (AMM).\u00a0Tamb\u00e9m fazem parte do comit\u00ea executivo da comiss\u00e3o a Procuradoria-Geral do Estado e as secretarias de Comunica\u00e7\u00e3o, de Turismo e da Cultura.<\/p>\n<p>Na ocasi\u00e3o, Gabriel falou sobre a import\u00e2ncia da comiss\u00e3o, que organizar\u00e1 os festejos em 2026, e destacou que\u00a0o\u00a0movimento ir\u00e1 al\u00e9m das oportunidades de desenvolvimento da regi\u00e3o. \u201c<em>As celebra\u00e7\u00f5es, mais do que fomentar o turismo e a economia, representam um resgate hist\u00f3rico. As pol\u00edticas p\u00fablicas para apoio a povos origin\u00e1rios s\u00e3o o centro das comemora\u00e7\u00f5es. Se n\u00e3o fosse a presen\u00e7a deles,\u00a0n\u00e3o ter\u00edamos o que comemorar nesses 400 anos<\/em>\u201d, afirmou.<\/p>\n<p>O pacote re\u00fane iniciativas que somam cerca de R$ 60 milh\u00f5es em investimentos. Avalia\u00e7\u00f5es preliminares do governo apontam que R$ 40 milh\u00f5es dos\u00a0projetos t\u00eam potencial para se concretizarem.<\/p>\n<p>Entre eles, est\u00e3o a requalifica\u00e7\u00e3o dos atrativos tur\u00edsticos, a proje\u00e7\u00e3o\u00a0de novos museus, a qualifica\u00e7\u00e3o do artesanato e das aldeias guaranis, a implanta\u00e7\u00e3o de projetos educacionais com o tema dos 400 anos e a requalifica\u00e7\u00e3o de rodovias.<\/p>\n<p>Beatriz destacou os investimentos da Secretaria da Cultura (Sedac) realizados na regi\u00e3o das Miss\u00f5es, com mais de R$ 11 milh\u00f5es pelo Pr\u00f3-Cultura. Em Santo \u00c2ngelo e S\u00e3o Nicolau tamb\u00e9m foram investidos mais de R$ 5 milh\u00f5es pelo programa Avan\u00e7ar Turismo. \u201c<em>Estamos falando de futuro, de um programa robusto do governo em prol de\u00a0uma\u00a0regi\u00e3o cuja\u00a0cultura \u00e9 fundamental para o Rio Grande do Sul<\/em>\u201d, destacou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-69752 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/21-400x267.jpeg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/21-400x267.jpeg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/21-768x512.jpeg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/21-600x400.jpeg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/21.jpeg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p><strong>Cruz Missioneira como s\u00edmbolo das miss\u00f5es jesu\u00edticas<\/strong><\/p>\n<p>O\u00a0governador em exerc\u00edcio tamb\u00e9m sancionou a lei que institui a Cruz Missioneira como s\u00edmbolo oficial das Miss\u00f5es Jesu\u00edticas Guaranis. O projeto,\u00a0protocolado pelo deputado Eduardo Loureiro (PDT), determina que a cruz dever\u00e1 ter as seis extremidades no mesmo tamanho e formato e que, onde for instalada, precisar\u00e1\u00a0estar acompanhada de texto explicativo.<\/p>\n<p><strong>Assinatura de of\u00edcio com manifesta\u00e7\u00e3o de interesse<\/strong><\/p>\n<p>Durante a cerim\u00f4nia, prefeitos e representantes dos munic\u00edpios de Bossoroca, Caibat\u00e9, Entre-Iju\u00eds, Porto Xavier, S\u00e3o Borja, S\u00e3o Francisco de Assis, S\u00e3o Luiz Gonzaga, S\u00e3o Miguel das Miss\u00f5es, S\u00e3o Nicolau, S\u00e3o Pedro do Sul, Santo Ant\u00f4nio das Miss\u00f5es, Santo \u00c2ngelo e Vit\u00f3ria das Miss\u00f5es assinaram of\u00edcios com manifesta\u00e7\u00e3o de interesse em rela\u00e7\u00e3o aos projetos dos festejos.<\/p>\n<p>Os munic\u00edpios dever\u00e3o encaminhar anteprojetos e documenta\u00e7\u00e3o necess\u00e1ria para a formaliza\u00e7\u00e3o do conv\u00eanio com o Executivo ga\u00facho.<\/p>\n<p><strong>Investimentos na Regi\u00e3o das Miss\u00f5es<\/strong><\/p>\n<p>O governo do Estado tamb\u00e9m prev\u00ea investimentos na regi\u00e3o, como a constru\u00e7\u00e3o de novas pistas na ERS-344,\u00a0entre Entre-Iju\u00eds e Santa Rosa;\u00a0a remodela\u00e7\u00e3o dos trevos na ERS-344 e ERS-218;\u00a0e melhorias em acessos aos munic\u00edpios de Rolador, Garruchos e Pirap\u00f3. O acesso a Ubiretama j\u00e1 est\u00e1 asfaltado,\u00a0e a constru\u00e7\u00e3o da ponte aguarda o projeto do Departamento Aut\u00f4nomo de Estradas de Rodagem\u00a0(Daer), com execu\u00e7\u00e3o prevista para o pr\u00f3ximo ano.<\/p>\n<p>Outras obras previstas s\u00e3o o contorno do munic\u00edpio de Catu\u00edpe,\u00a0que liga a ERS-342 \u00e0 ERS-218, a fim de facilitar o acesso ao aeroporto de Santo \u00c2ngelo. No aeroporto Sep\u00e9 Tiaraj\u00fa, no munic\u00edpio, al\u00e9m das altera\u00e7\u00f5es no projeto de concess\u00e3o para atrair investidores, o governo prev\u00ea aporte de R$ 6 milh\u00f5es\u00a0por meio de conv\u00eanio com a Secretaria de Log\u00edstica e Transportes.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Dayanne Rodrigues\/Ascom GVG | Edi\u00e7\u00e3o: Felipe Borges\/Secom | Fotos: Rodrigo Ziebell\/Ascom GVG<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Gabriel Souza apresentou investimentos do governo na regi\u00e3o e sancionou lei que institui Cruz Missioneira como s\u00edmbolo oficial O\u00a0governador em exerc\u00edcio, Gabriel Souza, conduziu, nesta quinta-feira (14\/11),\u00a0a instala\u00e7\u00e3o da Comiss\u00e3o Oficial dos 400 Anos das\u00a0Miss\u00f5es Jesu\u00edticas Guaranis, que ocorrem em 2026. O grupo \u00e9 composto por 36 entidades, incluindo as prefeituras dos munic\u00edpios missioneiros que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=69750"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69750\/revisions"}],"predecessor-version":[{"id":69753,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69750\/revisions\/69753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/69751"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=69750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=69750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=69750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}