{"id":69782,"date":"2024-11-19T09:06:34","date_gmt":"2024-11-19T12:06:34","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=69782"},"modified":"2024-11-19T09:06:36","modified_gmt":"2024-11-19T12:06:36","slug":"invest-rs-inaugura-acoes-com-missao-ao-japao-e-a-china","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/invest-rs-inaugura-acoes-com-missao-ao-japao-e-a-china\/","title":{"rendered":"Invest RS inaugura a\u00e7\u00f5es com miss\u00e3o ao Jap\u00e3o e \u00e0 China"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Comitiva liderada pelo governador Eduardo Leite ter\u00e1 agendas em empresas como Toyota, Mitsubishi e BYD<\/em><\/p>\n<p>A\u00a0<strong><a href=\"https:\/\/www.estado.rs.gov.br\/invest-rs-agencia-de-desenvolvimento\" target=\"_blank\" rel=\"noopener\">Invest RS<\/a><\/strong>, Ag\u00eancia de Desenvolvimento do Rio Grande do Sul, inaugura suas atividades de promo\u00e7\u00e3o comercial e atra\u00e7\u00e3o de investimentos participando da\u00a0<strong><a href=\"https:\/\/www.missoesinternacionais.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\">miss\u00e3o do governo do Estado\u00a0ao Jap\u00e3o e \u00e0 China<\/a><\/strong>, que come\u00e7a nesta segunda-feira\u00a0(18\/11) e vai at\u00e9\u00a027 de novembro. O presidente da Invest RS, Rafael Prikladinicki, \u00e9 um dos integrantes da comitiva oficial, liderada pelo governador Eduardo Leite.<\/p>\n<p>Com foco em inova\u00e7\u00e3o e sustentabilidade, o roteiro\u00a0prev\u00ea agendas em empresas como Toyota, Mitsubishi Heavy Industries e Shizen Energy, no Jap\u00e3o, e com representantes da BYD e Huawei, na China, onde tamb\u00e9m ocorre\u00a0a Supply Chain Expo (Cisce). A feira da cadeia de suprimentos e de log\u00edstica contar\u00e1\u00a0com a participa\u00e7\u00e3o do Rio Grande do Sul por meio de um estande pr\u00f3prio.<\/p>\n<p>Conforme Prikladinicki, \u00e9 a primeira oportunidade para mostrar a ag\u00eancia, que conta com estrutura e modo de opera\u00e7\u00e3o alinhados ao que h\u00e1 de mais inovador em capta\u00e7\u00e3o de investimentos. <em>\u201cEstados como o Rio Grande do Sul precisam estar sempre na vitrine, promovendo seus diferenciais\u00a0e buscando\u00a0as oportunidades onde estiverem<\/em>\u201d, destaca\u00a0o presidente da ag\u00eancia.<\/p>\n<p><em>\u201cO in\u00edcio da opera\u00e7\u00e3o da Invest RS inaugura uma nova fase no nosso esfor\u00e7o de acelerar o desenvolvimento<\/em>\u201d, afirma o secret\u00e1rio de Desenvolvimento Econ\u00f4mico, Ernani Polo.\u00a0<em>\u201cA miss\u00e3o \u00e0 \u00c1sia \u00e9 a primeira dessa estrutura criada para potencializar a competitividade, impulsionar a atra\u00e7\u00e3o de investimentos e ampliar a abertura de mercados.\u201d<\/em><\/p>\n<p>A Invest RS ir\u00e1 atuar em coopera\u00e7\u00e3o com poder p\u00fablico, entidades e sociedade, como uma ferramenta do\u00a0<strong><a href=\"https:\/\/planoriogrande.rs.gov.br\/desenvolvimento\" target=\"_blank\" rel=\"noopener\">Plano de Desenvolvimento Econ\u00f4mico, Inclusivo e Sustent\u00e1vel<\/a><\/strong>\u00a0lan\u00e7ado pelo governo do Estado. A ag\u00eancia pretende posicionar o Rio Grande do Sul de forma competitiva\u00a0no cen\u00e1rio internacional, impulsionando as empresas locais e melhorando o ambiente de neg\u00f3cios.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Sedec | Edi\u00e7\u00e3o: Secom\u00a0<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Comitiva liderada pelo governador Eduardo Leite ter\u00e1 agendas em empresas como Toyota, Mitsubishi e BYD A\u00a0Invest RS, Ag\u00eancia de Desenvolvimento do Rio Grande do Sul, inaugura suas atividades de promo\u00e7\u00e3o comercial e atra\u00e7\u00e3o de investimentos participando da\u00a0miss\u00e3o do governo do Estado\u00a0ao Jap\u00e3o e \u00e0 China, que come\u00e7a nesta segunda-feira\u00a0(18\/11) e vai at\u00e9\u00a027 de novembro. O [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=69782"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69782\/revisions"}],"predecessor-version":[{"id":69784,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69782\/revisions\/69784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/69783"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=69782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=69782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=69782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}