{"id":69815,"date":"2024-11-19T10:10:42","date_gmt":"2024-11-19T13:10:42","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=69815"},"modified":"2024-11-19T10:10:48","modified_gmt":"2024-11-19T13:10:48","slug":"no-japao-governador-discute-com-a-toyota-ampliacao-da-atuacao-da-empresa-no-rs","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/no-japao-governador-discute-com-a-toyota-ampliacao-da-atuacao-da-empresa-no-rs\/","title":{"rendered":"No Jap\u00e3o, governador discute com a Toyota amplia\u00e7\u00e3o da atua\u00e7\u00e3o da empresa no RS"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Na sequ\u00eancia, a comitiva ga\u00facha foi recebida na Embaixada do Brasil em T\u00f3quio<\/em><\/p>\n<p>A comitiva do governo do Rio Grande do Sul, liderada pelo governador Eduardo Leite, deu sequ\u00eancia \u00e0 miss\u00e3o oficial no Jap\u00e3o nesta ter\u00e7a-feira (19\/11) com agendas estrat\u00e9gicas voltadas a neg\u00f3cios. O dia come\u00e7ou com uma visita \u00e0 sede da Toyota, em T\u00f3quio, para tratar da amplia\u00e7\u00e3o da presen\u00e7a da empresa no Estado e explorar tecnologias sustent\u00e1veis no setor automotivo. Na sequ\u00eancia, o grupo foi recebido na Embaixada do Brasil no Jap\u00e3o, onde foram discutidos os avan\u00e7os da rela\u00e7\u00e3o Brasil-Jap\u00e3o e as oportunidades de coopera\u00e7\u00e3o em \u00e1reas priorit\u00e1rias para o Rio Grande do Sul.<\/p>\n<p>Na Toyota, uma das maiores montadoras do mundo, o governador refor\u00e7ou as potencialidades do Rio Grande do Sul e destacou o compromisso do Estado com o desenvolvimento sustent\u00e1vel. Durante a reuni\u00e3o, a Toyota exp\u00f4s sua estrat\u00e9gia global de descarboniza\u00e7\u00e3o, que inclui um foco especial em ve\u00edculos movidos a hidrog\u00eanio. A empresa \u00e9 pioneira no desenvolvimento de modelos como o Toyota Mirai, que utiliza c\u00e9lulas de combust\u00edvel para transformar hidrog\u00eanio em eletricidade, emitindo apenas \u00e1gua como subproduto.<\/p>\n<p>\u201c<em>O Rio Grande do Sul tem o compromisso de liderar a transi\u00e7\u00e3o para uma economia verde no Brasil. A Toyota \u00e9 uma parceira estrat\u00e9gica para o nosso Estado, e queremos ampliar essa rela\u00e7\u00e3o com projetos que promovam inova\u00e7\u00e3o e sustentabilidade, beneficiando nossa ind\u00fastria automotiva e a mobilidade urbana<\/em>\u201d, afirmou o governador.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-69817 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/91-3-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/91-3-400x266.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/91-3-768x511.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/91-3-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/91-3.jpg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A Toyota opera um centro de distribui\u00e7\u00e3o em Gua\u00edba desde 2005 e tem manifestado interesse em explorar novas oportunidades no Estado, especialmente em projetos relacionados ao uso de hidrog\u00eanio como combust\u00edvel sustent\u00e1vel. A montadora destacou ainda o potencial do mercado brasileiro para a introdu\u00e7\u00e3o de tecnologias de mobilidade verde, como ve\u00edculos el\u00e9tricos e movidos a hidrog\u00eanio.<\/p>\n<p>Ap\u00f3s o encontro com a Toyota, a comitiva foi recebida pelo embaixador do Brasil no Jap\u00e3o, Oct\u00e1vio Henrique C\u00f4rtes, na Embaixada do Brasil em T\u00f3quio. Durante a reuni\u00e3o, o governador e o embaixador discutiram o papel estrat\u00e9gico do Jap\u00e3o como parceiro comercial e tecnol\u00f3gico do Brasil, com \u00eanfase nas rela\u00e7\u00f5es com o Rio Grande do Sul.<\/p>\n<p><em>\u201cEssa miss\u00e3o demonstra que estamos alinhados com as demandas globais por sustentabilidade e inova\u00e7\u00e3o. O Jap\u00e3o \u00e9 um parceiro importante para que possamos atrair investimentos e consolidar o Rio Grande do Sul como um Estado competitivo internacionalmente<\/em>\u201d, ressaltou Leite.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-69818 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/92-1-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/92-1-400x266.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/92-1-768x511.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/92-1-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/11\/92-1.jpg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Tamb\u00e9m participam da miss\u00e3o oficial os secret\u00e1rios estaduais Artur Lemos (Casa Civil), Ernani Polo (Desenvolvimento Econ\u00f4mico), Caio Tomazeli (Comunica\u00e7\u00e3o), Pedro Capeluppi (Reconstru\u00e7\u00e3o Ga\u00facha) e Ronaldo Santini (Turismo), o procurador-geral do Estado, Eduardo Cunha da Costa, o presidente da Assembleia, Adolfo Brito, e o l\u00edder do governo, Frederico Antunes, entre outras autoridades.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Juliano Rodrigues\/Secom | Edi\u00e7\u00e3o: Rodrigo Toledo Fran\u00e7a\/Secom | Fotos: Maur\u00edcio Tonetto\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Na sequ\u00eancia, a comitiva ga\u00facha foi recebida na Embaixada do Brasil em T\u00f3quio A comitiva do governo do Rio Grande do Sul, liderada pelo governador Eduardo Leite, deu sequ\u00eancia \u00e0 miss\u00e3o oficial no Jap\u00e3o nesta ter\u00e7a-feira (19\/11) com agendas estrat\u00e9gicas voltadas a neg\u00f3cios. O dia come\u00e7ou com uma visita \u00e0 sede da Toyota, em T\u00f3quio, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=69815"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69815\/revisions"}],"predecessor-version":[{"id":69819,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69815\/revisions\/69819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/69816"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=69815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=69815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=69815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}