{"id":69956,"date":"2024-11-26T09:19:22","date_gmt":"2024-11-26T12:19:22","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=69956"},"modified":"2024-11-26T10:11:26","modified_gmt":"2024-11-26T13:11:26","slug":"na-maior-votacao-da-historia-da-oab-rs-leonardo-lamachia-e-reeleito-presidente","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/na-maior-votacao-da-historia-da-oab-rs-leonardo-lamachia-e-reeleito-presidente\/","title":{"rendered":"Na maior vota\u00e7\u00e3o da hist\u00f3ria da OAB\/RS, Leonardo Lamachia \u00e9 reeleito presidente"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p>Leonardo Lamachia foi reconduzido \u00e0 presid\u00eancia da OAB\/RS com a maior vota\u00e7\u00e3o da hist\u00f3ria da entidade. O grupo OAB Mais venceu as elei\u00e7\u00f5es, na \u00faltima sexta-feira (22), para a presid\u00eancia da Ordem dos Advogados do Brasil \u2013 Seccional Rio Grande do Sul (OAB\/RS), para o tri\u00eanio 2025\/2027. Lamachia foi reeleito com 77% dos votos para continuar \u00e0 frente da OAB ga\u00facha \u2014 em uma chapa formada em sua maioria por mulheres, com Clarid\u00ea Chitolina Taffarel como vice-presidente, Ana L\u00facia Kaercher Piccoli como secret\u00e1ria-geral e Regina Pereira Soares como secret\u00e1ria-geral adjunta; Jorge Fara \u00e9 o diretor-tesoureiro.<\/p>\n<p><em>\u201cAgrade\u00e7o profundamente a cada advogada e advogado pelo reconhecimento do nosso trabalho e esfor\u00e7o. Tenho plena consci\u00eancia dos desafios que a advocacia enfrenta diariamente, e \u00e9 por isso que essa vota\u00e7\u00e3o refor\u00e7a a legitimidade necess\u00e1ria para seguirmos lutando, avan\u00e7ando e realizando ainda mais. Juntos, seguimos firmes em defesa da nossa profiss\u00e3o e da sociedade<\/em>\u201d, afirmou Leonardo Lamachia.<br \/>A elei\u00e7\u00e3o de 2024 foi a maior da hist\u00f3ria da OAB\/RS em votos registrados. Lamachia recebeu 77% de votos v\u00e1lidos. O segundo colocado Paulo Torelly (Chapa 2 - Somos tod@s OAB - Muda OAB\/RS) recebeu 23%.<\/p>\n<p><strong>Conhe\u00e7a Leonardo Lamachia<\/strong><\/p>\n<p>Irm\u00e3o do primeiro e \u00fanico ga\u00facho a presidir a OAB Nacional, Claudio Lamachia, Leonardo Lamachia tem uma carreira s\u00f3lida na advocacia. Natural de Porto Alegre, \u00e9 formado em Direito pela PUCRS e s\u00f3cio do escrit\u00f3rio de advocacia Lamachia Advogados Associados. Com vasta experi\u00eancia em Direito Empresarial, atua em sustenta\u00e7\u00f5es orais junto aos Tribunais do Estado, Superior Tribunal de Justi\u00e7a e Supremo Tribunal Federal. Vice-presidente do Instituto dos Advogados do Rio Grande do Sul \u2013 IARGS, nas gest\u00f5es 2013\/2015, 2016\/2018 e 2019\/2021, tamb\u00e9m foi presidente do F\u00f3rum dos Conselhos Regionais e Ordens das Profiss\u00f5es Regulamentadas do Rio Grande do Sul.<\/p>\n<hr \/>\n<h6><strong>OAB\/RS | Foto: Diogo Mendes - OAB\/RS<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Leonardo Lamachia foi reconduzido \u00e0 presid\u00eancia da OAB\/RS com a maior vota\u00e7\u00e3o da hist\u00f3ria da entidade. O grupo OAB Mais venceu as elei\u00e7\u00f5es, na \u00faltima sexta-feira (22), para a presid\u00eancia da Ordem dos Advogados do Brasil \u2013 Seccional Rio Grande do Sul (OAB\/RS), para o tri\u00eanio 2025\/2027. Lamachia foi reeleito com 77% dos votos para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-69956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=69956"}],"version-history":[{"count":2,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69956\/revisions"}],"predecessor-version":[{"id":69979,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/69956\/revisions\/69979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/69957"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=69956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=69956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=69956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}