{"id":70066,"date":"2024-11-29T09:39:20","date_gmt":"2024-11-29T12:39:20","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70066"},"modified":"2024-11-29T09:39:22","modified_gmt":"2024-11-29T12:39:22","slug":"periodo-para-ingresso-na-rede-estadual-segue-ate-1o-de-dezembro","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/periodo-para-ingresso-na-rede-estadual-segue-ate-1o-de-dezembro\/","title":{"rendered":"Per\u00edodo para ingresso na Rede Estadual segue at\u00e9 1\u00ba de dezembro"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Interessados devem se inscrever no site da Secretaria da Educa\u00e7\u00e3o<\/em><\/p>\n<p>O per\u00edodo de inscri\u00e7\u00f5es para a pr\u00e9-matr\u00edcula na Rede Estadual de educa\u00e7\u00e3o segue at\u00e9 domingo (1\/12). Os interessados em se matricular nas escolas estaduais devem acessar o\u00a0<strong><a href=\"https:\/\/educacao.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\">site da Secretaria da Educa\u00e7\u00e3o (Seduc)<\/a><\/strong>\u00a0e buscar a aba \u201cMatr\u00edculas - Chamada P\u00fablica\u201d. Tamb\u00e9m \u00e9 preciso selecionar a etapa de ensino desejada.\u00a0<\/p>\n<p>Neste momento, a etapa de inscri\u00e7\u00f5es \u00e9 voltada somente aos estudantes que ir\u00e3o ingressar no 1\u00b0 ano do Ensino Fundamental e na 1\u00aa s\u00e9rie do Ensino M\u00e9dio, incluindo as modalidades regular, Curso Normal, aproveitamento de estudos do Curso Normal e Educa\u00e7\u00e3o Profissional. No \u00faltimo caso, a escolha inclui as op\u00e7\u00f5es de cursos t\u00e9cnicos, que podem ser integrados ao Ensino M\u00e9dio, Concomitante ou Subsequente.\u00a0<\/p>\n<p>Os estudantes que j\u00e1 possuem matr\u00edcula ativa na Rede Estadual, independentemente das etapas de modalidades de ensino, ser\u00e3o matriculados de forma autom\u00e1tica, desde que apresentem uma frequ\u00eancia escolar m\u00ednima de 75% de presen\u00e7a.\u00a0Essa rematr\u00edcula ocorre at\u00e9 18 de dezembro, sem a necessidade de inscri\u00e7\u00e3o no site. Aqueles que quiserem trocar de escola precisam ficar atentos aos prazos da segunda etapa da pr\u00e9-matr\u00edcula, quando ser\u00e1 aberto o per\u00edodo de transfer\u00eancias.<\/p>\n<p>Da mesma forma, estudantes do 2\u00b0 ao 9\u00b0 ano do Ensino Fundamental e da 2\u00aa e 3\u00aa s\u00e9ries do Ensino M\u00e9dio que j\u00e1 est\u00e3o matriculados em escolas estaduais, municipais ou privadas, e que desejam mudar de escola ou ingressar na Rede Estadual, precisam realizar a matr\u00edcula durante a segunda etapa, pois essas situa\u00e7\u00f5es s\u00e3o consideradas transfer\u00eancias.\u00a0<\/p>\n<p>As designa\u00e7\u00f5es para as escolas pretendidas ocorrer\u00e3o a partir de 6 de janeiro de 2025. As informa\u00e7\u00f5es ser\u00e3o enviadas aos respons\u00e1veis pelos estudantes por meio do e-mail cadastrado no sistema da Seduc. Tamb\u00e9m \u00e9 poss\u00edvel conferir os dados na \u00e1rea de Consulta ao Candidato, na aba \u201cMatr\u00edcula - Chamada P\u00fablica\u201d, no site da Seduc. \u00a0<\/p>\n<p>Para designar as escolas, s\u00e3o levados em considera\u00e7\u00e3o fatores como a proximidade da casa do estudante em rela\u00e7\u00e3o \u00e0s institui\u00e7\u00f5es de ensino dispon\u00edveis e a idade, priorizando crian\u00e7as mais novas (a n\u00e3o ser nos casos em que o estudante j\u00e1 tenha irm\u00e3os matriculados na escola desejada).\u00a0<\/p>\n<p>Quando for fazer o pedido de transfer\u00eancia, o respons\u00e1vel legal ou o pr\u00f3prio estudante pode indicar at\u00e9 tr\u00eas escolas, organizadas em ordem de prefer\u00eancia. \u00c9 poss\u00edvel escolher op\u00e7\u00f5es que ofere\u00e7am o Ensino M\u00e9dio em Tempo Integral.<\/p>\n<p>Os estudantes que ingressar\u00e3o na 2\u00aa s\u00e9rie do Ensino M\u00e9dio precisam escolher o Itiner\u00e1rio Formativo - Trilha de Aprofundamento Curricular. De 25 de novembro a 20 de dezembro, eles devem acessar o Aplicativo Escola RS, realizar o login e selecionar a op\u00e7\u00e3o desejada para confirmar a matr\u00edcula.<\/p>\n<p><strong>Efetiva\u00e7\u00e3o da matr\u00edcula<\/strong><\/p>\n<p>As inscri\u00e7\u00f5es e transfer\u00eancias somente ser\u00e3o efetivadas com a matr\u00edcula presencial. Entre 6 a 17 de janeiro, os candidatos \u00e0s vagas, acompanhados de seus respons\u00e1veis, devem entregar os seguintes documentos\u00a0na escola designadas:<\/p>\n<ul>\n<li>CPF e Certid\u00e3o de nascimento ou RG do estudante;<\/li>\n<li>CPF e documentos do respons\u00e1vel;<\/li>\n<li>comprovante de resid\u00eancia;<\/li>\n<li>para alunos do 1\u00ba Ano do Ensino Fundamental: Cart\u00e3o Nacional de Sa\u00fade (CNS), N\u00famero de Identifica\u00e7\u00e3o Social (NIS) e atestado (carteira) de vacina\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>Para ingressar nessa etapa, o requisito \u00e9 ter a idade m\u00ednima de seis anos completos at\u00e9 30 de mar\u00e7o de 2025.\u00a0<\/p>\n<p><strong>Cronograma<\/strong><\/p>\n<p><strong>11\/11 a 1\/12\/2024 \u2013 Inscri\u00e7\u00f5es para pr\u00e9-matr\u00edcula (1\u00aa chamada)<\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0popula\u00e7\u00e3o em geral para solicita\u00e7\u00e3o de ingresso na rede p\u00fablica para o 1\u00ba ano do Ensino Fundamental; 1\u00ba ano do Ensino M\u00e9dio; Educa\u00e7\u00e3o Profissional - Cursos t\u00e9cnicos Subsequentes, Concomitantes e Aproveitamento de estudos do curso normal e Educa\u00e7\u00e3o de Jovens e Adultos (EJA).<\/li>\n<\/ul>\n<p><strong>18\/11 a 18\/12\/2024 \u2013 Rematr\u00edcula autom\u00e1tica<br \/><\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0todos os estudantes que possuem matr\u00edcula ativa nas Unidades Escolares Estaduais, em todas as etapas e modalidades de ensino que tiverem, no m\u00ednimo, 75% de frequ\u00eancia.<\/li>\n<\/ul>\n<p><strong>25\/11 a 20\/12\/2024<\/strong>\u00a0\u2013 Escolha do itiner\u00e1rio formativo (para alunos que cursar\u00e3o o 2\u00ba ano do Ensino M\u00e9dio) no aplicativo para efetivar a matr\u00edcula.<\/p>\n<p><strong>6\/1\/2025 \u2013 Resultados (designa\u00e7\u00f5es) das inscri\u00e7\u00f5es para pr\u00e9-matr\u00edcula.<br \/><\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0todos que se inscreveram de 11 de novembro a 1\u00ba de dezembro de 2024.<\/li>\n<\/ul>\n<p><strong>6\/1 a 17\/1\/2025 \u2013 Efetiva\u00e7\u00e3o da matr\u00edcula<br \/><\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0todos que se inscreveram de 11 de novembro a 1\u00ba de dezembro de 2024, diretamente nas Unidades Escolares.<\/li>\n<\/ul>\n<p><strong>6\/1 a 19\/1\/2025 \u2013 Segunda oportunidade de inscri\u00e7\u00f5es e pr\u00e9-matr\u00edcula (2\u00aa chamada) e solicita\u00e7\u00e3o de transfer\u00eancias<br \/><\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0todos que perderam o primeiro per\u00edodo de inscri\u00e7\u00f5es (que foi de 11 de novembro a 1\u00ba de dezembro de 2024).<\/li>\n<\/ul>\n<p><strong>30\/1 a 7\/2\/2025 \u2013 Efetiva\u00e7\u00e3o da matr\u00edcula para a 2\u00aa etapa de inscri\u00e7\u00f5es<br \/><\/strong><\/p>\n<ul>\n<li><strong>P\u00fablico:<\/strong>\u00a0todos que solicitaram transfer\u00eancia e aqueles que se inscreveram na segunda chamada (realizada de 6 a 19 de janeiro de 2024).<\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Seduc |Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Interessados devem se inscrever no site da Secretaria da Educa\u00e7\u00e3o O per\u00edodo de inscri\u00e7\u00f5es para a pr\u00e9-matr\u00edcula na Rede Estadual de educa\u00e7\u00e3o segue at\u00e9 domingo (1\/12). Os interessados em se matricular nas escolas estaduais devem acessar o\u00a0site da Secretaria da Educa\u00e7\u00e3o (Seduc)\u00a0e buscar a aba \u201cMatr\u00edculas - Chamada P\u00fablica\u201d. Tamb\u00e9m \u00e9 preciso selecionar a etapa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70066"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70066\/revisions"}],"predecessor-version":[{"id":70068,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70066\/revisions\/70068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70067"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}