{"id":70094,"date":"2024-12-02T09:14:14","date_gmt":"2024-12-02T12:14:14","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70094"},"modified":"2024-12-02T09:14:16","modified_gmt":"2024-12-02T12:14:16","slug":"campanha-em-referencia-ao-dezembro-vermelho-combate-preconceito-contra-pessoas-com-hiv-aids","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/campanha-em-referencia-ao-dezembro-vermelho-combate-preconceito-contra-pessoas-com-hiv-aids\/","title":{"rendered":"Campanha em refer\u00eancia ao Dezembro Vermelho combate preconceito contra pessoas com HIV\/Aids"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>A tem\u00e1tica ser\u00e1 abordada no site, nas redes sociais e em pe\u00e7as publicit\u00e1rias afixadas em \u00f4nibus e pain\u00e9is<\/em><\/p>\n<p>A alta preval\u00eancia do v\u00edrus HIV no Rio Grande do Sul\u00a0\u00e9 uma realidade na hist\u00f3ria epidemiol\u00f3gica do\u00a0Estado. Para marcar o\u00a0Dia Mundial de Luta Contra a Aids (1\u00ba\/12), a campanha\u00a0estadual lan\u00e7ada\u00a0este ano\u00a0busca combater o preconceito. O\u00a0Dezembro\u00a0Vermelho \u00e9 o m\u00eas de conscientiza\u00e7\u00e3o sobre o tema e, anualmente, busca abordar aspectos sociais que envolvem a situa\u00e7\u00e3o de sa\u00fade.<\/p>\n<p>Em conson\u00e2ncia com a campanha federal, lan\u00e7ada pelo Minist\u00e9rio da Sa\u00fade, a Secretaria da Sa\u00fade (SES) lan\u00e7ou\u00a0nesta\u00a0semana a campanha: HIV Positivo. Preconceito?\u00a0Negativo. A tem\u00e1tica ser\u00e1 abordada no site, nas redes sociais e em pe\u00e7as publicit\u00e1rias afixadas em \u00f4nibus e em pain\u00e9is.\u00a0<\/p>\n<p>O v\u00edrus da imunodefici\u00eancia humana (HIV) causa a S\u00edndrome da Imunodefici\u00eancia Adquirida\u00a0(Aids).\u00a0Ele\u00a0age no organismo enfraquecendo o sistema imunol\u00f3gico, tornando-o mais suscet\u00edvel a doen\u00e7as e infec\u00e7\u00f5es. Se o HIV n\u00e3o \u00e9 tratado, pode evoluir para a Aids, que n\u00e3o \u00e9 uma doen\u00e7a em si, mas sim o est\u00e1gio final da infec\u00e7\u00e3o por HIV.\u00a0A busca pela elimina\u00e7\u00e3o da transmiss\u00e3o vertical do HIV\u00a0\u00e9\u00a0uma das\u00a0metas globais da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU)\u00a0e tem sido\u00a0um compromisso estrat\u00e9gico\u00a0do\u00a0Sistema \u00danico de Sa\u00fade nos \u00faltimos anos.\u00a0<\/p>\n<p><strong>Boletim epidemiol\u00f3gico\u00a0do RS\u00a0<\/strong><\/p>\n<p>Os dados do boletim epidemiol\u00f3gico de 2023 (\u00faltimo divulgado oficialmente pelo Minist\u00e9rio da\u00a0Sa\u00fade)\u00a0indicam\u00a0que houve uma redu\u00e7\u00e3o de 45,2% entre os anos de 2012 e 2022 na taxa de detec\u00e7\u00e3o de Aids no Rio Grande do Sul. Apesar disso, o\u00a0Estado ainda tem uma taxa superior \u00e0 do Brasil e a\u00a0sexta\u00a0 mais elevada entre os estados brasileiros.\u00a0\u00a0<\/p>\n<p>A\u00a0taxa de detec\u00e7\u00e3o do HIV em gestantes no Estado em\u00a02022\u00a0\u00e9 de 7,5 casos para cada\u00a0mil\u00a0nascidos vivos. A taxa de detec\u00e7\u00e3o em gestantes de Porto Alegre \u00e9 de 16 casos para cada\u00a0mil\u00a0nascidos vivos, ocupando a\u00a0primeira\u00a0posi\u00e7\u00e3o entre as capitais do pa\u00eds.\u00a0<\/p>\n<p>Apesar de o coeficiente de mortalidade por Aids no RS apresentar um valor superior\u00a0ao do Brasil, ele tem declinado nos \u00faltimos anos. Apesar da redu\u00e7\u00e3o, o RS ocupa\u00a0o\u00a0primeiro\u00a0lugar no\u00a0ranking dos Estados. Quanto \u00e0\u00a0Capital, apesar da diminui\u00e7\u00e3o de 4,4% da mortalidade entre 2021 e 2022, ela tem o maior coeficiente entre as capitais brasileiras: 23,8 \u00f3bitos\u00a0por cem\u00a0mil habitantes.\u00a0<\/p>\n<p><strong>A\u00e7\u00f5es no RS\u00a0<\/strong><\/p>\n<p>A\u00a0Pol\u00edtica Estadual de Infec\u00e7\u00f5es Sexualmente Transmiss\u00edveis (IST)\/HIV\/Aids atua em diversas frentes no enfrentamento\u00a0da\u00a0contamina\u00e7\u00e3o por HIV no Rio Grande do Sul.\u00a0O\u00a0Previne RS nasceu\u00a0com o objetivo de promover a\u00e7\u00f5es articuladas da SES para responder \u00e0 complexa situa\u00e7\u00e3o epidemiol\u00f3gica de alta preval\u00eancia de\u00a0IST\/HIV\/Aids no\u00a0Estado. O programa atua nos eixos:\u00a0elimina\u00e7\u00e3o\u00a0da\u00a0transmiss\u00e3o\u00a0vertical do HIV e da s\u00edfilis,\u00a0preven\u00e7\u00e3o de novas infec\u00e7\u00f5es,\u00a0redu\u00e7\u00e3o da mortalidade e\u00a0fortalecimento da\u00a0sociedade\u00a0civil.<\/p>\n<p>Dentro do Previne RS a SES realiza o programa Gera\u00e7\u00e3o Consciente, que\u00a0\u00e9 realizada dentro das escolas p\u00fablicas, em 48 munic\u00edpios e 429 escolas. O objetivo \u00e9 promover a sa\u00fade integral dos adolescentes a partir de\u00a0eixos tem\u00e1ticos\u00a0trabalhados ao longo do ano:\u00a0aprendizagem socioemocional;\u00a0preven\u00e7\u00e3o \u00e0s\u00a0vulnerabilidades,\u00a0bullying e\u00a0viol\u00eancias;\u00a0preven\u00e7\u00e3o\u00a0combinada do HIV,\u00a0direitos\u00a0sexuais e\u00a0reprodutivos.\u00a0<\/p>\n<p>O\u00a0Gera\u00e7\u00e3o\u00a0Consciente\u00a0oferece aprendizado interativo, din\u00e2mico, bem como\u00a0 instrumentaliza\u00e7\u00e3o de professores, que realizam percursos formativos e aplicam as metodologias ativas em sala de aula com os alunos. As 150 escolas mais bem pontuadas finalizam o percurso de um ano no Arena Gera\u00e7\u00e3o Consciente.\u00a0 \u00a0<\/p>\n<p>Al\u00e9m dessa iniciativa, em 2024, o governo do Estado\u00a0instituiu os Centros Regionalizados de Aten\u00e7\u00e3o Integral e Preven\u00e7\u00e3o \u00e0s\u00a0Infec\u00e7\u00f5es Sexualmente Transmiss\u00edveis, ao HIV\/Aids e coinfec\u00e7\u00f5es (Craip), por meio da\u00a0<a href=\"https:\/\/saude.rs.gov.br\/upload\/arquivos\/202406\/24091800-portaria-361-2024-craip.pdf\" target=\"_blank\" rel=\"noopener\">Portaria SES 361\/2024<\/a>, aportando or\u00e7amento anual de R$ 25\u00a0milh\u00f5es.\u00a0<\/p>\n<p>A\u00a0Certifica\u00e7\u00e3o Estadual da Elimina\u00e7\u00e3o da Transmiss\u00e3o Vertical do HIV e\/ou da S\u00edfilis e os Selos de Boas Pr\u00e1ticas para a Elimina\u00e7\u00e3o da Transmiss\u00e3o Vertical do HIV e\/ou da S\u00edfilis\u00a0representam importante avan\u00e7o no Rio Grande do Sul.\u00a0No m\u00eas de dezembro ser\u00e3o certificados munic\u00edpios entre 50 e 100 mil habitantes que alcan\u00e7aram indicadores e metas estabelecidas pelo Minist\u00e9rio da Sa\u00fade.\u00a0As cidades de maior porte ser\u00e3o certificadas\u00a0diretamente\u00a0pelo MS.\u00a0<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom SES | Edi\u00e7\u00e3o: Secom\u00a0<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A tem\u00e1tica ser\u00e1 abordada no site, nas redes sociais e em pe\u00e7as publicit\u00e1rias afixadas em \u00f4nibus e pain\u00e9is A alta preval\u00eancia do v\u00edrus HIV no Rio Grande do Sul\u00a0\u00e9 uma realidade na hist\u00f3ria epidemiol\u00f3gica do\u00a0Estado. Para marcar o\u00a0Dia Mundial de Luta Contra a Aids (1\u00ba\/12), a campanha\u00a0estadual lan\u00e7ada\u00a0este ano\u00a0busca combater o preconceito. O\u00a0Dezembro\u00a0Vermelho \u00e9 o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70094","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70094","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70094"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70094\/revisions"}],"predecessor-version":[{"id":70096,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70094\/revisions\/70096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70095"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70094"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70094"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70094"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}