{"id":70133,"date":"2024-12-03T09:07:59","date_gmt":"2024-12-03T12:07:59","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70133"},"modified":"2024-12-03T09:08:00","modified_gmt":"2024-12-03T12:08:00","slug":"copa-rs-de-futebol-amador-2024-define-seus-campeoes-em-rodada-especial","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/copa-rs-de-futebol-amador-2024-define-seus-campeoes-em-rodada-especial\/","title":{"rendered":"Copa RS de Futebol Amador 2024 define seus campe\u00f5es em rodada especial"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Organizada pela Secretaria do Esporte e Lazer, a copa \u00e9 a maior competi\u00e7\u00e3o de equipes de futebol do Estado<\/em><\/p>\n<p>Depois de 237 partidas, 165 times e mais de 6,5 mil profissionais envolvidos, a segunda edi\u00e7\u00e3o da Copa RS de Futebol Amador definiu os campe\u00f5es das tr\u00eas categorias em decis\u00f5es realizadas no est\u00e1dio Ant\u00f4nio Vieira Ramos, o Vieir\u00e3o, em Gravata\u00ed, no domingo (1\u00ba\/11). Organizada pela Secretaria do Esporte e Lazer (SEL), a Copa RS \u00e9 maior competi\u00e7\u00e3o de equipes de futebol do Rio Grande do Sul, movimentando a economia e o lazer de 82 munic\u00edpios.<\/p>\n<p>O domingo de futebol come\u00e7ou \u00e0s 9h30 com a cerim\u00f4nia de abertura da competi\u00e7\u00e3o, que contou com a presen\u00e7a do titular da SEL Juliano Franczak, o Ga\u00facho da Geral. \"A Copa RS j\u00e1 \u00e9 um patrim\u00f4nio esportivo do nosso Estado, promovendo a integra\u00e7\u00e3o entre as regi\u00f5es e movimentando a economia nos locais dos jogos. O domingo foi emocionante no Est\u00e1dio Vieir\u00e3o, com arquibancadas cheias e a valoriza\u00e7\u00e3o do esporte ga\u00facho\", destacou.<\/p>\n<p>A primeira decis\u00e3o foi a da categoria Master, para jogadores acima de 50 anos, uma das novidades desta edi\u00e7\u00e3o. O Esporte Clube Barnab\u00e9, de Gravata\u00ed, venceu o Carrossel, de Caxias do Sul, por 4 a 0 e conquistou o t\u00edtulo.<\/p>\n<p>Depois, \u00e0s 13h, foi a vez da categoria Livre, para os jogadores acima de 18 anos. O grande destaque ficou por conta da arbitragem. Com duas finais de Copa do Brasil no curr\u00edculo, o catarinense Braulio da Silva, \u00e1rbitro Fifa de 45 anos, apitou o duelo entre o Vila Nova, de Taquara, e o S\u00e3o Pedrense, de S\u00e3o Pedro do Sul. O time do S\u00e3o Pedrense venceu por 1 a 0 e foi o campe\u00e3o.<\/p>\n<p>Encerrando o dia de muito futebol, a categoria Veterano, para atletas a partir de 40 anos, definiu seu campe\u00e3o ap\u00f3s a partida entre o Caponense, de Cap\u00e3o da Canoa, e o Respeito e Igualdade, de Torres. No tempo normal, houve empate em 2 a 2. A decis\u00e3o por p\u00eanaltis foi longa e emocionante, terminando em 9 a 8 para o Caponense, campe\u00e3o da Copa RS.<\/p>\n<p><strong>Campe\u00f5es<\/strong><\/p>\n<ul>\n<li>Categoria Master: EC Barnab\u00e9 (Gravata\u00ed)<\/li>\n<li>Categoria Livre: GE S\u00e3o Pedrense (S\u00e3o Pedro do Sul)<\/li>\n<li>Categoria Veterano: Caponense FC (Cap\u00e3o da Canoa)<\/li>\n<\/ul>\n<p><strong>Resultados<\/strong><\/p>\n<ul>\n<li>Categoria Master:\u00a0EC Barnab\u00e9 de Gravata\u00ed 4 x 0 Carrosel de Caxias do Sul\u00a0<\/li>\n<li>Categoria Livre:\u00a0Vila Nova de Taquara 0 x 1 GE S\u00e3o Pedrense\u00a0<\/li>\n<li>Categoria Veterano: Caponense FC de Cap\u00e3o da Canoa 2 x 2 Respeito e Igualdade de Torres. Caponense 9 x 8 Respeito nos p\u00eanaltis.<\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom SEL | Edi\u00e7\u00e3o: Secom | Foto: Willian Abi\/Divulga\u00e7\u00e3o<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Organizada pela Secretaria do Esporte e Lazer, a copa \u00e9 a maior competi\u00e7\u00e3o de equipes de futebol do Estado Depois de 237 partidas, 165 times e mais de 6,5 mil profissionais envolvidos, a segunda edi\u00e7\u00e3o da Copa RS de Futebol Amador definiu os campe\u00f5es das tr\u00eas categorias em decis\u00f5es realizadas no est\u00e1dio Ant\u00f4nio Vieira Ramos, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70133"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70133\/revisions"}],"predecessor-version":[{"id":70135,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70133\/revisions\/70135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70134"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}