{"id":70159,"date":"2024-12-03T10:43:36","date_gmt":"2024-12-03T13:43:36","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70159"},"modified":"2024-12-03T10:43:40","modified_gmt":"2024-12-03T13:43:40","slug":"natal-cooperativo-da-sicredi-caminho-das-aguas-carreatas-natalinas-iluminam-o-litoral-norte-e-o-vale-do-paranhana","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/natal-cooperativo-da-sicredi-caminho-das-aguas-carreatas-natalinas-iluminam-o-litoral-norte-e-o-vale-do-paranhana\/","title":{"rendered":"Natal Cooperativo da Sicredi Caminho das \u00c1guas: Carreatas natalinas iluminam o Litoral Norte e o Vale do Paranhana"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em><span data-olk-copy-source=\"MessageBody\">Celebra\u00e7\u00e3o une comunidade, esp\u00edrito cooperativo e magia do Natal em cada cidade<\/span><\/em><\/p>\n<p>A magia do Natal vai tomar conta das ruas e avenidas do Litoral Norte e do Vale do Paranhana com as carreatas natalinas do\u00a0<em>Natal Cooperativo<\/em>\u00a0da Sicredi Caminho das \u00c1guas. Com um esp\u00edrito de solidariedade e alegria, a cooperativa levar\u00e1 luzes, m\u00fasicas e o encanto do Natal para diversas cidades da regi\u00e3o entre os dias 3 e 20 de dezembro.<\/p>\n<p>Ap\u00f3s um m\u00eas de arrecada\u00e7\u00e3o de brinquedos nas ag\u00eancias de seus munic\u00edpios de atua\u00e7\u00e3o, o Sicredi Caminho das \u00c1guas traz para a comunidade um presente especial: carreatas noturnas que ir\u00e3o passar por pontos estrat\u00e9gicos das cidades, iluminando os cora\u00e7\u00f5es e reunindo fam\u00edlias para uma celebra\u00e7\u00e3o coletiva. O\u00a0<em>Sicredi Conecta<\/em>, uma unidade m\u00f3vel especialmente decorada e iluminada para a ocasi\u00e3o, tamb\u00e9m estar\u00e1 presente, proporcionando um momento de integra\u00e7\u00e3o e encantamento para os moradores.<\/p>\n<p>A a\u00e7\u00e3o tem como objetivo n\u00e3o s\u00f3 espalhar a magia do Natal, mas tamb\u00e9m promover a solidariedade, com a entrega de brinquedos para crian\u00e7as da regi\u00e3o. A cooperativa convida a todos a participar e celebrar a data com o esp\u00edrito cooperativo, que caracteriza as a\u00e7\u00f5es da Sicredi Caminho das \u00c1guas.<\/p>\n<p>As carreatas acontecer\u00e3o de segunda a s\u00e1bado, conforme o cronograma abaixo. Nas cidades onde n\u00e3o h\u00e1 ag\u00eancia da cooperativa, a a\u00e7\u00e3o ser\u00e1 composta apenas pela carreata natalina, sem a distribui\u00e7\u00e3o de brinquedos.<\/p>\n<p>A Sicredi Caminho das \u00c1guas convida toda a comunidade a participar dessa celebra\u00e7\u00e3o natalina, que traz uni\u00e3o e solidariedade, al\u00e9m de refor\u00e7ar a import\u00e2ncia do cooperativismo como um agente de transforma\u00e7\u00e3o social e de fortalecimento das rela\u00e7\u00f5es comunit\u00e1rias.<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<h3><strong>Programe-se<\/strong><\/h3>\n<p><strong>3 de dezembro (ter\u00e7a-feira)<\/strong><\/p>\n<p>18h: Cara\u00e1 \u2013 Em frente aos Correios<\/p>\n<p>19h: Santo Ant\u00f4nio da Patrulha \u2013 Em frente \u00e0 Redemac<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>4 de dezembro (quarta-feira)<\/strong><\/p>\n<p>18h: Nova Hartz<\/p>\n<p>20h: Araric\u00e1<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>5 de dezembro (quinta-feira)<\/strong><\/p>\n<p>18h: Parob\u00e9<\/p>\n<p>20h: Taquara<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>6 de dezembro (sexta-feira)<\/strong><\/p>\n<p>18h: Igrejinha<\/p>\n<p>20h: Tr\u00eas Coroas<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>9 de dezembro (segunda-feira)<\/strong><\/p>\n<p>18h: Tavares\u00a0<\/p>\n<p>19h: Mostardas<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>10 de dezembro (ter\u00e7a-feira)<\/strong><\/p>\n<p>18h: Palmares do Sul<\/p>\n<p>20h: Capivari do Sul<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>11 de dezembro (quarta-feira)<\/strong><\/p>\n<p>16h: Imb\u00e9<\/p>\n<p>18h: Tramanda\u00ed<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>12 de dezembro (quinta-feira)<\/strong><\/p>\n<p>18h: Maquin\u00e9<\/p>\n<p>20h: Os\u00f3rio\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>13 de dezembro (sexta-feira)<\/strong><\/p>\n<p>17h: Xangri-l\u00e1<\/p>\n<p>19h: Cap\u00e3o da Canoa\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>14 de dezembro (s\u00e1bado)<\/strong><\/p>\n<p>18h: Balne\u00e1rio Pinhal\u00a0<\/p>\n<p>19h30: Cidreira<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>16 de dezembro (segunda-feira)<\/strong><\/p>\n<p>18h: Arroio do Sal\u00a0<\/p>\n<p>20h: Torres\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>17 de dezembro (ter\u00e7a-feira)<\/strong><\/p>\n<p>18h30: Morrinhos do Sul\u00a0<\/p>\n<p>19h30: Tr\u00eas Cachoeiras\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>18 de dezembro (quarta-feira)<\/strong><\/p>\n<p>18h: Terra de Areia\u00a0<\/p>\n<p>20h: Tr\u00eas Forquilhas<\/p>\n<p>20h15: Itati\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>19 de dezembro (quinta-feira)<\/strong><\/p>\n<p>18h: Campo Bom\u00a0<\/p>\n<p>20h: Sapiranga\u00a0<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>20 de dezembro (sexta-feira)<\/strong><\/p>\n<p>18h: Riozinho\u00a0<\/p>\n<p>20h: Rolante\u00a0<\/p>\n<hr \/>\n<h6><strong>Sublinha! Comunica\u00e7\u00e3o |\u00a0Consevitis-RS - Assessoria de Imprensa | Foto: Divulga\u00e7\u00e3o<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Celebra\u00e7\u00e3o une comunidade, esp\u00edrito cooperativo e magia do Natal em cada cidade A magia do Natal vai tomar conta das ruas e avenidas do Litoral Norte e do Vale do Paranhana com as carreatas natalinas do\u00a0Natal Cooperativo\u00a0da Sicredi Caminho das \u00c1guas. Com um esp\u00edrito de solidariedade e alegria, a cooperativa levar\u00e1 luzes, m\u00fasicas e o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70159"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70159\/revisions"}],"predecessor-version":[{"id":70161,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70159\/revisions\/70161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70160"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}