{"id":70165,"date":"2024-12-03T10:52:01","date_gmt":"2024-12-03T13:52:01","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70165"},"modified":"2024-12-03T10:52:03","modified_gmt":"2024-12-03T13:52:03","slug":"governo-realiza-repasse-emergencial-de-r-144-milhao-para-49-escolas-da-rede-estadual-atingidas-pelas-enchentes","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governo-realiza-repasse-emergencial-de-r-144-milhao-para-49-escolas-da-rede-estadual-atingidas-pelas-enchentes\/","title":{"rendered":"Governo realiza repasse emergencial de R$ 1,44 milh\u00e3o para 49 escolas da Rede Estadual atingidas pelas enchentes"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Valores adicionais, que come\u00e7aram a ser transferidos em junho, totalizam R$ 70,7 milh\u00f5es<\/em><\/p>\n<p>O governo do Estado realizou, nesta segunda-feira (2\/12), o repasse de R$ 1,44 milh\u00e3o\u00a0para 49 escolas estaduais que foram diretamente atingidas pelas enchentes de maio. Os valores comp\u00f5em a s\u00e9tima parcela emergencial encaminhada \u00e0s institui\u00e7\u00f5es de ensino por meio do programa Agiliza.\u00a0O\u00a0objetivo \u00e9\u00a0auxiliar na recupera\u00e7\u00e3o da Rede Estadual.<\/p>\n<p>Os investimentos fazem parte do\u00a0<strong><a href=\"https:\/\/planoriogrande.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\">Plano Rio Grande<\/a><\/strong>, que contempla tr\u00eas frentes de enfrentamento aos efeitos da crise meteorol\u00f3gica: a\u00e7\u00f5es emergenciais, reconstru\u00e7\u00e3o e prepara\u00e7\u00e3o para o futuro. Os recursos s\u00e3o depositados na conta das escolas, que podem utilizar as verbas adicionais para efetuar pequenas reformas e adquirir equipamentos e materiais, contando com autonomia financeira das equipes diretivas.\u00a0<\/p>\n<p>As parcelas extras variam de acordo com o grau do\u00a0impacto\u00a0das cheias. O primeiro n\u00edvel corresponde a um valor extra de R$ 20 mil\u00a0e\u00a0\u00e9 destinado \u00e0s escolas que registraram perdas menores\u00a0\u2013\u00a0como materiais pedag\u00f3gicos, administrativos e de bens de consumo.\u00a0<\/p>\n<p>As institui\u00e7\u00f5es que tamb\u00e9m registraram estragos em equipamentos e mobili\u00e1rios recebem um repasse maior, de R$ 40 mil. Nos casos mais cr\u00edticos, onde houve alagamentos, inc\u00eandios ou queda de telhados, as escolas s\u00e3o contempladas com o maior valor adicional, de R$ 80 mil.<\/p>\n<p>Os recursos extras para eventos clim\u00e1ticos come\u00e7aram a ser distribu\u00eddos em junho com um primeiro repasse de R$ 24,2 milh\u00f5es para 702 institui\u00e7\u00f5es de ensino. No m\u00eas de julho, um segundo montante de R$ 18,2 milh\u00f5es foi direcionado a 718 escolas. Em agosto, ocorreu um terceiro repasse de R$ 9,7 milh\u00f5es, que beneficiou 310 unidades escolares.<\/p>\n<p>Em setembro, R$ 4,7 milh\u00f5es foram alocados para 83 escolas, enquanto em outubro foram R$ 8 milh\u00f5es para 208 institui\u00e7\u00f5es. Por fim, em novembro, o Estado repassou R$ 4,46 milh\u00f5es para 162 escolas. Ao todo, somando com os valores depositados em dezembro, mais de R$ 70,7 milh\u00f5es foram destinados via Agiliza.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Seduc | Edi\u00e7\u00e3o: Felipe Borges\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Valores adicionais, que come\u00e7aram a ser transferidos em junho, totalizam R$ 70,7 milh\u00f5es O governo do Estado realizou, nesta segunda-feira (2\/12), o repasse de R$ 1,44 milh\u00e3o\u00a0para 49 escolas estaduais que foram diretamente atingidas pelas enchentes de maio. Os valores comp\u00f5em a s\u00e9tima parcela emergencial encaminhada \u00e0s institui\u00e7\u00f5es de ensino por meio do programa Agiliza.\u00a0O\u00a0objetivo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70165"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70165\/revisions"}],"predecessor-version":[{"id":70167,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70165\/revisions\/70167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70166"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}