{"id":70289,"date":"2024-12-09T09:28:06","date_gmt":"2024-12-09T12:28:06","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70289"},"modified":"2024-12-09T09:28:08","modified_gmt":"2024-12-09T12:28:08","slug":"ministerio-da-agricultura-e-pecuaria-reconhece-selo-ambiental-do-instituto-rio-grandense-do-arroz","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/ministerio-da-agricultura-e-pecuaria-reconhece-selo-ambiental-do-instituto-rio-grandense-do-arroz\/","title":{"rendered":"Minist\u00e9rio da Agricultura e Pecu\u00e1ria reconhece Selo Ambiental do Instituto Rio Grandense do Arroz"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Agora, produtores ga\u00fachos agraciados com a distin\u00e7\u00e3o t\u00eam direito a desconto nos empr\u00e9stimos do Plano Safra<\/em><\/p>\n<p>O Minist\u00e9rio da Agricultura e Pecu\u00e1ria (Mapa), por interm\u00e9dio da Secretaria de Inova\u00e7\u00e3o, Desenvolvimento Sustent\u00e1vel, Irriga\u00e7\u00e3o e Cooperativismo, reconheceu que o Selo Ambiental do Instituto Rio Grandense do Arroz (Irga) atende aos requisitos m\u00ednimos de Boas Pr\u00e1ticas Agr\u00edcolas, conforme a Portaria Mapa 337\/2021. A decis\u00e3o foi publicada no Di\u00e1rio Oficial da Uni\u00e3o.<\/p>\n<p>A partir dessa defini\u00e7\u00e3o, o Irga, que \u00e9 vinculado \u00e0 Secretaria da Agricultura, Pecu\u00e1ria, Produ\u00e7\u00e3o Sustent\u00e1vel e Irriga\u00e7\u00e3o (Seapi), torna-se uma entidade certificadora do Mapa e os produtores agraciados com o Selo Ambiental passam a ter direito a desconto nos empr\u00e9stimos contra\u00eddos por meio do Plano Safra.<\/p>\n<p>Programa do governo federal, o Plano Safra oferece financiamento para a atividade agr\u00edcola no Brasil. S\u00e3o v\u00e1rias linhas de cr\u00e9dito, que podem ser utilizadas para custeio, comercializa\u00e7\u00e3o e investimento. O acesso \u00e0s linhas de cr\u00e9dito depende de v\u00e1rios fatores, como a atividade do produtor, o tamanho da propriedade e a renda anual. \u00c9 destinado a todos os produtores rurais, mas prioriza pequenos e m\u00e9dios agricultores, cooperativas, agroind\u00fastrias e agricultura empresarial.<\/p>\n<p>A autarquia formalizou o pedido de reconhecimento junto ao Minist\u00e9rio da Agricultura e Pecu\u00e1ria no in\u00edcio deste ano, durante a 34\u00aa Abertura Oficial da Colheita do Arroz, que ocorreu em Cap\u00e3o do Le\u00e3o. <em>\u201cAguard\u00e1vamos com muita aten\u00e7\u00e3o esse reconhecimento do Mapa, que comemoramos agora a oficializa\u00e7\u00e3o. Isso ir\u00e1 agilizar de forma consider\u00e1vel os processos de empr\u00e9stimos solicitados pelos orizicultores por meio do Plano Safra, al\u00e9m de garantir um desconto para quem recebeu o nosso Selo Ambiental. Neste processo, quero destacar o trabalho da diretora t\u00e9cnica, Fl\u00e1via Tomita, e do coordenador do programa, engenheiro agr\u00f4nomo Rafael Nunes, que se empenharam muito na tarefa de conseguir essa aprova\u00e7\u00e3o do Minist\u00e9rio<\/em>\u201d, explicou o presidente do instituto, Rodrigo Machado.<\/p>\n<p>O Selo Ambiental foi criado pelo Irga em 2008 e tem como objetivos principais promover a sustentabilidade ambiental do sistema de produ\u00e7\u00e3o de arroz irrigado e garantir aos empreendimentos agr\u00edcolas o reconhecimento quanto ao uso de pr\u00e1ticas ambientais e sociais corretas na lavoura de arroz irrigado. Al\u00e9m disso, busca melhorar a gest\u00e3o da propriedade rural, reduzir custos agregados ao processo produtivo, contribuir para agrega\u00e7\u00e3o de valor ao produto e incentivar a produ\u00e7\u00e3o de arroz dentro dos princ\u00edpios da seguran\u00e7a do alimento.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Seapi e Ascom Irga | Edi\u00e7\u00e3o: Secom | Foto: Divulga\u00e7\u00e3o Seapi<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Agora, produtores ga\u00fachos agraciados com a distin\u00e7\u00e3o t\u00eam direito a desconto nos empr\u00e9stimos do Plano Safra O Minist\u00e9rio da Agricultura e Pecu\u00e1ria (Mapa), por interm\u00e9dio da Secretaria de Inova\u00e7\u00e3o, Desenvolvimento Sustent\u00e1vel, Irriga\u00e7\u00e3o e Cooperativismo, reconheceu que o Selo Ambiental do Instituto Rio Grandense do Arroz (Irga) atende aos requisitos m\u00ednimos de Boas Pr\u00e1ticas Agr\u00edcolas, conforme [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70289"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70289\/revisions"}],"predecessor-version":[{"id":70291,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70289\/revisions\/70291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70290"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}