{"id":70415,"date":"2024-12-12T09:03:04","date_gmt":"2024-12-12T12:03:04","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70415"},"modified":"2024-12-12T09:03:05","modified_gmt":"2024-12-12T12:03:05","slug":"com-premio-especial-no-valor-de-r-100-mil-sorteio-de-dezembro-do-nfg-distribui-r-250-mil-na-quinta-12","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/com-premio-especial-no-valor-de-r-100-mil-sorteio-de-dezembro-do-nfg-distribui-r-250-mil-na-quinta-12\/","title":{"rendered":"Com pr\u00eamio especial no valor de R$ 100 mil, sorteio de dezembro do NFG distribui R$ 250 mil na quinta (12)"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Em comemora\u00e7\u00e3o ao Natal, ganhador da premia\u00e7\u00e3o principal levar\u00e1 o dobro da quantia tradicional<\/em><\/p>\n<p>O m\u00eas de dezembro j\u00e1 \u00e9 tradicionalmente conhecido pelos cadastrados no Nota Fiscal Ga\u00facha (NFG) como um per\u00edodo com ainda mais pr\u00eamios. E em celebra\u00e7\u00e3o ao Natal, o pr\u00eamio principal do sorteio mensal de dezembro ser\u00e1 no valor de R$ 100 mil, o dobro da quantia tradicional.<\/p>\n<p><em>\u201cNo \u00faltimo m\u00eas do ano, al\u00e9m do pr\u00eamio especial, outra mudan\u00e7a que temos \u00e9 a antecipa\u00e7\u00e3o da realiza\u00e7\u00e3o do sorteio em fun\u00e7\u00e3o das festas de final de ano. Essas duas a\u00e7\u00f5es s\u00e3o uma maneira de tornar as datas celebrativas ainda mais especiais para o cidad\u00e3o que participa do NFG e exerce a cidadania fiscal.\u00a0 Como o pr\u00eamio principal \u00e9 o dobro do sorteado nos outros meses, em dezembro ser\u00e3o ao todo R$ 250 mil divididos em 111 pr\u00eamios. Al\u00e9m do vencedor dos R$ 100 mil, dez consumidores levar\u00e3o R$ 5 mil cada e outros 100 receber\u00e3o R$ 1 mil\u201d<\/em>, informou o coordenador do Nota Fiscal Ga\u00facha, Fernando Rodrigues dos Santos.<\/p>\n<p>Conforme as regras do programa, est\u00e3o concorrendo aos pr\u00eamios os consumidores inscritos no NFG que solicitaram nota fiscal com a inclus\u00e3o do n\u00famero do CPF durante todo o m\u00eas de novembro. O resultado do sorteio ser\u00e1 disponibilizado no site ou no aplicativo do programa Nota Fiscal Ga\u00facha. As pessoas contempladas dever\u00e3o solicitar o resgate dos valores em at\u00e9 90 dias, contados a partir da homologa\u00e7\u00e3o do sorteio.<\/p>\n<p>Em dezembro, mais de 68 milh\u00f5es de bilhetes disputar\u00e3o os diversos pr\u00eamios do sorteio mensal n\u00ba 147.<\/p>\n<p><strong>Pr\u00eamios do sorteio mensal de dezembro<\/strong><\/p>\n<ul>\n<li>R$ 100 mil (uma pessoa)<\/li>\n<li>R$ 5 mil (dez pessoas)\u00a0<\/li>\n<li>R$ 1 mil (100 pessoas)<\/li>\n<\/ul>\n<p><strong>Nota Fiscal Ga\u00facha<\/strong><\/p>\n<p>O Nota Fiscal Ga\u00facha conta com 3,9 milh\u00f5es de participantes. Cada vez que um consumidor solicita a inclus\u00e3o do seu CPF na nota fiscal, o programa gera pontos para concorrer a pr\u00eamios.<\/p>\n<p>Coordenado pela Receita Estadual, o NFG incentiva a popula\u00e7\u00e3o a solicitar a nota fiscal, como forma de conscientizar sobre a import\u00e2ncia social dos impostos, em uma iniciativa de cidadania fiscal.<\/p>\n<p>Ao incluir o CPF no momento da compra, o cidad\u00e3o concorre a pr\u00eamios em dinheiro e garante outros benef\u00edcios. \u00c9 poss\u00edvel tamb\u00e9m indicar entidades sociais das \u00e1reas de sa\u00fade, educa\u00e7\u00e3o, assist\u00eancia social e prote\u00e7\u00e3o animal, que recebem repasses trimestrais.<\/p>\n<p><strong>Outras vantagens<\/strong><\/p>\n<p><strong>Receita da Sorte:<\/strong>\u00a0distribui diariamente pr\u00eamios instant\u00e2neos de R$ 500, R$ 50, R$ 10 e R$ 5. No total, s\u00e3o R$ 24 mil por dia. Em datas especiais, as premia\u00e7\u00f5es chegam a R$ 1 mil. Para concorrer, \u00e9 preciso ter o aplicativo do NFG instalado e solicitar CPF na nota. No mesmo dia da compra, os contribuintes devem acessar a aba \u201cReceita da Sorte\u201d e clicar na nota fiscal ou fazer a leitura do QR Code do documento. O resultado sai na hora.<\/p>\n<p><strong>Receita Certa:<\/strong>\u00a0distribui valores sempre que h\u00e1 aumento real na arrecada\u00e7\u00e3o do ICMS do varejo. As apura\u00e7\u00f5es s\u00e3o trimestrais, feitas nos meses de mar\u00e7o, junho, setembro e dezembro. Todos os inscritos no NFG que incluem o CPF na nota no respectivo per\u00edodo participam automaticamente.<\/p>\n<p><strong>Bom Cidad\u00e3o:<\/strong>\u00a0\u00e9 um desconto no valor do IPVA, que varia de acordo com o n\u00famero de notas fiscais com CPF. Quem acumula 150 notas ou mais alcan\u00e7a redu\u00e7\u00e3o de 5%. O desconto \u00e9 de 3% para quem tem entre 100 e 149 documentos e de 1% para quem acumula de 51 a 99 notas.<\/p>\n<p><strong>Repasse a entidades:<\/strong>\u00a0na hora do cadastro, os cidad\u00e3os podem escolher pelo menos uma entidade da sua regi\u00e3o que atue nas \u00e1reas de assist\u00eancia social, educa\u00e7\u00e3o, sa\u00fade e prote\u00e7\u00e3o animal. As institui\u00e7\u00f5es indicadas podem receber repasses em dinheiro. \u00c9 poss\u00edvel indicar at\u00e9 cinco entidades, sendo que uma delas deve pertencer a um Conselho Regional de Desenvolvimento diferente dos demais.<\/p>\n<p>Nas redes sociais do NFG s\u00e3o divulgadas novidades e premia\u00e7\u00f5es:\u00a0<\/p>\n<ul>\n<li><strong>Instagram:\u00a0<a href=\"https:\/\/www.instagram.com\/notafiscalgaucha\/\" target=\"_blank\" rel=\"noopener\">@notafiscalgaucha\u00a0<\/a>\u00a0<\/strong><\/li>\n<li><strong>Facebook:\u00a0<a href=\"https:\/\/www.facebook.com\/notafiscalgaucha\/?locale=pt_BR\" target=\"_blank\" rel=\"noopener\">@notafiscalgaucha<\/a><\/strong><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Juliane Kerschner\/Ascom Sefaz | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Em comemora\u00e7\u00e3o ao Natal, ganhador da premia\u00e7\u00e3o principal levar\u00e1 o dobro da quantia tradicional O m\u00eas de dezembro j\u00e1 \u00e9 tradicionalmente conhecido pelos cadastrados no Nota Fiscal Ga\u00facha (NFG) como um per\u00edodo com ainda mais pr\u00eamios. E em celebra\u00e7\u00e3o ao Natal, o pr\u00eamio principal do sorteio mensal de dezembro ser\u00e1 no valor de R$ 100 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70415"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70415\/revisions"}],"predecessor-version":[{"id":70417,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70415\/revisions\/70417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70416"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}