{"id":70424,"date":"2024-12-12T09:26:15","date_gmt":"2024-12-12T12:26:15","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70424"},"modified":"2024-12-12T09:26:16","modified_gmt":"2024-12-12T12:26:16","slug":"governo-lanca-plataforma-tudo-facil-empresas-em-15-municipios","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governo-lanca-plataforma-tudo-facil-empresas-em-15-municipios\/","title":{"rendered":"Governo lan\u00e7a plataforma Tudo F\u00e1cil Empresas em 15 munic\u00edpios"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Eduardo Leite afirmou que a burocracia n\u00e3o pode ser um entrave ao empreendedorismo<\/em><\/p>\n<p>O governo do Estado lan\u00e7ou, nesta quarta-feira (11\/12), a plataforma Tudo F\u00e1cil Empresas (TFE) em 15 munic\u00edpios ga\u00fachos, sendo esse o \u00faltimo lote de 2024. O projeto da Junta Comercial, Industrial e Servi\u00e7os do RS (JucisRS), vinculada \u00e0 Secretaria de Desenvolvimento Econ\u00f4mico (Sedec), tem o objetivo de facilitar a abertura e a formaliza\u00e7\u00e3o de empresas de baixo risco, de forma totalmente gratuita, sem burocracia e em at\u00e9 10 minutos. A cerim\u00f4nia, com a presen\u00e7a do governador Eduardo Leite, ocorreu no Pal\u00e1cio Piratini.<\/p>\n<p>Os 15 novos munic\u00edpios contemplados s\u00e3o: Lajeado, Santo Augusto, Faxinal do Soturno, S\u00e3o Sebasti\u00e3o do Ca\u00ed, Cangu\u00e7u, Marau, Chiapetta, S\u00e3o Jos\u00e9 do Norte, Camaqu\u00e3, Dom Pedrito, Ca\u00e7apava do Sul, Rodeio Bonito, \u00c1gua Santa, Soledade e Lavras do Sul.<\/p>\n<p>Desse modo, o Estado termina o ano com a plataforma ativa em 61 munic\u00edpios. A proje\u00e7\u00e3o \u00e9 aumentar para 80 munic\u00edpios em 2025. Leite destacou que a burocracia n\u00e3o pode ser um entrave ao empreendedorismo.<\/p>\n<p>\u201c<em>Desburocratiza\u00e7\u00e3o \u00e9 um comando desse governo desde os primeiros anos da gest\u00e3o. Conseguimos avan\u00e7ar muito nesses \u00faltimos anos. Al\u00e9m de contar com essa ferramenta que permite a abertura de empresas de forma mais c\u00e9lere, o Rio Grande do Sul \u00e9 o Estado tricampe\u00e3o em servi\u00e7os digitais ofertados aos cidad\u00e3os e que possui o maior n\u00famero de atividades dispensadas de licenciamentos. Com o Tudo F\u00e1cil Empresas, temos a certeza de que estamos em um bom caminho e vamos continuar propiciando um ambiente de neg\u00f3cios favor\u00e1vel no Estado<\/em>\u201d, afirmou o governador.<\/p>\n<p>O titular da Sedec, Ernani Polo, ressaltou que ferramentas como esta est\u00e3o alinhadas com o prop\u00f3sito do governo estadual de tornar o Rio Grande do Sul um local prop\u00edcio para quem quer empreender. <em>\u201cQueremos que o Estado seja um parceiro do empreendedor, com acesso \u00e0s facilidades, mais celeridade e menos burocracia. \u00c9 uma rea\u00e7\u00e3o em cadeia que movimenta direta e indiretamente os envolvidos\u201d<\/em>, disse.\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-70426 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/12\/51-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/12\/51-400x266.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/12\/51-768x511.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/12\/51-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2024\/12\/51.jpg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A presidente da JucisRS, Lauren Momback Mazzardo, comentou a import\u00e2ncia dessa funcionalidade para o desenvolvimento dos munic\u00edpios ga\u00fachos. \u201c<em>O TFE \u00e9 essencial para simplificar os processos, al\u00e9m de ampliar o acesso dos empreendedores a servi\u00e7os de formaliza\u00e7\u00e3o. Ele representa o fortalecimento do empreendedorismo no Estado, oferecendo rapidez e praticidade para aqueles que desejam iniciar suas atividades empresariais<\/em>\u201d, pontuou.\u00a0<\/p>\n<p>O processo est\u00e1 no escopo do\u00a0<a href=\"https:\/\/www.estado.rs.gov.br\/apresentado-por-leite-plano-de-desenvolvimento-economico-inclusivo-e-sustentavel-sera-gps-para-o-estado-nas-proximas-decadas\" target=\"_blank\" rel=\"noopener\"><strong>Plano de Desenvolvimento Econ\u00f4mico, Inclusivo e Sustent\u00e1vel<\/strong><\/a>\u00a0e se enquadra no habilitador (que consiste em uma prioridade estrat\u00e9gica) ambiente de neg\u00f3cios, por oferecer facilidades na abertura de empresas.<\/p>\n<p><strong>Tudo F\u00e1cil Empresas<\/strong><\/p>\n<p>Lan\u00e7ada no dia 15 de dezembro de 2021, a plataforma Tudo F\u00e1cil Empresas tamb\u00e9m disponibiliza para o empreendedor ga\u00facho toda a documenta\u00e7\u00e3o necess\u00e1ria para iniciar seus neg\u00f3cios, como a dispensa dos licenciamentos, inscri\u00e7\u00e3o municipal e estadual e an\u00e1lise de endere\u00e7amento, em at\u00e9 10 minutos.<\/p>\n<p>O sistema conta ainda com a vers\u00e3o 2.0, que une dois fluxos para abertura de neg\u00f3cios, o fluxo tradicional, em que as etapas s\u00e3o realizadas separadamente, com a an\u00e1lise humana, e o fluxo r\u00e1pido, que \u00e9 feito de forma totalmente online e por meio da plataforma TFE. At\u00e9 o in\u00edcio de dezembro, foram abertas 2.022 empresas pelo fluxo r\u00e1pido e 8.547 pelo tradicional, totalizando 10.569 novos empreendimentos.<\/p>\n<p>Al\u00e9m disso, h\u00e1 uma atualiza\u00e7\u00e3o mais recente, o TFE 3.0, que permite a abertura de matriz e filiais simultaneamente para as naturezas jur\u00eddicas Empres\u00e1rio Individual e Sociedade Empresarial Limitada. A ferramenta \u00e9 idealizada de acordo com a Lei de Liberdade Econ\u00f4mica pelo Conselho Estadual de Desburocratiza\u00e7\u00e3o e Empreendedorismo (Cede), DescomplicaRS, JucisRS e Servi\u00e7o Brasileiro de Apoio \u00e0s Micro e Pequenas Empresas (Sebrae).<\/p>\n<p><strong>Os 61 munic\u00edpios ga\u00fachos contemplados at\u00e9 agora s\u00e3o:<\/strong><\/p>\n<ul>\n<li>Porto Alegre<\/li>\n<li>Novo Hamburgo<\/li>\n<li>Panambi<\/li>\n<li>Bag\u00e9<\/li>\n<li>Erechim<\/li>\n<li>Gravata\u00ed<\/li>\n<li>Estrela<\/li>\n<li>Santa Cruz do Sul<\/li>\n<li>Esteio<\/li>\n<li>Caxias do Sul<\/li>\n<li>Rio Grande<\/li>\n<li>S\u00e3o Borja<\/li>\n<li>Sapiranga<\/li>\n<li>Farroupilha<\/li>\n<li>Sapucaia do Sul<\/li>\n<li>Ven\u00e2ncio Aires<\/li>\n<li>Montenegro<\/li>\n<li>Frederico Westphalen<\/li>\n<li>Rio Pardo<\/li>\n<li>S\u00e3o Leopoldo<\/li>\n<li>Uruguaiana<\/li>\n<li>Santo Ant\u00f4nio da Patrulha<\/li>\n<li>Gua\u00edba<\/li>\n<li>Tapejara<\/li>\n<li>Palmeira das Miss\u00f5es<\/li>\n<li>Santiago<\/li>\n<li>Ant\u00f4nio Prado<\/li>\n<li>Feliz<\/li>\n<li>Viam\u00e3o<\/li>\n<li>Restinga S\u00eaca<\/li>\n<li>Santa Maria<\/li>\n<li>Vera Cruz<\/li>\n<li>Pelotas<\/li>\n<li>Ivoti<\/li>\n<li>Campo Bom<\/li>\n<li>Brochier<\/li>\n<li>Flores da Cunha<\/li>\n<li>Carazinho<\/li>\n<li>Tupanciret\u00e3<\/li>\n<li>Salto do Jacu\u00ed<\/li>\n<li>Alvorada<\/li>\n<li>Mostardas<\/li>\n<li>Bento Gon\u00e7alves<\/li>\n<li>Itaqui<\/li>\n<li>Ibirub\u00e1<\/li>\n<li>Passo Fundo<\/li>\n<li>Lajeado<\/li>\n<li>Santo Augusto<\/li>\n<li>Faxinal do Soturno<\/li>\n<li>S\u00e3o Sebasti\u00e3o do Ca\u00ed<\/li>\n<li>Cangu\u00e7u<\/li>\n<li>Marau<\/li>\n<li>S\u00e3o Jos\u00e9 do Norte<\/li>\n<li>Camaqu\u00e3<\/li>\n<li>Chiapetta<\/li>\n<li>Dom Pedrito<\/li>\n<li>Ca\u00e7apava do Sul<\/li>\n<li>Rodeio Bonito<\/li>\n<li>\u00c1gua Santa<\/li>\n<li>Soledade<\/li>\n<li>Lavras do Sul<\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Sedec e Juliana Dias\/Secom | Edi\u00e7\u00e3o: Secom | Fotos: Vitor Rosa\/Pal\u00e1cio Piratini<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Eduardo Leite afirmou que a burocracia n\u00e3o pode ser um entrave ao empreendedorismo O governo do Estado lan\u00e7ou, nesta quarta-feira (11\/12), a plataforma Tudo F\u00e1cil Empresas (TFE) em 15 munic\u00edpios ga\u00fachos, sendo esse o \u00faltimo lote de 2024. O projeto da Junta Comercial, Industrial e Servi\u00e7os do RS (JucisRS), vinculada \u00e0 Secretaria de Desenvolvimento Econ\u00f4mico [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70425,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70424"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70424\/revisions"}],"predecessor-version":[{"id":70427,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70424\/revisions\/70427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70425"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}