{"id":70563,"date":"2024-12-18T09:58:36","date_gmt":"2024-12-18T12:58:36","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70563"},"modified":"2024-12-18T09:58:39","modified_gmt":"2024-12-18T12:58:39","slug":"22a-regiao-tradicionalista-apresenta-seus-novos-representantes","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/22a-regiao-tradicionalista-apresenta-seus-novos-representantes\/","title":{"rendered":"22\u00aa Regi\u00e3o Tradicionalista apresenta seus novos representantes"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p><em>\u201cAgrade\u00e7o a confian\u00e7a de todos e tenho plena certeza de que, juntos, vamos iniciar 2025 com muita for\u00e7a. Vamos trabalhar unidos para fortalecer ainda mais nossa regi\u00e3o e o tradicionalismo\u201d<\/em>, afirmou o novo coordenador da 22\u00aa Regi\u00e3o Tradicionalista (22\u00aa RT), Jo\u00e3o Rog\u00e9rio Machado, durante a solenidade de posse e apresenta\u00e7\u00e3o dos novos membros da coordenadoria. O evento aconteceu na noite de 16 de dezembro, na sede do CTG Quer\u00eancia Azaleia, em Parob\u00e9, e contou com a presen\u00e7a de patr\u00f5es e representantes de todas as entidades tradicionalistas da regi\u00e3o. A 2\u00aa Prenda do Rio Grande do Sul, J\u00falia Calvi da Silva, tamb\u00e9m esteve presente, destacando a import\u00e2ncia do trabalho coletivo para o crescimento e valoriza\u00e7\u00e3o do tradicionalismo.<\/p>\n<p>Jo\u00e3o Rog\u00e9rio Machado assume o cargo de coordenador da 22\u00aa RT para a gest\u00e3o 2025\/2026, tendo como vice coordenadora a tradicionalista Carla Elisa Behs. O Conselheiro do MTG, Ricardo Glademir Haag, completa a nova equipe de autoridade tradicionalista da regi\u00e3o. Eleitos no \u00faltimo dia 7 de dezembro, os novos membros da coordenadoria tomaram posse oficialmente em um evento realizado pelo Movimento Tradicionalista Ga\u00facho (MTG) em General C\u00e2mara, no dia 14 de dezembro, que reuniu conselheiros, coordenadores e vice coordenadores de todas as regi\u00f5es tradicionalistas do Estado, al\u00e9m da apresenta\u00e7\u00e3o do novo presidente do MTG.<\/p>\n<p>A cerim\u00f4nia em Parob\u00e9 foi marcada por uma combina\u00e7\u00e3o de despedidas e renova\u00e7\u00e3o das lideran\u00e7as tradicionalistas, mas com um prop\u00f3sito unificado: continuar promovendo e valorizando as tradi\u00e7\u00f5es e os valores da cultura rio-grandense.<\/p>\n<p>De acordo com os representantes da nova Coordenadoria da 22\u00aa RT, um dos principais objetivos da gest\u00e3o \u00e9 estreitar os la\u00e7os entre as entidades tradicionalistas e apoiar a\u00e7\u00f5es que promovam e fortale\u00e7am as tradi\u00e7\u00f5es ga\u00fachas. O novo coordenador, Jo\u00e3o Rog\u00e9rio Machado, ressaltou a import\u00e2ncia de dar continuidade e expandir os projetos voltados para o envolvimento das novas gera\u00e7\u00f5es com o tradicionalismo. <em>\u201cNosso foco ser\u00e1 incentivar a participa\u00e7\u00e3o dos jovens e dar mais visibilidade \u00e0s nossas tradi\u00e7\u00f5es, al\u00e9m de fortalecer ainda mais os la\u00e7os de fraternidade entre os CTGs\u201d,<\/em> afirmou Machado.<\/p>\n<p>A nova gest\u00e3o da 22\u00aa RT assume com a responsabilidade de manter viva a chama do tradicionalismo ga\u00facho, garantindo a continuidade de eventos e celebra\u00e7\u00f5es que representam a rica cultura do Rio Grande do Sul e com a miss\u00e3o de envolver as futuras gera\u00e7\u00f5es na preserva\u00e7\u00e3o dessas tradi\u00e7\u00f5es<\/p>\n<p>\u00a0<\/p>\n<p><strong>Os representantes da 22\u00aaRT \u2013 Gest\u00e3o 2025\/2026<\/strong><\/p>\n<p>Conselheiro do MTG - Ricardo Glademir Haag<\/p>\n<p>Coordenador 22\u00aa RT - Jo\u00e3o Rog\u00e9rio Machado<\/p>\n<p>Vice coordenadora 22\u00aa RT - Carla Elisa Behs<\/p>\n<p>Tesoureiro: Ezequiel Maur\u00edcio Haag<\/p>\n<p>Secret\u00e1ria: Marlizane Moraes Rocha<\/p>\n<p><strong>Comiss\u00e3o de \u00e9tica:<\/strong><\/p>\n<p>Ubiratan da Cunha Guilherme<\/p>\n<p>Joaquim Jos\u00e9 de Oliveira<\/p>\n<p>Solange Martins<\/p>\n<p>J\u00falio Bartzen de Ara\u00fajo<\/p>\n<p>Luciano Silva da Rosa<\/p>\n<p>Paulo Ricardo Machado<\/p>\n<p><strong>Conselho Fiscal:<\/strong><\/p>\n<p>Ivanilde Perboni Hoffmann<\/p>\n<p>Cassiano da Rocha<\/p>\n<p>Jeferson Luis Ferreira<\/p>\n<p>Auro Paulo Sander<\/p>\n<p>Angelo Daniel Schneider<\/p>\n<p>Estev\u00e3o Felipe dos Passos<\/p>\n<p><strong>Diretores de Departamentos:<\/strong><\/p>\n<p>Campeiro - Marcelo Camargo de Moraes<\/p>\n<p>Art\u00edstico - M\u00e1rcia Goreti da Silva<\/p>\n<p>Cultural - Marlizane Moraes Rocha<\/p>\n<p>Vice -Cultural: Ang\u00e9lica Smaniotto<\/p>\n<p>Esportes - Ant\u00f4nio Raul Rocha<\/p>\n<p>Cavalgadas - Claudecir Barbosa<\/p>\n<p>Dpto. Jovem - Camilly Moraes Rocha<\/p>\n<p><strong>Assessoras jur\u00eddicas:<\/strong><\/p>\n<p>Solange Martins e Carla Elisa Behs<\/p>\n<hr \/>\n<h6><strong>Assessoria de Imprensa - 22\u00aaRT \u2013 Gest\u00e3o 2025\/2026 | Texto e fotos: Claucia Ferreira\/ Assessora de Imprensa da 22\u00aaRT - Gest\u00e3o 2025\/2026<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cAgrade\u00e7o a confian\u00e7a de todos e tenho plena certeza de que, juntos, vamos iniciar 2025 com muita for\u00e7a. Vamos trabalhar unidos para fortalecer ainda mais nossa regi\u00e3o e o tradicionalismo\u201d, afirmou o novo coordenador da 22\u00aa Regi\u00e3o Tradicionalista (22\u00aa RT), Jo\u00e3o Rog\u00e9rio Machado, durante a solenidade de posse e apresenta\u00e7\u00e3o dos novos membros da coordenadoria. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70564,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70563"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70563\/revisions"}],"predecessor-version":[{"id":70565,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70563\/revisions\/70565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70564"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}