{"id":70602,"date":"2024-12-19T10:01:32","date_gmt":"2024-12-19T13:01:32","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70602"},"modified":"2024-12-19T10:01:33","modified_gmt":"2024-12-19T13:01:33","slug":"por-tras-das-luzes-como-a-caravana-de-natal-da-coca-cola-femsa-brasil-e-planejada-para-encantar-milhares-de-pessoas","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/por-tras-das-luzes-como-a-caravana-de-natal-da-coca-cola-femsa-brasil-e-planejada-para-encantar-milhares-de-pessoas\/","title":{"rendered":"Por tr\u00e1s das luzes: Como a Caravana de Natal da Coca-Cola FEMSA Brasil \u00e9 planejada para encantar milhares de pessoas"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>A empresa paranaense de marketing PromoPlus Live Marketing est\u00e1 \u00e0 frente de uma das principais a\u00e7\u00f5es de Natal no Brasil<\/em><\/p>\n<p>A Caravana de Natal da Coca-Cola FEMSA Brasil rodar\u00e1 o pa\u00eds at\u00e9 o dia 23 de dezembro. O show itiner\u00e1rio encanta o p\u00fablico por onde passa. Ao todo, a Caravana de Natal percorrer\u00e1 19 mil quil\u00f4metros, visitando 85 munic\u00edpios, distribu\u00eddos por 7 Estados, e impactar\u00e1 mais de 62 milh\u00f5es de pessoas. A empresa paranaense de marketing PromoPlus Live Marketing, respons\u00e1vel pela Caravana de Natal h\u00e1 mais de 10 anos, faz a magia acontecer atrav\u00e9s de muito trabalho e dedica\u00e7\u00e3o. Para que tudo isso seja poss\u00edvel, a empresa conta com profissionais de v\u00e1rios estados contratados temporariamente. \u201c<em>S\u00e3o seis meses de prepara\u00e7\u00e3o todos os anos para fazer a caravana em v\u00e1rias cidades do Brasil, geramos mais de 150 empregos diretos e indiretos na execu\u00e7\u00e3o desta campanha que \u00e9 uma de refer\u00eancia mundial na Coca-Cola\u201d<\/em>, explica a s\u00f3cia fundadora da PromoPlus, Ana Paula Barbosa.<\/p>\n<p>\u00a0<\/p>\n<p>Nos bastidores da Caravana de Natal da Coca-Cola FEMSA Brasil, a equipe de produ\u00e7\u00e3o trabalha com 3.200 metros de mangueiras luminosas e 1.000 pontos de fibra \u00f3ptica para compor o cen\u00e1rio visual. Um dos elementos principais \u00e9 a instala\u00e7\u00e3o de 40 metros de pain\u00e9is de LED em formato de lata de Coca-Cola, que exigem programa\u00e7\u00e3o detalhada para apresentar v\u00eddeos com \u00edcones da marca, simula\u00e7\u00f5es do l\u00edquido da bebida e elementos desenvolvidos com intelig\u00eancia artificial. A montagem e sincroniza\u00e7\u00e3o dessas estruturas s\u00e3o realizadas por equipes especializadas, garantindo a execu\u00e7\u00e3o de cada detalhe t\u00e9cnico. <em>\u201cEssa caravana representa o resultado de meses de planejamento e trabalho em equipe, com profissionais de diversas \u00e1reas alinhados para criar uma experi\u00eancia que vai al\u00e9m do visual. Nosso foco est\u00e1 em unir tecnologia e criatividade para transmitir a mensagem da marca de forma impactante e memor\u00e1vel, sempre considerando os desafios de log\u00edstica e produ\u00e7\u00e3o que um projeto dessa magnitude exige. \u00c9 um orgulho ver o conceito ganhar vida e se transformar em um espet\u00e1culo que envolve e emociona o p\u00fablico\u201d<\/em>, comenta Ana Paula.<\/p>\n<p>\u00a0<\/p>\n<p>Todo ano h\u00e1 uma novidade, mas neste ano a Caravana traz uma simbologia duplamente especial. Com o tema \u201cDesperte o Papai Noel que h\u00e1 em voc\u00ea\u201d, a caravana ter\u00e1 a\u00e7\u00f5es e atra\u00e7\u00f5es especiais quando passar pelo Rio Grande do Sul. Um caminh\u00e3o extra no comboio traz a mensagem \u201cUnidos Pelo Rio Grande do Sul\u201d e um jingle ga\u00facho foi criado para celebrar a regi\u00e3o. A a\u00e7\u00e3o tamb\u00e9m ir\u00e1 envolver doa\u00e7\u00f5es de 900 cestas b\u00e1sicas, que ser\u00e3o entregues para 18 ONGs de diversas cidades, al\u00e9m de visitar clientes da Coca-Cola FEMSA Brasil. \u201c<em>A iniciativa \u00e9 uma das mais aguardadas em todo o territ\u00f3rio da Coca-Cola FEMSA Brasil, e este ano ela ganha um significado ainda mais especial. Ap\u00f3s os desafios enfrentados pelas comunidades do Rio Grande do Sul, devido \u00e0s recentes enchentes, decidimos expandir nossa Caravana de Natal e criar uma a\u00e7\u00e3o pensada especialmente para o Estado, com o objetivo de levar mais esperan\u00e7a e alegria \u00e0s localidades afetadas. Al\u00e9m disso, vamos atender duas rotas simultaneamente, ampliando o n\u00famero de cidades contempladas e levando a magia do Natal a ainda mais pessoas, especialmente \u00e0quelas que enfrentaram momentos de dificuldade\u201d<\/em>, afirma Luciano S\u00e1, gerente de Experience &amp; Prestige Accounts da Coca-Cola FEMSA Brasil.<\/p>\n<p>\u00a0<\/p>\n<p>Outra simbologia desse ano \u00e9 que a Ag\u00eancia PromoPlus Live Marketing celebra 25 anos de muita hist\u00f3ria e parceria com a Coca-Cola. \u201c<em>Celebrar 25 anos de hist\u00f3ria com um projeto t\u00e3o especial como a caravana de Natal \u00e9 muito significativo para n\u00f3s, especialmente por estarmos \u00e0 frente dessa produ\u00e7\u00e3o h\u00e1 10 anos. Cada edi\u00e7\u00e3o nos desafia a inovar e entregar resultados que impactam o p\u00fablico de forma positiva. Este ano, estamos especialmente orgulhosos de incluir uma a\u00e7\u00e3o social voltada ao apoio das comunidades do Rio Grande do Sul, refor\u00e7ando nosso compromisso em usar nosso trabalho para gerar conex\u00f5es mais profundas e contribuir com quem mais precisa<\/em>\u201d, finaliza a s\u00f3cia fundadora da PromoPlus, Ana Paula Barbosa.<\/p>\n<p>\u00a0<\/p>\n<p>A Caravana Iluminada \u00e9 uma atra\u00e7\u00e3o gratuita e suas datas e percursos detalhados podem ser conferidos no site <a href=\"https:\/\/natal.coca-cola.com.br\/\">https:\/\/natal.coca-cola.com.br\/<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p><strong>25 anos de hist\u00f3ria<\/strong><\/p>\n<p>A PromoPlus possui ra\u00edzes diversas, fundada no Paran\u00e1, em 1999, por Renato Rema Gaudeoso, natural de S\u00e3o Paulo, formado em administra\u00e7\u00e3o pela USP e p\u00f3s-graduado em T\u00e9cnicas de Consumo e Pesquisa pela Universidade de Barcelona, e Ana Paula Barbosa, nascida na Fran\u00e7a, formada em marketing e publicidade no Instituto de Com\u00e9rcio de Paris e p\u00f3s-graduada em T\u00e9cnica de Pesquisa e Comunica\u00e7\u00e3o tamb\u00e9m pela Universidade de Barcelona. A ag\u00eancia logo alcan\u00e7ou o mercado nacional em 2005, com a compra da Spaipa, f\u00e1brica da Coca-Cola no Paran\u00e1, pela FEMSA, que levou a PromoPlus a atender todas as suas marcas, dando in\u00edcio a expans\u00e3o para S\u00e3o Paulo. <em>\u201cJ\u00e1 trabalh\u00e1vamos em a\u00e7\u00f5es da Coca-Cola e naquele ano est\u00e1vamos com um projeto incr\u00edvel de ver\u00e3o no litoral do Paran\u00e1. Quando houve a compra pelo grupo FEMSA, nosso trabalho foi solicitado para a praia de Maresias em S\u00e3o Paulo e a partir disso come\u00e7amos a atender o grupo todo<\/em>\u201d, conta a s\u00f3cia Ana Paula Barbosa.<\/p>\n<p>Atualmente s\u00e3o 24 marcas que englobam a FEMSA, al\u00e9m da Coca-Cola. Todas est\u00e3o no portf\u00f3lio da PromoPlus. Com o crescimento da ag\u00eancia, mais uma s\u00f3cia se juntou ao grupo, a curitibana Samara Ribas Zacharow, formada em Gest\u00e3o em Turismo pela Faculdade Curitiba e possui MBA em gest\u00e3o em comunica\u00e7\u00e3o organizacional pela FGV, come\u00e7ou como assistente no in\u00edcio da empresa e foi convidada a se unir a Ana e Renato em 2007. \u201c<em>A PromoPlus representa uma importante parte da minha vida profissional. Estar nesta posi\u00e7\u00e3o em uma empresa que chega aos seus 25 anos com uma vis\u00e3o estrat\u00e9gica atual e busca estar constantemente alinhada com as novas tecnologias \u00e9 gratificante\u201d<\/em>, comenta Samara.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Sobre a PromoPlus Live Marketing<\/strong><\/p>\n<p>A PromoPlus Live Marketing \u00e9 uma das principais empresas de marketing do Brasil, fundada pelo paulista Renato Rema Gaudeoso e a francesa Ana Paula Barbosa h\u00e1 25 anos, coleciona cases de sucesso e clientes de renome no pa\u00eds. Sua principal ativa\u00e7\u00e3o e talvez a mais conhecida seja a Caravana de Natal da Coca-Cola. Al\u00e9m disso, a ag\u00eancia atende clientes como a Coca-Cola FEMSA e suas 24 marcas, Monster, Positivo, O Botic\u00e1rio, Fox Lux, Cyrela, Renault, Nissan, Branco Motores, Paran\u00e1 Banco, Avantim, Enaex e Terminal de Paranagu\u00e1.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Roteiro da Caravana Iluminada da Coca-Cola FEMSA Brasil em 2024<\/strong><\/p>\n<p><strong>Santa Catarina<\/strong><br \/>13\/11 - Chapec\u00f3<br \/>27\/11 - Tubar\u00e3o e Crici\u00fama<br \/>28\/11 - Palho\u00e7a e S\u00e3o Jos\u00e9<br \/>29\/11 - Antonio Carlos e Bigua\u00e7u<br \/>30\/11 - Itaja\u00ed e Balne\u00e1rio Cambori\u00fa<br \/>16\/12 - Joinville<br \/>17\/12 - Blumenau<br \/>18\/12 - Florian\u00f3polis<\/p>\n<p>\u00a0<\/p>\n<p><strong>Rio Grande do Sul<\/strong><br \/>15\/11 - Passo Fundo<br \/>16\/11 - Santa Maria<br \/>17\/11 - Vera Cruz e Santa Cruz<br \/>18\/11 - Arroio de Moio, Lajeado e Estrela<br \/>20\/11 - Pelotas<br \/>22\/11 - Farroupilha e Caxias do Sul<br \/>23\/11 - Canoas, Cachoeirinha e Gravata\u00ed<br \/>24\/11 - Esteio, Sapucaia do Sul, Novo Hamburgo e S\u00e3o Leopoldo<br \/>20\/12 - Porto Alegre<br \/>21\/12 - Canela e Gramado<\/p>\n<p>\u00a0<\/p>\n<p><strong>Minas Gerais<\/strong><br \/>26\/11 - Belo Horizonte e Nova Lima<br \/>27\/11 - Itabirito<br \/>28\/11 - Juiz de Fora<br \/>06\/12 - Divin\u00f3polis<br \/>07\/12 - Betim e Contagem<\/p>\n<p>\u00a0<\/p>\n<p><strong>S\u00e3o Paulo<\/strong><br \/>19\/11 - Campinas<br \/>20\/11 - Jundia\u00ed<br \/>22, 23 e 24\/11 - S\u00e3o Paulo<br \/>02\/12 - Indaiatuba<br \/>03\/12 - Limeira<br \/>03\/12 - S\u00e3o Jos\u00e9 dos Campos<br \/>04\/12 - Cosm\u00f3polis, Americana e Santa B\u00e1rbara do Oeste<br \/>04\/12 - Mogi das Cruzes e Suzano<br \/>05\/12 - Praia Grande e Guaruj\u00e1<br \/>06\/12 - S\u00e3o Vicente e Santos<br \/>07\/12 - Santo Andr\u00e9 e S\u00e3o Caetano do Sul<br \/>08\/12 - Osasco e Guarulhos<br \/>09\/12 - Sumar\u00e9<br \/>11\/12 - Ol\u00edmpia e S\u00e3o Jos\u00e9 do Rio Preto<br \/>10\/12 - Bauru<br \/>11\/12 - Mar\u00edlia<br \/>12\/12 - Aracatuba<\/p>\n<p>\u00a0<\/p>\n<p><strong>Mato Grosso do Sul<\/strong><br \/>13\/12 - Campo Grande<br \/>14\/12 - Itapor\u00e3 e Dourados<\/p>\n<p>\u00a0<\/p>\n<p><strong>Paran\u00e1<\/strong><br \/>16\/12 - Foz do Igua\u00e7u<br \/>17\/12 - Cascavel e Toledo<br \/>18\/12 - Mandagua\u00e7u, Maring\u00e1 e Sarandi<br \/>19\/12 - Camb\u00e9 e Londrina<br \/>21\/12 - Guarapuava<br \/>23\/12 - Ponta Grossa<br \/>23\/12 - Curitiba e S\u00e3o Jos\u00e9 do Pinhais<\/p>\n<p>\u00a0<\/p>\n<p><strong>Rio de Janeiro<\/strong><br \/>29\/11 - Teres\u00f3polis e Petr\u00f3polis<br \/>01\/12 - Porto Real e Volta Redonda<\/p>\n<hr \/>\n<h6><strong>Grupo Excom | Foto: Divulga\u00e7\u00e3o PromoPlus\/ Caravana de Natal da Coca-Cola FEMSA Brasil<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>A empresa paranaense de marketing PromoPlus Live Marketing est\u00e1 \u00e0 frente de uma das principais a\u00e7\u00f5es de Natal no Brasil A Caravana de Natal da Coca-Cola FEMSA Brasil rodar\u00e1 o pa\u00eds at\u00e9 o dia 23 de dezembro. O show itiner\u00e1rio encanta o p\u00fablico por onde passa. Ao todo, a Caravana de Natal percorrer\u00e1 19 mil [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70602"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70602\/revisions"}],"predecessor-version":[{"id":70604,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70602\/revisions\/70604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70603"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}