{"id":70621,"date":"2024-12-20T09:22:56","date_gmt":"2024-12-20T12:22:56","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70621"},"modified":"2024-12-20T09:22:57","modified_gmt":"2024-12-20T12:22:57","slug":"olivicultura-avalia-ano-marcado-pela-resiliencia-e-projeta-2025-com-mais-avancos-para-o-setor","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/olivicultura-avalia-ano-marcado-pela-resiliencia-e-projeta-2025-com-mais-avancos-para-o-setor\/","title":{"rendered":"Olivicultura avalia ano marcado pela resili\u00eancia e projeta 2025 com mais avan\u00e7os para o setor"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Ibraoliva comemora in\u00fameras conquistas mesmo em ano marcado por enchentes<\/em><\/p>\n<p>O Instituto Brasileiro de Olivicultura (Ibraoliva) teve um ano de 2024 que ficar\u00e1 marcado pela resili\u00eancia e pela esperan\u00e7a. A avalia\u00e7\u00e3o \u00e9 do presidente do Instituto, Renato Fernandes, ao fazer um balan\u00e7o do ano. O presidente da entidade lembrou a dificuldade extrema para o setor imposta por uma enchente sem precedentes no Rio Grande do Sul, em maio.<\/p>\n<p>O dirigente refor\u00e7a que a olivicultura teve alguns desafios, enfrentando as chuvas ainda no ano de 2023 e a grande enchente de maio de 2024, o que encharcou demais o solo para o manejo da cultura.No entanto, Fernandes enumerou uma s\u00e9rie de conquistas no setor, mesmo em um ano negativamente at\u00edpico. \u201c<em>Come\u00e7o pela participa\u00e7\u00e3o do Ibraoliva no encontro ocorrido na C\u00e2mara Setorial de Fruticultura, em Bras\u00edlia (DF), depois acertamos parcerias estrat\u00e9gicas junto com o sistema Fecom\u00e9rcio, e tamb\u00e9m participamos de uma a\u00e7\u00e3o importante para os nossos produtores que mandaram os seus azeites para o Pr\u00eamio Governo do Estado do Rio Grande do Sul, sendo todos eles agraciados com a premia\u00e7\u00e3o<\/em>\u201d, destacou.<\/p>\n<p>Fernandes citou tamb\u00e9m a abertura da colheita, em fevereiro, em Gramado, a Olifeira, em Gua\u00edba, a Festa do Azeite em Ca\u00e7apava do Sul, a Feira do Azeite Novo, que acontece a cada 15 dias na Secretaria da Agricultura, as parcerias entre Ibraoliva, Senac e Sebrae e o apoio nas a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o do Minist\u00e9rio da Agricultura contra o azeite extravirgem adulterado.<\/p>\n<p>O presidente do Ibraoliva destacou ainda dois eventos muito importantes ocorridos dentro da Expointer deste ano. Um deles foi a inaugura\u00e7\u00e3o da casa Ibraoliva, no Parque Assis Brasil em Esteio (RS). \u201c<em>Esta foi uma grande conquista para os olivicultores e l\u00e1 se falou muito, recebemos autoridades. Outro ponto importante dentro da Expointer foi a assinatura da redu\u00e7\u00e3o de ICMS, de 12% para 4% na venda do azeite de oliva para fora do Rio Grande do Sul bem como o in\u00edcio da articula\u00e7\u00e3o para tentar zerar essa al\u00edquota<\/em>\u201d, ressaltou.<\/p>\n<p>Outro ponto fundamental destacado por Fernandes foi a visita de integrantes do Conselho Ole\u00edcola Internacional (COI) em propriedades de Restinga Seca, Ca\u00e7apava do Sul e Cachoeira do Sul para conhecer o trabalho e as potencialidades da olivicultura na regi\u00e3o.<em> \u201cE a\u00ed, sim, passamos um degrau acima, onde fomos considerados pela Associa\u00e7\u00e3o Mundial, tivemos a impress\u00e3o e a certeza que estamos no caminho certo, a partir do reconhecimento da qualidade do nosso azeite, onde tamb\u00e9m fomos apontados como um futuro produtor mundial<\/em>\u201d, projetou.<\/p>\n<p>Fernandes espera um 2025 com mais avan\u00e7os no sentido da busca de novas parcerias e tamb\u00e9m seguir perseguindo a consolida\u00e7\u00e3o de toda a olivicultura brasileira nos mercados. O presidente do Ibraoliva destacou como fundamental neste sentido que as pesquisas t\u00e9cnicas sigam avan\u00e7ando. <em>\u201cPara isso ser\u00e1 necess\u00e1rio o apoio governamental e a participa\u00e7\u00e3o do pr\u00f3prio COI neste processo, oferecendo conhecimentos dos bancos de germoplasma que eles t\u00eam tanto na Argentina como tamb\u00e9m na Europa\u201d<\/em>, concluiu. Bancos de germoplasma s\u00e3o institui\u00e7\u00f5es que conservam material gen\u00e9tico de plantas, animais e microrganismos para preservar a diversidade gen\u00e9tica e disponibilizar material gen\u00e9tico para pesquisa cient\u00edfica, agricultura e conserva\u00e7\u00e3o.<\/p>\n<hr \/>\n<h6><strong>AgroEffective | Assessoria de Comunica\u00e7\u00e3o do Instituto Brasileiro de Olivicultura (Ibraoliva) | Foto: Divulga\u00e7\u00e3o | Texto: Artur Chagas\/AgroEffective<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ibraoliva comemora in\u00fameras conquistas mesmo em ano marcado por enchentes O Instituto Brasileiro de Olivicultura (Ibraoliva) teve um ano de 2024 que ficar\u00e1 marcado pela resili\u00eancia e pela esperan\u00e7a. A avalia\u00e7\u00e3o \u00e9 do presidente do Instituto, Renato Fernandes, ao fazer um balan\u00e7o do ano. O presidente da entidade lembrou a dificuldade extrema para o setor [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70621"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70621\/revisions"}],"predecessor-version":[{"id":70623,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70621\/revisions\/70623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70622"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}