{"id":70750,"date":"2024-12-27T09:37:01","date_gmt":"2024-12-27T12:37:01","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70750"},"modified":"2024-12-27T09:37:02","modified_gmt":"2024-12-27T12:37:02","slug":"atingidos-pelas-enchentes-tem-ate-31-de-dezembro-para-adquirir-eletrodomesticos-com-restituicao-de-imposto","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/atingidos-pelas-enchentes-tem-ate-31-de-dezembro-para-adquirir-eletrodomesticos-com-restituicao-de-imposto\/","title":{"rendered":"Atingidos pelas enchentes t\u00eam at\u00e9 31 de dezembro para adquirir eletrodom\u00e9sticos com restitui\u00e7\u00e3o de imposto"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Programa Devolve ICMS Linha Branca ajuda a popula\u00e7\u00e3o afetada na reconstru\u00e7\u00e3o de seus lares<\/em><\/p>\n<p>O pr\u00f3ximo 31 de dezembro de 2024 \u00e9 o \u00faltimo dia para que pessoas atingidas pelas enchentes comprem eletrodom\u00e9sticos dentro do programa Devolve ICMS Linha Branca. A iniciativa da Secretaria da Fazenda (Sefaz), por meio da Receita Estadual, devolve parte do imposto pago na aquisi\u00e7\u00e3o desses itens, buscando ajudar a popula\u00e7\u00e3o afetada na reconstru\u00e7\u00e3o de seus lares.<\/p>\n<p>Os eletrodom\u00e9sticos inclu\u00eddos no programa s\u00e3o fog\u00e3o de cozinha (a g\u00e1s, a lenha ou el\u00e9trico), refrigerador, lava-roupas (inclusive lava e seca) de at\u00e9 18kg, m\u00e1quina de secar roupas de at\u00e9 10kg, m\u00e1quina de centrifugar roupas de at\u00e9 23kg e micro-ondas. A compra pode ser em loja on-line ou f\u00edsica, desde que o estabelecimento esteja localizado no Rio Grande do Sul \u2013\u00a0<a href=\"https:\/\/devolveicmslinhabranca.rs.gov.br\/veja-se-o-estabelecimento-e-participante\" target=\"_blank\" rel=\"noopener\"><strong>clique para conferir a lista de empresas participantes<\/strong><\/a>.<\/p>\n<p>Outras duas etapas ainda devem ser cumpridas. O comprador ou compradora deve solicitar a inclus\u00e3o de seu CPF na nota fiscal e tamb\u00e9m pedir ao estabelecimento que inclua na nota a Nomenclatura Comum do Mercosul (NCM), que representa o c\u00f3digo da mercadoria eleg\u00edvel. Os dados est\u00e3o dispon\u00edveis na tabela abaixo.<\/p>\n<figure class=\"artigo__ilustracao\"><a href=\"https:\/\/estado.rs.gov.br\/upload\/recortes\/202412\/26113700_2164627_GDO.jpg\" data-credito=\"\" data-urlamigavel=\"\/midia\/imagem\/tabela-novos-itens-lb-jpg\" data-legenda=\"-\" data-label-credito=\"Foto: \"><img decoding=\"async\" class=\"img-responsive\" src=\"https:\/\/estado.rs.gov.br\/upload\/recortes\/202412\/26113700_2164627_GDO.jpg\" alt=\"TABELA NOVOS ITENS LB\" \/><\/a><\/figure>\n<p>H\u00e1 um teto para a devolu\u00e7\u00e3o de valores referentes a cada item. A restitui\u00e7\u00e3o do ICMS pode ser de 100% ou parcial, sendo que cada benefici\u00e1rio(a) pode receber at\u00e9 R$ 1,5 mil. Para saber quem tem direito \u00e0 devolu\u00e7\u00e3o, basta\u00a0<a href=\"https:\/\/devolveicmslinhabranca.rs.gov.br\/quem-tem-direito\" target=\"_blank\" rel=\"noopener\"><strong>acessar este link<\/strong><\/a>\u00a0e fazer a consulta por CPF e data de nascimento. As pessoas inclu\u00eddas no programa foram identificadas por meio do Mapa \u00danico do Plano Rio Grande (MUP), que representa a mancha de inunda\u00e7\u00e3o\u00a0no Estado. As informa\u00e7\u00f5es foram cruzadas com endere\u00e7os de faturas e de cadastros estaduais.<\/p>\n<p>Os cidad\u00e3os que residem em \u00e1reas atingidas e que n\u00e3o foram contemplados podem fazer contato com a Receita Estadual por meio do\u00a0<a href=\"https:\/\/www.sefaz.rs.gov.br\/portal\" target=\"_blank\" rel=\"noopener\"><strong>Portal da Pessoa F\u00edsica<\/strong><\/a>, na se\u00e7\u00e3o Processos Administrativos, e solicitar a inclus\u00e3o do CPF na base de benefici\u00e1rios. Tamb\u00e9m \u00e9 poss\u00edvel pedir a an\u00e1lise de notas fiscais de compras emitidas sem o c\u00f3digo NCM ou com o c\u00f3digo incorreto. Em caso de d\u00favidas, deve-se entrar em contato com a central de atendimento pelo telefone 0800 541 2323, de segunda a sexta-feira, das 8h \u00e0s 20h, e aos s\u00e1bados, das 8h \u00e0s 14h.<\/p>\n<p>Mais detalhes sobre o\u00a0<a href=\"https:\/\/devolveicmslinhabranca.rs.gov.br\/passo-a-passo\" target=\"_blank\" rel=\"noopener\"><strong>passo a passo para o recebimento dos valores<\/strong>\u00a0<\/a>est\u00e3o dispon\u00edveis no\u00a0<a href=\"https:\/\/devolveicmslinhabranca.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\"><strong>site do Devolve ICMS Linha Branca<\/strong><\/a>, no qual tamb\u00e9m pode ser consultada uma p\u00e1gina de<a href=\"https:\/\/devolveicmslinhabranca.rs.gov.br\/duvidas-frequentes\" target=\"_blank\" rel=\"noopener\"><strong>\u00a0d\u00favidas frequentes<\/strong><\/a>.<\/p>\n<p><strong>Formas de devolu\u00e7\u00e3o<\/strong><\/p>\n<p>O valor pode ser devolvido aos cidad\u00e3os de duas formas. Uma delas \u00e9 por meio do Cart\u00e3o Cidad\u00e3o, usado por quem j\u00e1 \u00e9 integrante dos programas Devolve ICMS, Volta por Cima, Todo Jovem na Escola ou Professor do Amanh\u00e3. Nesse caso, n\u00e3o \u00e9 preciso fazer nenhuma a\u00e7\u00e3o, pois o pagamento se d\u00e1 de forma autom\u00e1tica.<\/p>\n<p>Outra parte dos benefici\u00e1rios recebe a restitui\u00e7\u00e3o por meio do programa Nota Fiscal Ga\u00facha (NFG). Nesse caso, \u00e9 preciso que a pessoa esteja cadastrada no NFG. No site ou no aplicativo, os participantes devem clicar em Devolve ICMS Linha Branca e aceitar a declara\u00e7\u00e3o de que foram afetados pelas enchentes, confirmando os dados banc\u00e1rios.<\/p>\n<p>Todas as pessoas beneficiadas que tiverem comprado eletrodom\u00e9sticos entre 1\u00ba de maio e 31 de dezembro de 2024 t\u00eam at\u00e9 30 de abril de 2025 para fazer a solicita\u00e7\u00e3o de resgate no NFG. Assim que o pedido \u00e9 feito, o valor est\u00e1 garantido. O pagamento tem prazo estimado de at\u00e9 30 dias, podendo chegar a 60 em situa\u00e7\u00f5es at\u00edpicas. O repasse pode ser feito via Pix (somente se a chave for CPF) ou via conta no Banrisul.<\/p>\n<p>A iniciativa faz parte do\u00a0<a href=\"https:\/\/planoriogrande.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\"><strong>Plano Rio Grande<\/strong><\/a>, que atua em tr\u00eas eixos de enfrentamento aos efeitos do desastre meteorol\u00f3gico: a\u00e7\u00f5es emergenciais, a\u00e7\u00f5es de reconstru\u00e7\u00e3o e Rio Grande do Sul do futuro.<\/p>\n<p><strong>Mais de R$ 30 milh\u00f5es repassados<\/strong><\/p>\n<p>Somando os seis lotes do Devolve ICMS at\u00e9 agora, a a\u00e7\u00e3o de pol\u00edtica p\u00fablica j\u00e1 disponibilizou R$ 30,67 milh\u00f5es a 122,6 mil pessoas afetadas pelo desastre meteorol\u00f3gico no Rio Grande do Sul. No total, j\u00e1 foram adquiridos 137,4 mil eletrodom\u00e9sticos.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Sefaz | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Programa Devolve ICMS Linha Branca ajuda a popula\u00e7\u00e3o afetada na reconstru\u00e7\u00e3o de seus lares O pr\u00f3ximo 31 de dezembro de 2024 \u00e9 o \u00faltimo dia para que pessoas atingidas pelas enchentes comprem eletrodom\u00e9sticos dentro do programa Devolve ICMS Linha Branca. A iniciativa da Secretaria da Fazenda (Sefaz), por meio da Receita Estadual, devolve parte do [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70750"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70750\/revisions"}],"predecessor-version":[{"id":70752,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70750\/revisions\/70752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70751"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}