{"id":70838,"date":"2025-01-03T10:34:44","date_gmt":"2025-01-03T13:34:44","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70838"},"modified":"2025-01-03T10:34:46","modified_gmt":"2025-01-03T13:34:46","slug":"com-sinais-de-recuperacao-apos-enchentes-pib-do-rs-registra-variacao-de-03-no-terceiro-trimestre-de-2024","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/com-sinais-de-recuperacao-apos-enchentes-pib-do-rs-registra-variacao-de-03-no-terceiro-trimestre-de-2024\/","title":{"rendered":"Com sinais de recupera\u00e7\u00e3o ap\u00f3s enchentes, PIB do RS registra varia\u00e7\u00e3o de -0,3% no terceiro trimestre de 2024"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Resultados foram divulgados pelo Departamento de Economia e Estat\u00edstica<\/em><\/p>\n<p>A economia do Rio Grande do Sul apresentou sinais de recupera\u00e7\u00e3o ap\u00f3s as enchentes ao registrar varia\u00e7\u00e3o de -0,3% no terceiro trimestre de 2024 na compara\u00e7\u00e3o com o segundo trimestre. Os n\u00fameros do Produto Interno Bruto (PIB) do Estado mostram ainda que,\u00a0em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2023, a alta foi de 4,1%. No Brasil, nas mesmas bases comparativas, o PIB registrou avan\u00e7o de 0,9% e 4%, respectivamente.\u00a0\u00a0<\/p>\n<p>Os resultados do PIB do RS relativos ao per\u00edodo entre julho e setembro foram divulgados nesta quinta-feira (2\/1) pelo Departamento de Economia e Estat\u00edstica (DEE), vinculado \u00e0 Secretaria de Planejamento, Governan\u00e7a e Gest\u00e3o (SPGG). No acumulado dos tr\u00eas primeiros trimestres do ano, a economia do Estado teve alta de 5,2% na compara\u00e7\u00e3o com o mesmo per\u00edodo de 2023, enquanto no Brasil o avan\u00e7o alcan\u00e7ou 3,3%. Na soma dos \u00faltimos quatro trimestres, a varia\u00e7\u00e3o no RS atingiu 3,7%, acima da registrada no pa\u00eds, que alcan\u00e7ou 3,1%.\u00a0\u00a0<\/p>\n<p>No Estado, o terceiro trimestre \u00e9 o per\u00edodo tradicionalmente com menor repercuss\u00e3o\u00a0das atividades agropecu\u00e1rias no PIB.<\/p>\n<p>\"<em>Apesar da queda na margem, causada pela retra\u00e7\u00e3o da agropecu\u00e1ria t\u00edpica do\u00a0per\u00edodo, o PIB mostrou sinais de recupera\u00e7\u00e3o ap\u00f3s os impactos mais severos das enchentes. Tanto a ind\u00fastria quanto os servi\u00e7os tiveram crescimento no terceiro trimestre em rela\u00e7\u00e3o ao segundo, com destaque para os bons resultados da ind\u00fastria de transforma\u00e7\u00e3o e do com\u00e9rcio<\/em>\u201d, destaca\u00a0o pesquisador em Economia do DEE, Martinho Lazzari.<\/p>\n<p><strong>Terceiro trimestre x\u00a0<\/strong><strong>s<\/strong><strong>egundo trimestre<\/strong><\/p>\n<p>Entre as grandes atividades da economia, a agropecu\u00e1ria recuou 30,6% no terceiro trimestre em rela\u00e7\u00e3o ao segundo trimestre, enquanto a ind\u00fastria cresceu 1,1%, e os servi\u00e7os registraram avan\u00e7o de 2,3%. Na ind\u00fastria, a alta foi puxada pelo desempenho da ind\u00fastria de transforma\u00e7\u00e3o, a com maior participa\u00e7\u00e3o no segmento, que cresceu 2%. As atividades de eletricidade e g\u00e1s, \u00e1gua, esgoto e limpeza urbana (-10,3%) e constru\u00e7\u00e3o (-0,4%) recuaram no per\u00edodo.<\/p>\n<p>Nos servi\u00e7os, segmento mais representativo na forma\u00e7\u00e3o da taxa, o com\u00e9rcio (+3,9%), os servi\u00e7os de informa\u00e7\u00e3o (2,6%) e o setor de transportes, armazenagem e correio (2,3%) foram as atividades que apresentaram as maiores altas no per\u00edodo.<\/p>\n<p><strong>2024 x 2023<\/strong><\/p>\n<p>Na compara\u00e7\u00e3o dos n\u00fameros do terceiro trimestre de 2024 com os de 2023, o PIB do RS cresceu 4,1%, com alta nos n\u00fameros da agropecu\u00e1ria (+7,9%) e dos servi\u00e7os (+4,2%), enquanto a ind\u00fastria teve recuo (-1,3%).<\/p>\n<p>A queda na atividade industrial foi puxada pelos n\u00fameros da ind\u00fastria de transforma\u00e7\u00e3o, com baixa de 2,8% no per\u00edodo. Na transforma\u00e7\u00e3o, as maiores influ\u00eancias para a queda vieram das atividades de m\u00e1quinas e equipamentos (-16,4%), bebidas (-11,4%) e celulose, papel e produtos de papel (-6,9%). Por outro lado, os avan\u00e7os mais relevantes foram registrados em m\u00f3veis (+14,9%), metalurgia (+37,9%) e ve\u00edculos automotores, reboques e carrocerias (+5,3%).<\/p>\n<p>Nos servi\u00e7os, as sete atividades pesquisadas registraram alta, com destaque para com\u00e9rcio (+8,2%), outros servi\u00e7os (5,2%) e servi\u00e7os da informa\u00e7\u00e3o (+5,1%). No importante segmento do com\u00e9rcio, os avan\u00e7os mais significativos ocorreram nas atividades de com\u00e9rcio de ve\u00edculos (+21,5%), hipermercados, supermercados, produtos aliment\u00edcios, bebidas e fumo (+9,3%) e material de constru\u00e7\u00e3o (+18,5%).\u00a0\u00a0<\/p>\n<p><strong>Acumulado de 2024\u00a0<\/strong>\u00a0<\/p>\n<p>No acumulado do ano, o avan\u00e7o de 5,2% do PIB do Estado\u00a0em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2023 foi impulsionado pelo desempenho positivo da agropecu\u00e1ria (+37,1%) e dos servi\u00e7os (+3,2%), enquanto a ind\u00fastria teve varia\u00e7\u00e3o negativa (-0,2%).<\/p>\n<ul>\n<li><a href=\"https:\/\/estado.rs.gov.br\/upload\/arquivos\/202501\/nt-dee-104-resultados-do-pib-trimestral-do-rio-grande-do-sul-3-trimestre-de-2024-1.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Nota t\u00e9cnica<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/estado.rs.gov.br\/upload\/arquivos\/202501\/pib-trimestral-rs-3-trim-2024-apresentacao.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Apresenta\u00e7\u00e3o<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/estado.rs.gov.br\/upload\/arquivos\/202501\/serie-historica-2002-2024.xlsx\" target=\"_blank\" rel=\"noopener\"><strong>S\u00e9rie hist\u00f3rica<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Vagner Benites\/Ascom SPGG | Edi\u00e7\u00e3o: Secom | Foto: Davi Besson\/SPGG<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Resultados foram divulgados pelo Departamento de Economia e Estat\u00edstica A economia do Rio Grande do Sul apresentou sinais de recupera\u00e7\u00e3o ap\u00f3s as enchentes ao registrar varia\u00e7\u00e3o de -0,3% no terceiro trimestre de 2024 na compara\u00e7\u00e3o com o segundo trimestre. Os n\u00fameros do Produto Interno Bruto (PIB) do Estado mostram ainda que,\u00a0em rela\u00e7\u00e3o ao mesmo per\u00edodo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70839,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70838"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70838\/revisions"}],"predecessor-version":[{"id":70840,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70838\/revisions\/70840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70839"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}