{"id":70875,"date":"2025-01-06T09:38:18","date_gmt":"2025-01-06T12:38:18","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70875"},"modified":"2025-01-06T09:38:19","modified_gmt":"2025-01-06T12:38:19","slug":"sicoob-maxicredito-credita-r-265-milhoes-em-juros-ao-capital-aos-associados","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/sicoob-maxicredito-credita-r-265-milhoes-em-juros-ao-capital-aos-associados\/","title":{"rendered":"Sicoob MaxiCr\u00e9dito credita R$ 26,5 milh\u00f5es em Juros ao Capital aos associados"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Valores foram pagos diretamente em Conta Capital no dia 31 de dezembro de 2024<\/em><\/p>\n<p>\u00a0<\/p>\n<p>Ser mais que uma escolha financeira \u00e9 promover um c\u00edrculo virtuoso de prosperidade. \u00c9, atrav\u00e9s de solu\u00e7\u00f5es financeiras justas e competitivas, incentivar o desenvolvimento de pessoas e comunidades e, por meio da proximidade e confian\u00e7a, ajudar a construir um futuro mais pr\u00f3spero. Com esse prop\u00f3sito, no dia 31 de dezembro de 2024, o Sicoob MaxiCr\u00e9dito fez o pagamento de mais de R$ 26,5 milh\u00f5es em Juros ao Capital dos associados.<\/p>\n<p>O valor \u00e9 referente \u00e0 remunera\u00e7\u00e3o sobre o saldo que cada cooperado possui em Conta Capital. <em>\u201cA Cota Capital \u00e9 a primeira integraliza\u00e7\u00e3o que o associado faz ao iniciar seu relacionamento com a cooperativa. Esse valor permanece na institui\u00e7\u00e3o durante todo o per\u00edodo de relacionamento cooperativa\/cooperado. E os rendimentos s\u00e3o remunerados atrav\u00e9s dos Juros ao Capital\u201d<\/em>, explica o vice-presidente do Conselho de Administra\u00e7\u00e3o do Sicoob MaxiCr\u00e9dito, Francisco Souza Leite.<\/p>\n<p>Al\u00e9m do valor integralizado no momento da associa\u00e7\u00e3o, ao longo do relacionamento com a cooperativa, o associado pode adquirir mais cotas, aumentando seu capital social e, assim, os rendimentos sobre ele.<\/p>\n<p>Francisco destaca que o montante \u00e9 um dos maiores pagos por uma cooperativa do Sistema Sicoob, e um diferencial do sistema cooperativo. <em>\u201cO associado \u00e9 a for\u00e7a transformadora que permite que a gente apoie cada vez mais os empreendedores, a realiza\u00e7\u00e3o de sonhos e o desenvolvimento das comunidades. E al\u00e9m disso, recebem parte dos resultados da cooperativa, seja por meio do Juros ao Capital ou da distribui\u00e7\u00e3o de resultado\u201d<\/em>, comenta.<\/p>\n<p><br \/><strong>Como consultar<\/strong><\/p>\n<p>Para acessar o valor destinado em Juros ao Capital basta acessar o aplicativo do Sicoob, clicando em Menu \u2013 Conta Capital \u2013 Extrato Conta Capital ou conversar diretamente com a equipe da sua ag\u00eancia.<\/p>\n<hr \/>\n<h6><strong>Assessoria de Comunica\u00e7\u00e3o - SICOOB MaxiCr\u00e9dito<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Valores foram pagos diretamente em Conta Capital no dia 31 de dezembro de 2024 \u00a0 Ser mais que uma escolha financeira \u00e9 promover um c\u00edrculo virtuoso de prosperidade. \u00c9, atrav\u00e9s de solu\u00e7\u00f5es financeiras justas e competitivas, incentivar o desenvolvimento de pessoas e comunidades e, por meio da proximidade e confian\u00e7a, ajudar a construir um futuro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70875"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70875\/revisions"}],"predecessor-version":[{"id":70877,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70875\/revisions\/70877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70876"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}