{"id":70897,"date":"2025-01-07T10:10:14","date_gmt":"2025-01-07T13:10:14","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=70897"},"modified":"2025-01-07T10:10:15","modified_gmt":"2025-01-07T13:10:15","slug":"brde-divulga-projetos-sociais-que-serao-apoiados-no-rio-grande-do-sul","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/brde-divulga-projetos-sociais-que-serao-apoiados-no-rio-grande-do-sul\/","title":{"rendered":"BRDE divulga projetos sociais que ser\u00e3o apoiados no Rio Grande do Sul"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Com prioridade para munic\u00edpios atingidos pela enchente, banco repassa mais de R$ 1,8 milh\u00e3o a entidades ga\u00fachas<\/em><\/p>\n<p>O Banco Regional de Desenvolvimento do Extremo Sul (BRDE) est\u00e1 destinando um total de R$ 1,81 milh\u00e3o para projetos que ser\u00e3o apoiados no Rio Grande do Sul atrav\u00e9s da sua pol\u00edtica de responsabilidade socioambiental. Por meio das leis de incentivo fiscal, foram selecionadas 48 iniciativas de entidades ga\u00fachas, com prioridade para os munic\u00edpios que est\u00e3o sob situa\u00e7\u00e3o de calamidade em consequ\u00eancia da enchente de maio de 2024. Os valores j\u00e1 foram repassados na v\u00e9spera do Ano Novo e beneficiam p\u00fablicos de todas as idades com a\u00e7\u00f5es de assist\u00eancia social, educa\u00e7\u00e3o, cultura e esporte.<\/p>\n<p>Parte dos valores, no entanto, j\u00e1 havia sido antecipada no m\u00eas de outubro, atrav\u00e9s de um esfor\u00e7o para auxiliar na retomada das regi\u00f5es mais afetadas pelo desastre ambiental. <em>\u201cO BRDE j\u00e1 tem uma trajet\u00f3ria em apoiar iniciativas com um olhar para as pessoas que mais precisam, mas desta vez buscamos refor\u00e7ar o esp\u00edrito de solidariedade do povo ga\u00facho\u201d<\/em>, destacou o diretor-presidente do banco, Ranolfo Vieira J\u00fanior.<\/p>\n<p>Al\u00e9m do aux\u00edlio na retomada da economia, Ranolfo observou que a reconstru\u00e7\u00e3o do Estado \u201c<em>passa igualmente pelo socorro \u00e0s institui\u00e7\u00f5es sociais que foram igualmente impactadas<\/em>\u201d.\u00a0Das propostas selecionadas no \u00e2mbito do Rio Grande do Sul, pouco mais de R$ 722 mil s\u00e3o destinados para projetos na \u00e1rea de produ\u00e7\u00e3o cultural, setor com 22 a\u00e7\u00f5es contempladas.<\/p>\n<p>Entre as iniciativas, destacam-se dois projetos que visam reconstruir as bibliotecas em escolas da rede p\u00fablica que perderam seus acervos com a invas\u00e3o das \u00e1guas. \u201c<em>Procuramos selecionar projetos que s\u00e3o grandes referenciais para os ga\u00fachos e que refor\u00e7am todo o nosso esp\u00edrito de resili\u00eancia. Importante que esses recursos dos impostos fiquem aqui e sejam aplicados em projetos que fazem a transforma\u00e7\u00e3o social acontecer\u201d<\/em>, frisou o diretor de Planejamento do BRDE, Leonardo Busatto.<\/p>\n<p><strong>Demais segmentos<\/strong><\/p>\n<p>Outras quatro cotas iguais de R$ 180 mil est\u00e3o sendo destinadas para iniciativas de cuidados com a sa\u00fade e bem-estar dos idosos, da prote\u00e7\u00e3o \u00e0s crian\u00e7as, atendimento e assist\u00eancia social e diagn\u00f3stico e tratamento do c\u00e2ncer. J\u00e1 o incentivo ao esporte ter\u00e1 cerca de R$ 366,6 mil em repasses do BRDE para um conjunto de 11 a\u00e7\u00f5es em diferentes cidades ga\u00fachas.<\/p>\n<p>As iniciativas apoiadas qualificam equipes e programa\u00e7\u00f5es de entidades que prestam atendimento a crian\u00e7as, jovens e idosos; promovem atividades de educa\u00e7\u00e3o pelo esporte e competi\u00e7\u00f5es que valorizam atletas; permitem a aquisi\u00e7\u00e3o de equipamentos para hospitais, creches e asilos; estimulam a produ\u00e7\u00e3o e a distribui\u00e7\u00e3o de livros para escolas e bibliotecas p\u00fablicas; possibilitam apresenta\u00e7\u00f5es de dan\u00e7a, m\u00fasica, artes visuais e c\u00eanicas, bem como a valoriza\u00e7\u00e3o do patrim\u00f4nio arquitet\u00f4nico e hist\u00f3rico, e ajudam a manter programa\u00e7\u00f5es anuais de institui\u00e7\u00f5es como museus, centros de cultura e orquestras, entre outras.<\/p>\n<p><strong>Regi\u00e3o Sul<\/strong><\/p>\n<p>Considerando os tr\u00eas estados do Sul do pa\u00eds, o BRDE est\u00e1 destinando um total de R$ 5,4 milh\u00f5es para 155 projetos selecionados no edital de 2024. O montante \u00e9 divido de maneira equ\u00e2nime entre o Rio Grande do Sul, Santa Catarina e Paran\u00e1. Com os valores que foram depositados nesta edi\u00e7\u00e3o, o banco j\u00e1 se aproxima dos R$ 40 milh\u00f5es em apoio atrav\u00e9s das leis de incentivos nos \u00faltimos nove anos.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.estado.rs.gov.br\/upload\/arquivos\/202501\/projetos-apoiados-2024-rio-grande-do-sul-1.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Projetos selecionados no Estado<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom BRDE | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Com prioridade para munic\u00edpios atingidos pela enchente, banco repassa mais de R$ 1,8 milh\u00e3o a entidades ga\u00fachas O Banco Regional de Desenvolvimento do Extremo Sul (BRDE) est\u00e1 destinando um total de R$ 1,81 milh\u00e3o para projetos que ser\u00e3o apoiados no Rio Grande do Sul atrav\u00e9s da sua pol\u00edtica de responsabilidade socioambiental. Por meio das leis [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":70898,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=70897"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70897\/revisions"}],"predecessor-version":[{"id":70899,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/70897\/revisions\/70899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/70898"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=70897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=70897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=70897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}