{"id":71032,"date":"2025-01-13T09:58:31","date_gmt":"2025-01-13T12:58:31","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71032"},"modified":"2025-01-13T09:58:34","modified_gmt":"2025-01-13T12:58:34","slug":"investigacao-celere-do-estado-comprova-que-mulher-envenenou-sogro-no-litoral-norte","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/investigacao-celere-do-estado-comprova-que-mulher-envenenou-sogro-no-litoral-norte\/","title":{"rendered":"Investiga\u00e7\u00e3o c\u00e9lere do Estado comprova que mulher envenenou sogro no Litoral Norte"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Caso veio \u00e0 tona ap\u00f3s tr\u00eas pessoas morrerem depois de consumir bolo de Natal em Torres, em dezembro do ano passado<\/em><\/p>\n<p>A Secretaria da Seguran\u00e7a P\u00fablica divulgou, nesta sexta-feira (10\/1), os desdobramentos da investiga\u00e7\u00e3o e da per\u00edcia sobre o caso do bolo envenenado que matou tr\u00eas pessoas em Torres, no Litoral ga\u00facho, na v\u00e9spera do Natal. A suspeita, em pris\u00e3o tempor\u00e1ria desde o \u00faltimo domingo (5\/1), ir\u00e1 responder por quatro homic\u00eddios triplamente qualificados, al\u00e9m de tr\u00eas tentativas de homic\u00eddio. O quarto caso se refere ao sogro, que, ap\u00f3s ter o corpo exumado pelo Instituto-Geral de Per\u00edcias (IGP), foi comprovado que ele ingeriu ars\u00eanio, subst\u00e2ncia letal tamb\u00e9m usada no bolo em Torres.<\/p>\n<p>O trabalho das for\u00e7as de seguran\u00e7a do Rio Grande do Sul pode ser um marco para novos protocolos de atua\u00e7\u00e3o na \u00e1rea de sa\u00fade para mortes suspeitas. O secret\u00e1rio da Seguran\u00e7a P\u00fablica, Sandro Caron, destacou o trabalho dos servidores e, tamb\u00e9m, a import\u00e2ncia de elucidar um crime desta natureza.<\/p>\n<p>\u201c<em>Crimes que ocorrem dentro do seio familiar s\u00e3o desafiadores, porque eles n\u00e3o podem ser prevenidos com policiamento, s\u00e3o crimes silenciosos. Nosso papel \u00e9 mostrar que um crime repugnante como este precisa ser elucidado, com um inqu\u00e9rito robusto que s\u00f3 a investiga\u00e7\u00e3o s\u00e9ria e a prova pericial podem trazer. Quero parabenizar todos os envolvidos neste caso que atuaram incansavelmente para encontrar provas t\u00e9cnicas e contundentes que nos fizeram chegar aos resultados que estamos apresentando<\/em>\u201d, disse.<\/p>\n<p>Com uma atua\u00e7\u00e3o r\u00e1pida e eficaz, a Pol\u00edcia Civil e o Instituto-Geral de Per\u00edcias (IGP) trabalharam dando celeridade ao caso do bolo envenenado em Torres, situa\u00e7\u00e3o que ganhou repercuss\u00e3o pela brutalidade de envenenar seis pessoas, levando tr\u00eas das v\u00edtimas \u00e0 morte, em uma trag\u00e9dia que poderia ter sido ainda maior. Ao longo da investiga\u00e7\u00e3o foi verificada que outra morte, ocorrida em setembro em Arroio do Sal, tamb\u00e9m poderia se tratar de um crime.<\/p>\n<p>Inicialmente tratada como uma morte por intoxica\u00e7\u00e3o alimentar, o corpo do sogro da suspeita presa foi exumado pelo IGP para exames laboratoriais. Por j\u00e1 ter resultados positivos para ars\u00eanio, presente na farinha, no bolo e nas v\u00edtimas do caso que ocorreu pr\u00f3ximo ao Natal, o IGP tinha um ponto de partida para os exames. O ars\u00eanio \u00e9 um metal pesado e o seu formato em veneno tem capacidade de se conectar com materiais biol\u00f3gicos como o rim, o f\u00edgado e a queratina, presente em unhas e cabelos. Com as amostras retiradas na exuma\u00e7\u00e3o, o IGP chegou rapidamente ao resultado, uma dose alt\u00edssima de ars\u00eanio tamb\u00e9m na v\u00edtima de setembro.<\/p>\n<p>Amorfo e inodoro, o ars\u00eanico se constitui de um p\u00f3 branco ou levemente acinzentado. Adquirido pela suspeita, o veneno foi dissimulado em grandes quantidades em itens de consumo para praticar os crimes: leite em p\u00f3 e farinha de trigo.<\/p>\n<p>A diretora-geral o IGP, perita Marguet Mittmann, disse que em todos os trabalhos, os n\u00edveis de ars\u00eanio localizados foram t\u00f3xicos e letais. \u201c<em>Os n\u00edveis de ars\u00eanio localizados em todas as amostras da exuma\u00e7\u00e3o deram positivo no segundo n\u00edvel mais alto localizados em compara\u00e7\u00e3o com todas as v\u00edtimas. Este resultado n\u00e3o deixa d\u00favidas da inten\u00e7\u00e3o de causar a morte e elimina qualquer possibilidade de contamina\u00e7\u00e3o acidental. Assim, como nas v\u00edtimas examinadas ap\u00f3s a morte em Torres, constatamos que a v\u00edtima exumada teve como causa da morte envenenamento por ars\u00eanio.\u201d<\/em><\/p>\n<p>Os tr\u00eas homic\u00eddios ent\u00e3o passaram a ser quatro mortes intencionais e trouxeram um novo alerta as autoridades: a facilidade com que a suspeita teve acesso ao ars\u00eanio, comprando pela internet e recebendo pelo servi\u00e7o dos Correios, e tamb\u00e9m a caracter\u00edstica acidental da morte por intoxica\u00e7\u00e3o alimentar. A delegada Regional de Cap\u00e3o da Canoa, Sabrina Deffente, ressaltou que a investiga\u00e7\u00e3o pode ser um marco na atua\u00e7\u00e3o dos profissionais de sa\u00fade em casos de morte suspeita.<\/p>\n<p><em>\u201cVamos ampliar essa integra\u00e7\u00e3o com a \u00e1rea da sa\u00fade para estabelecer novos protocolos em casos de intoxica\u00e7\u00e3o alimentar, para que a Pol\u00edcia Civil investigue casos como este. Inclusive, durante as investiga\u00e7\u00f5es descobrimos que a suspeita tentou for\u00e7ar que a fam\u00edlia optasse pela crema\u00e7\u00e3o do sogro, para apagar os vest\u00edgios do crime, mas ela n\u00e3o conseguiu uma assinatura m\u00e9dica necess\u00e1ria para casos de crema\u00e7\u00e3o<\/em>\u201d, disse.<\/p>\n<p>A celeridade dos trabalhos foi acompanhada de muito cuidado para garantir os direitos humanos e a seguran\u00e7a jur\u00eddica do inqu\u00e9rito. A prova testemunhal j\u00e1 garantia a pris\u00e3o da suspeita, mas o delegado Marcos Veloso, que investiga o caso, foi cauteloso e, certo das provas que j\u00e1 tinham, aguardou a confirma\u00e7\u00e3o da prova pericial.<\/p>\n<p><em>\u201cFizemos a revoga\u00e7\u00e3o de um primeiro pedido de pris\u00e3o, aguardando o momento certo de fazer um novo pedido, com mais elementos t\u00e9cnicos e incontest\u00e1veis. Iremos permanecer nas investiga\u00e7\u00f5es, para finalizar um inqu\u00e9rito perfeito e n\u00e3o descartamos, inclusive, que ela tenha cometido outros crimes. Posso dizer que se trata de uma pessoa fria, que premeditou o crime e tinha respostas prontas para tentar desviar as suspeitas<\/em>\u201d, afirmou o delegado.<\/p>\n<p>Com as provas que indicam que a suspeita estava afastada do n\u00facleo familiar e se aproximou para poder executar o plano de envenenamento, o crime tem o acr\u00e9scimo de uma qualificadora, passando a ser um triplo homic\u00eddio triplamente qualificado, uma tripla tentativa de homic\u00eddio, al\u00e9m do homic\u00eddio triplamente qualificado do sogro, ocorrida em setembro, em Arroio do Sal. As qualificadoras deste crime s\u00e3o: motivo f\u00fatil, dissimula\u00e7\u00e3o e emprego de veneno.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Lurdinha Matos\/SSP | Edi\u00e7\u00e3o: \u00c9der Kurz\/Secom | Foto: Calvin Neruam\/SSP<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Caso veio \u00e0 tona ap\u00f3s tr\u00eas pessoas morrerem depois de consumir bolo de Natal em Torres, em dezembro do ano passado A Secretaria da Seguran\u00e7a P\u00fablica divulgou, nesta sexta-feira (10\/1), os desdobramentos da investiga\u00e7\u00e3o e da per\u00edcia sobre o caso do bolo envenenado que matou tr\u00eas pessoas em Torres, no Litoral ga\u00facho, na v\u00e9spera do [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71033,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71032"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71032\/revisions"}],"predecessor-version":[{"id":71034,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71032\/revisions\/71034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71033"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}