{"id":71042,"date":"2025-01-13T10:41:07","date_gmt":"2025-01-13T13:41:07","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71042"},"modified":"2025-01-13T10:41:08","modified_gmt":"2025-01-13T13:41:08","slug":"programa-do-estado-rede-praia-acessivel-resgata-alegria-e-autoestima-de-pessoas-com-deficiencia-ou-mobilidade-reduzidaprograma-do-estado-rede-praia-acessivel-resgata-alegria-e-autoestima-de-pessoas","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/programa-do-estado-rede-praia-acessivel-resgata-alegria-e-autoestima-de-pessoas-com-deficiencia-ou-mobilidade-reduzidaprograma-do-estado-rede-praia-acessivel-resgata-alegria-e-autoestima-de-pessoas\/","title":{"rendered":"Programa do Estado, Rede Praia Acess\u00edvel resgata alegria e autoestima de pessoas com defici\u00eancia ou mobilidade reduzidaPrograma do Estado, Rede Praia Acess\u00edvel resgata alegria e autoestima de pessoas com defici\u00eancia ou mobilidade reduzida"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Cidad\u00e3os como Ad\u00e3o Paulo Jesus Jr. s\u00e3o beneficiados com a iniciativa, que faz parte da Opera\u00e7\u00e3o Ver\u00e3o Total<\/em><\/p>\n<p>Ad\u00e3o Paulo Jesus Jr. sempre foi um apaixonado pelo mar. Natural de Porto Alegre, ele viveu boa parte da vida tendo o oceano como palco de suas aventuras. No entanto, h\u00e1 cerca de 30 anos, sua hist\u00f3ria ganhou um novo rumo. Durante um dia de surfe na plataforma de Xangri-l\u00e1, no Litoral Norte ga\u00facho, uma onda forte o derrubou e a prancha atingiu sua cabe\u00e7a. O acidente resultou em um AVC, que paralisou o lado esquerdo de seu corpo, e ele ficou em uma cadeira de rodas.<\/p>\n<p>Para algu\u00e9m que amava o mar, o acidente foi devastador. \"<em>Eu s\u00f3 podia observ\u00e1-lo [mar] de longe, sentado na beira da praia. Era como ver um amigo querido que eu n\u00e3o podia mais abra\u00e7ar\"<\/em>, lembra Ad\u00e3o, que nunca desistiu de tomar um banho de mar novamente. <em>\"A minha reabilita\u00e7\u00e3o foi longa e desafiadora, mas nunca desisti. Com muito esfor\u00e7o, troquei a cadeira de rodas pela bengala. Ainda assim, o sonho de voltar ao mar parecia distante.\"<\/em><\/p>\n<p>Essa realidade mudou em 2012, com o lan\u00e7amento do programa Rede Praia Acess\u00edvel, do governo do Estado. Ao participar do banho assistido pela primeira vez, Ad\u00e3o descreve a experi\u00eancia como um renascimento: \"<em>Quando entrei na \u00e1gua, senti aquela adrenalina de novo, como nos velhos tempos de surfe. A energia do mar, o movimento da \u00e1gua... N\u00e3o h\u00e1 palavras para descrever<\/em>\", diz ele, ressaltando que cada banho \u00e9 \u00fanico, uma nova chance de se reconectar com o oceano e com sua ess\u00eancia.<\/p>\n<p>Al\u00e9m do contato com o mar, Ad\u00e3o acredita que o programa tem um impacto profundo na sa\u00fade emocional e psicol\u00f3gica dos participantes. \"<em>Muitos acabam se isolando, o que pode levar \u00e0 depress\u00e3o. O Rede Praia Acess\u00edvel \u00e9 muito mais do que um banho: \u00e9 inclus\u00e3o de verdade. Mostra que todos t\u00eam direito \u00e0 alegria, ao lazer e a fazer parte da vida na praia. Nem tenho palavras para descrever tamanha a import\u00e2ncia do que para muitos parece ser s\u00f3 um banho numa cadeira anf\u00edbia\u201d<\/em>, conta.<\/p>\n<p>Questionado sobre ter medo da experi\u00eancia, ele seriamente diz: <em>\"Nunca me senti desafiado como quando surfava, muito bom me sentir assim de novo. Al\u00e9m disso,\u00a0a equipe que realiza o atendimento \u00e9 qualificada, atenciosa e cuidadosa. Explicam cada passo e garantem que tudo seja seguro. N\u00e3o tem perigo, s\u00f3 alegria<\/em>\", frisa.<\/p>\n<p>Morador de Xangri-l\u00e1 h\u00e1 10 anos, Ad\u00e3o espera que num futuro pr\u00f3ximo todos os locais sejam acess\u00edveis, possibilitando maior inclus\u00e3o. <em>\u201cHoje eu sinto que estamos mais pr\u00f3ximos deste caminho, vejo as pessoas mais solicitas com quem tem mobilidade reduzida ou \u00e9 PcD, vejo mais investimentos em acessibilidade apesar de ainda precisarmos muito mais. Pode me chamar de sonhador, mas eu sempre busco as autoridades e falo o que precisaria mudar para o local p\u00fablico e at\u00e9 privado ser acess\u00edvel.... Pois eu tenho esperan\u00e7a de um mundo onde todos somos iguais e temos as mesmas oportunidades<\/em>\", destaca ele com a voz serena.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71045 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/41-400x267.jpg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/41-400x267.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/41-768x512.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/41-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/41.jpg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>Ao encerrar, Ad\u00e3o deixa um recado para outras pessoas com defici\u00eancia ou mobilidade reduzida: \"<em>Superem seus medos e venham. O mar \u00e9 para todos. Voc\u00eas v\u00e3o sentir uma alegria que n\u00e3o cabe no peito\"<\/em>, conclui.<\/p>\n<p><strong>Entenda o programa<\/strong><\/p>\n<p>Coordenado pela Faders Acessibilidade e Inclus\u00e3o, o Rede Praia Acess\u00edvel \u00e9 um marco na inclus\u00e3o social do ver\u00e3o ga\u00facho. Parte da Opera\u00e7\u00e3o Ver\u00e3o Total, do governo do Estado, o programa oferece banhos assistidos para pessoas com defici\u00eancia ou mobilidade reduzida em 44 guaritas de 34 munic\u00edpios, abrangendo praias, piscinas, balne\u00e1rios fluviais e lagunares.<\/p>\n<p>O servi\u00e7o utiliza cadeiras anf\u00edbias que garantem conforto e seguran\u00e7a, e \u00e9 realizado desde o ano 2012 em parceria com as prefeituras ga\u00fachas. No ano de 2024 foi poss\u00edvel ampliar o programa com o refor\u00e7o do Corpo de Bombeiros Militar do Rio Grande do Sul.<\/p>\n<p>Desde ent\u00e3o, os banhos s\u00e3o realizados por guarda-vidas treinados pela equipe da Faders e funcion\u00e1rios da Funda\u00e7\u00e3o. Nesta temporada, a institui\u00e7\u00e3o alcan\u00e7ou a meta de dobrar o n\u00famero de guaritas acess\u00edveis, assegurando que mais pessoas possam desfrutar de um ver\u00e3o inclusivo.<\/p>\n<p><strong>Guaritas acess\u00edveis:<\/strong>\u00a0<\/p>\n<ul>\n<li>Litoral Norte:<br \/>Torres (Guaritas 07 e 03)<br \/>Balne\u00e1rio Atl\u00e2ntico (Guarita 26)<br \/>Rondinha (Guarita 28)<br \/>Areias Brancas (Guarita 34)<br \/>Arroio do Sal (Guarita 38)<br \/>Balne\u00e1rio Figueirinha (Guarita 42)<br \/>Balne\u00e1rio Santa Rita (Guarita 49)<br \/>Curumin (Guarita 51)<br \/>Arroio Teixeira (Guarita 56)<br \/>Cap\u00e3o Novo (Guarita 61)<br \/>Ara\u00e7\u00e1 (Guarita 69)<br \/>Cap\u00e3o da Canoa (Guarita 76)<br \/>Atl\u00e2ntida (Guarita 84)<br \/>Xangri-l\u00e1 (Guarita 92)<br \/>Atl\u00e2ntida Sul (Guarita 108)<br \/>Imara (Guarita 111)<br \/>Mariluz (Guarita 123)<br \/>Presidente ( Guarita 127)<br \/>Imb\u00e9 Centro (Guarita 129)<br \/>Imb\u00e9 Central (Guarita 133)<br \/>Tramanda\u00ed (Guarita 147)<br \/>Tramanda\u00ed Sul (Guarita 154)<br \/>Nova Tramanda\u00ed (Guarita 159)<br \/>Salinas (Guarita 174)<br \/>Cidreira (Guaritas 180 e 184)<br \/>Costa d Sol (Guarita 192)<br \/>Balne\u00e1rio Pinhal (Guarita 199)<br \/>Magist\u00e9rio (Guarita 209)<br \/>Quint\u00e3o (Guarita 215)<br \/>Mostardas (Guarita 227)<br \/><br \/><\/li>\n<li>Litoral Sul:<br \/>Cassino - Rio Grande (Guaritas 04,10,16)<br \/>Hermenegildo \u2013 Santa Vit\u00f3ria do Palmar (Guarita 23)<br \/><br \/><\/li>\n<li>\u00c1guas internas:<br \/>Arambar\u00e9<br \/>Barra do Ribeiro<br \/>Cristal<br \/>Lagoa Fortalza (Cidreira)<br \/>Lagoa dos Barros ( Santo Ant\u00f4nio da Patrulha)<br \/>Lami (Porto Alegre)<br \/>Parque N\u00e1utico (Cap\u00e3o da Canoa)<br \/>S\u00e3o Louren\u00e7o do Sul<\/li>\n<\/ul>\n<p><strong>Mais inclus\u00e3o, mais ver\u00e3o<\/strong><\/p>\n<p>O presidente da Faders, Marco Ant\u00f4nio Lang, afirma que o Rede Praia Acess\u00edvel \u00e9 mais do que um programa. \u201c<em>\u00c9 uma ponte para a inclus\u00e3o e a dignidade. Nossa meta era dobrar o n\u00famero de guaritas acess\u00edveis e conseguimos, j\u00e1 ultrapassamos... No domingo, com a inaugura\u00e7\u00e3o da Guarita de Itapu\u00e3, em Viam\u00e3o, teremos 45 em funcionamento. Isso mostra que estamos no caminho certo para um ver\u00e3o mais acess\u00edvel para todos<\/em>\", afirma.<\/p>\n<p>Para pessoas como Ad\u00e3o, o Rede Praia Acess\u00edvel representa uma segunda chance de se conectar com o mar e com a pr\u00f3pria ess\u00eancia. Para todos, \u00e9 uma prova de que a inclus\u00e3o transforma realidades e cria um mundo onde todos podem compartilhar da mesma alegria.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Bethania Haas Loblein\/Ascom Faders | Edi\u00e7\u00e3o: \u00c9der Kurz\/Secom | Fotos: Mauro Nascimento\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cidad\u00e3os como Ad\u00e3o Paulo Jesus Jr. s\u00e3o beneficiados com a iniciativa, que faz parte da Opera\u00e7\u00e3o Ver\u00e3o Total Ad\u00e3o Paulo Jesus Jr. sempre foi um apaixonado pelo mar. Natural de Porto Alegre, ele viveu boa parte da vida tendo o oceano como palco de suas aventuras. No entanto, h\u00e1 cerca de 30 anos, sua hist\u00f3ria [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71043,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71042"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71042\/revisions"}],"predecessor-version":[{"id":71046,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71042\/revisions\/71046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71043"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}