{"id":71103,"date":"2025-01-15T19:47:27","date_gmt":"2025-01-15T22:47:27","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71103"},"modified":"2025-01-15T19:47:28","modified_gmt":"2025-01-15T22:47:28","slug":"azeite-gaucho-com-selo-premium-do-governo-do-estado-esta-entre-os-melhores-do-mundo","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/azeite-gaucho-com-selo-premium-do-governo-do-estado-esta-entre-os-melhores-do-mundo\/","title":{"rendered":"Azeite ga\u00facho com selo premium do governo do Estado est\u00e1 entre os melhores do mundo"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Est\u00e2ncia das Oliveiras e outros produtores se destacam no EVOO World Ranking, classifica\u00e7\u00e3o global de azeites de oliva<\/em><\/p>\n<p>Certificado com o selo do programa\u00a0<strong><a href=\"https:\/\/sict.rs.gov.br\/produtos-premium\" target=\"_blank\" rel=\"noopener\">Produtos Premium<\/a><\/strong>, da Secretaria de Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia (Sict), o azeite produzido pela Est\u00e2ncia das Oliveiras, de Viam\u00e3o, foi reconhecido no\u00a0<strong><a href=\"https:\/\/evooworldranking.org\/_EN\/index.php\" target=\"_blank\" rel=\"noopener\">EVOO World Ranking<\/a><\/strong>, ranking global dos azeites de oliva extravirgem, consolidando-se entre os melhores do mundo.<\/p>\n<p>A conquista refor\u00e7a a qualidade e a excel\u00eancia dos produtos premium produzidos no Rio Grande do Sul, destacando a for\u00e7a do setor no cen\u00e1rio nacional e internacional.<\/p>\n<p>Para a secret\u00e1ria de Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia, Simone St\u00fclp, o reconhecimento reflete o impacto do programa Produtos Premium, que promove a valoriza\u00e7\u00e3o e proje\u00e7\u00e3o de itens diferenciados.<\/p>\n<p>\"<em>O programa \u00e9 fundamental para que os produtos ganhem destaque n\u00e3o s\u00f3 no Brasil, mas tamb\u00e9m no mercado global. \u00c9 uma prova de que investir em qualidade e inova\u00e7\u00e3o abre portas para novas oportunidades,\"<\/em> afirmou a titular da Sict.<\/p>\n<p>A Est\u00e2ncia das Oliveiras, localizada em um dos principais polos de olivicultura do Estado, ficou na quinta posi\u00e7\u00e3o entre os fabricantes de azeite de oliva mais premiados do mundo em 2024.<\/p>\n<p>As t\u00e9cnicas adotadas no local garantem a pureza e o sabor dos produtos, elevando-os \u00e0 categoria de refer\u00eancia no mercado.\u00a0Esse reconhecimento \u00e9 resultado de um trabalho constante para aliar tradi\u00e7\u00e3o e inova\u00e7\u00e3o na produ\u00e7\u00e3o de azeites de alta qualidade.<\/p>\n<p>O s\u00f3cio-diretor da Est\u00e2ncia das Oliveiras, Rafael Goelzer, ressaltou a import\u00e2ncia das caracter\u00edsticas do produto para receber as premia\u00e7\u00f5es.<\/p>\n<p>\u201c<em>A acidez \u00e9 importante, mas o que realmente diferencia um azeite extravirgem de alt\u00edssima qualidade s\u00e3o as notas de sabor e a complexidade que ele atinge com zero defeito. O azeite n\u00e3o pode apresentar defeitos olfativos ou gustativos e, al\u00e9m disso, precisa amplificar as notas de sabor. Nossos azeites chegam a atingir at\u00e9 12 notas de sabor\u201d<\/em>, constatou.<\/p>\n<p><strong>Selo do Estado serve como balizador para consumidores brasileiros<\/strong><\/p>\n<p><em>\u201cO selo, concedido pelo governo do Estado, \u00e9 uma grande iniciativa, que trabalha com os mais altos n\u00edveis de crit\u00e9rios de avalia\u00e7\u00e3o, os mesmos adotados nos grandes concursos mundiais. Isso serve como um balizador para os consumidores brasileiros<\/em>\u201d, complementou Goelzer.<\/p>\n<p>Conforme o s\u00f3cio-diretor da Est\u00e2ncia das Oliveiras, 2025 promete ser um ano ainda melhor que 2024 em termos de produtividade no Rio Grande do Sul, mantendo o mais importante, que \u00e9 a qualidade dos azeites.<\/p>\n<p><em>\u201cAl\u00e9m disso, estamos entusiasmados com a abertura das a\u00e7\u00f5es de olivoturismo, que incluir\u00e3o degusta\u00e7\u00f5es orientadas, almo\u00e7os tem\u00e1ticos, visitas aos olivais e ao lagar, proporcionando uma experi\u00eancia \u00fanica para quem deseja conhecer mais sobre a produ\u00e7\u00e3o e a excel\u00eancia dos nossos produtos<\/em>\", disse.<\/p>\n<p>A Prosperato (Ca\u00e7apava do Sul), a Fazendas do Azeite Sabi\u00e1 (Encruzilhada do Sul), a Al-Zait &amp; Co (Ros\u00e1rio do Sul) e a Agroturismo Recanto Maestro (Restinga Seca) tamb\u00e9m receberam reconhecimento internacional pelo trabalho desenvolvido na \u00e1rea.<\/p>\n<p><strong>Programa Produtos Premium<\/strong><\/p>\n<p>O programa Produtos Premium busca fomentar a competitividade dos produtos ga\u00fachos de excel\u00eancia, conectando produtores ao mercado e promovendo selos de qualidade que atestam a superioridade das marcas. Atualmente, h\u00e1 quatro selos:\u00a0<strong><a href=\"https:\/\/sict.rs.gov.br\/azeite-premium\" target=\"_blank\" rel=\"noopener\">azeite de oliva premium<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/sict.rs.gov.br\/carne-premium\" target=\"_blank\" rel=\"noopener\">carne premium<\/a><\/strong>,\u00a0<strong><a href=\"https:\/\/sict.rs.gov.br\/cordeiro-premium\" target=\"_blank\" rel=\"noopener\">cordeiro premium<\/a><\/strong>\u00a0e\u00a0<strong><a href=\"https:\/\/sict.rs.gov.br\/cachaca-premium\" target=\"_blank\" rel=\"noopener\">cacha\u00e7a premium<\/a><\/strong>.<br \/><br \/>O selo de reconhecimento do azeite de oliva extravirgem como Produto Premium \u2013 Origem e Qualidade RS \u00e9 resultado de uma parceria entre a Sict e o Instituto Brasileiro de Olivicultura (Ibraoliva).<\/p>\n<p>Assim como nas edi\u00e7\u00f5es anteriores, os azeites da safra 2024 que receberam o selo da Sict passaram por crit\u00e9rios rigorosos de comprova\u00e7\u00e3o de proced\u00eancia e qualidade, que inclu\u00edram an\u00e1lises f\u00edsico-qu\u00edmicas, sensoriais e documental.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Bernardo Zamperetti\/Ascom Sict | Edi\u00e7\u00e3o: Secom | Foto: Divulga\u00e7\u00e3o Sict<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Est\u00e2ncia das Oliveiras e outros produtores se destacam no EVOO World Ranking, classifica\u00e7\u00e3o global de azeites de oliva Certificado com o selo do programa\u00a0Produtos Premium, da Secretaria de Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia (Sict), o azeite produzido pela Est\u00e2ncia das Oliveiras, de Viam\u00e3o, foi reconhecido no\u00a0EVOO World Ranking, ranking global dos azeites de oliva extravirgem, consolidando-se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71103"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71103\/revisions"}],"predecessor-version":[{"id":71105,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71103\/revisions\/71105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71104"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}