{"id":71137,"date":"2025-01-16T13:23:53","date_gmt":"2025-01-16T16:23:53","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71137"},"modified":"2025-01-16T13:23:54","modified_gmt":"2025-01-16T16:23:54","slug":"ano-internacional-das-cooperativas-inspira-novos-projetos-da-sicredi-caminho-das-aguas","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/ano-internacional-das-cooperativas-inspira-novos-projetos-da-sicredi-caminho-das-aguas\/","title":{"rendered":"Ano Internacional das Cooperativas inspira novos projetos da Sicredi Caminho das \u00c1guas"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Programas sociais, educa\u00e7\u00e3o financeira e engajamento comunit\u00e1rio s\u00e3o prioridades para 2025<\/em><\/p>\n<p>\u00a0<\/p>\n<p>A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) declarou 2025 como o Ano Internacional das Cooperativas, com o tema \"Cooperativas Constroem um Mundo Melhor\". A Sicredi Caminho das \u00c1guas, institui\u00e7\u00e3o financeira cooperativa com mais de 100 anos de hist\u00f3ria, v\u00ea o reconhecimento como um marco que refor\u00e7a a relev\u00e2ncia do cooperativismo para o desenvolvimento econ\u00f4mico, social e sustent\u00e1vel das comunidades.<\/p>\n<p>De acordo com Francisco Ferreira, vice-presidente do Conselho de Administra\u00e7\u00e3o da Sicredi Caminho das \u00c1guas, o reconhecimento da ONU reflete a ess\u00eancia do cooperativismo, que une pessoas em torno de valores como coopera\u00e7\u00e3o, solidariedade e democracia. <em>\"Este an\u00fancio valida a contribui\u00e7\u00e3o das cooperativas para o fortalecimento das comunidades e nos incentiva a ampliar iniciativas de impacto positivo, local e globalmente\"<\/em>, destaca.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Iniciativas para 2025<\/strong><\/p>\n<p>Para celebrar o Ano Internacional das Cooperativas, a Sicredi Caminho das \u00c1guas ampliar\u00e1 projetos j\u00e1 existentes e lan\u00e7ar\u00e1 novas a\u00e7\u00f5es alinhadas ao prop\u00f3sito global. Entre os destaques est\u00e3o o Memorial de Resgate da Hist\u00f3ria, que preservar\u00e1 e celebrar\u00e1 a trajet\u00f3ria cooperativista; a ExpoCoop, uma exposi\u00e7\u00e3o com pain\u00e9is e eventos tem\u00e1ticos sobre cooperativismo e a Incubadora de Cooperativas, em parceria com as Faculdades Integradas de Taquara (Faccat), que apoiar\u00e1 a cria\u00e7\u00e3o e o fortalecimento de novas cooperativas. Essas iniciativas se somam a programas j\u00e1 consolidados, como o Bem-estar Financeiro, a inclus\u00e3o digital, a capacita\u00e7\u00e3o de associados e a sustentabilidade ambiental, todos voltados para as demandas das comunidades locais.<\/p>\n<p>A atua\u00e7\u00e3o da Sicredi Caminho das \u00c1guas tem contribu\u00eddo para a redu\u00e7\u00e3o das desigualdades e o fortalecimento econ\u00f4mico. Conforme Ferreira, programas como cooperativas escolares, financiamento a pequenos agricultores e apoio a empreendedores locais criam oportunidades para o desenvolvimento sustent\u00e1vel. Em parceria com ONGs e entidades, a cooperativa tamb\u00e9m desenvolve projetos sociais que transformam realidades por meio da colabora\u00e7\u00e3o.<\/p>\n<p>Para aproximar os princ\u00edpios do cooperativismo das comunidades, a Sicredi Caminho das \u00c1guas realiza encontros com associados, workshops de capacita\u00e7\u00e3o e assembleias de presta\u00e7\u00e3o de contas.<em> \"Contamos ainda com o suporte de 180 coordenadores de n\u00facleo, que garantem proximidade e representatividade no dia a dia\",<\/em> explica o vice-presidente.<\/p>\n<p>Entre os planos para engajar associados, colaboradores e parceiros em 2025 est\u00e3o uma campanha especial sobre o cooperativismo, o evento ExpoCoop e o fortalecimento de parcerias estrat\u00e9gicas. Destaques incluem a expans\u00e3o das cooperativas escolares e o lan\u00e7amento de novos projetos como a Incubadora de Cooperativas.<\/p>\n<hr \/>\n<h6><strong>Sublinha! Comunica\u00e7\u00e3o<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Programas sociais, educa\u00e7\u00e3o financeira e engajamento comunit\u00e1rio s\u00e3o prioridades para 2025 \u00a0 A Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) declarou 2025 como o Ano Internacional das Cooperativas, com o tema \"Cooperativas Constroem um Mundo Melhor\". A Sicredi Caminho das \u00c1guas, institui\u00e7\u00e3o financeira cooperativa com mais de 100 anos de hist\u00f3ria, v\u00ea o reconhecimento como um marco [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71137"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71137\/revisions"}],"predecessor-version":[{"id":71139,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71137\/revisions\/71139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71138"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}