{"id":71239,"date":"2025-01-21T14:16:23","date_gmt":"2025-01-21T17:16:23","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71239"},"modified":"2025-01-21T14:16:25","modified_gmt":"2025-01-21T17:16:25","slug":"governador-anuncia-investimento-de-r-12-bilhao-para-reconstrucao-de-estradas-e-pontes","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governador-anuncia-investimento-de-r-12-bilhao-para-reconstrucao-de-estradas-e-pontes\/","title":{"rendered":"Governador anuncia investimento de R$ 1,2 bilh\u00e3o para reconstru\u00e7\u00e3o de estradas e pontes"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Foram assinados contratos que envolvem tr\u00eas pontes e 15 lotes de rodovias em diversas regi\u00f5es do Estado<\/em><\/p>\n<p>O governador Eduardo Leite anunciou, nesta segunda-feira (20\/1), o investimento de R$ 1,2 bilh\u00e3o em obras de resili\u00eancia clim\u00e1tica em estradas e pontes do Rio Grande do Sul afetadas pelas enchentes de 2024. Em solenidade no Pal\u00e1cio Piratini, Leite e o secret\u00e1rio de Log\u00edstica e Transportes, Juvir Costella, assinaram contratos para tr\u00eas pontes e 15 lotes que incluem 11 rodovias em diversas regi\u00f5es do Estado.<\/p>\n<p>O governador explicou que os investimentos anunciados contemplam obras em locais que apresentavam risco, elencados a partir de um levantamento t\u00e9cnico. <em>\u201c\u00c9 um conjunto de obras que inequivocamente merecia um tratamento diferenciado para uma contrata\u00e7\u00e3o emergencial, mantendo todo o rigor t\u00e9cnico. O Departamento Aut\u00f4nomo de Estradas de Rodagem e toda a estrutura do governo v\u00e3o acompanhar intensamente o processo para que os prazos sejam cumpridos. Assim, poderemos restabelecer a normalidade e tamb\u00e9m dar resili\u00eancia para as estradas. N\u00e3o \u00e9 s\u00f3 sobre retomar a rodovia ou a ponte, \u00e9 sobre garantir que essas estruturas sejam capazes de suportar novos eventos clim\u00e1ticos<\/em>\u201d, afirmou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71241 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/51-1-400x267.jpeg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/51-1-400x267.jpeg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/51-1-768x512.jpeg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/51-1-600x400.jpeg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/51-1.jpeg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A iniciativa integra o\u00a0<a href=\"https:\/\/planoriogrande.rs.gov.br\/inicial\" target=\"_blank\" rel=\"noopener\"><strong>Plano Rio Grande<\/strong><\/a>, o programa de reconstru\u00e7\u00e3o, adapta\u00e7\u00e3o e resili\u00eancia clim\u00e1tica do Estado lan\u00e7ado em 2024, que visa planejar, coordenar e executar a\u00e7\u00f5es para enfrentar as consequ\u00eancias sociais, econ\u00f4micas e ambientais da enchente hist\u00f3rica.<\/p>\n<p>Do total aportado, R$ 1,18 bilh\u00e3o ser\u00e1 investido em rodovias e R$ 65,6 milh\u00f5es em pontes. A categoriza\u00e7\u00e3o das estradas e pontes afetadas foi baseada em sete crit\u00e9rios: situa\u00e7\u00e3o da rodovia, tempo gasto a mais em deslocamentos, quantidade de afetados, impactos na economia local, na sa\u00fade e na mobilidade urbana e volume de circula\u00e7\u00e3o de ve\u00edculos.<\/p>\n<p>Todas as obras contemplam estudos do Instituto de Pesquisas Hidr\u00e1ulicas (IPH), da Universidade Federal do Rio Grande do Sul (UFRGS), considerando proje\u00e7\u00f5es de mudan\u00e7as clim\u00e1ticas e riscos associados a eventos extremos como o ocorrido em 2024.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-71242 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/52-400x267.jpeg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/52-400x267.jpeg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/52-768x512.jpeg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/52-600x400.jpeg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/52.jpeg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>O secret\u00e1rio de Log\u00edstica e Transportes, Juvir Costella, destacou o an\u00fancio como um marco para a reconstru\u00e7\u00e3o do Estado.<em> \u201cEste \u00e9 um momento em que conseguimos devolver ao povo ga\u00facho aquilo que lhe pertence, que \u00e9 o direito de recome\u00e7ar a partir da reconstru\u00e7\u00e3o de estradas, de pontes e de um Rio Grande ainda mais forte e resiliente\u201d<\/em>, enfatizou.<\/p>\n<h4><strong>Pontes e rodovias que receber\u00e3o investimento<\/strong><\/h4>\n<p><strong>Lotes de rodovias<\/strong><\/p>\n<p>1. ERS-332 - Encantado a Anta Gorda<\/p>\n<p>2. ERS-332 - Anta Gorda a Soledade<\/p>\n<p>3. ERS-431 - Bento Gon\u00e7alves a Santa B\u00e1rbara (S\u00e3o Valentim do Sul)<\/p>\n<p>4. ERS-444 - Bento Gon\u00e7alves\/Monte Belo do Sul a Santa Tereza<\/p>\n<p>5. ERS-448 - Nova Roma do Sul ao Rio das Antas<\/p>\n<p>6. ERS-448 - Rio das Antas a Farroupilha<\/p>\n<p>7. ERS-452 - Bom Princ\u00edpio (Entr. ERS-122) a Caxias do Sul (Entr. BR-116)<\/p>\n<p>8. VRS-826 - Feliz - Alto Feliz - Farroupilha (Entr. ERS-122)<\/p>\n<p>9. ERS-129 - Estrela a Roca Sales<\/p>\n<p>10. ERS-149 - Entr. RSC-287 (p\/ Santa Maria) a Nova Palma<\/p>\n<p>11. ERS-348 - Dona Francisca a Agudo<\/p>\n<p>12. ERS-348 - Entr. ERS-149 (S\u00e3o Jo\u00e3o do Pol\u00easine) a Dona Francisca<\/p>\n<p>13. ERS-437 - Vila Flores ao km 9+200<\/p>\n<p>14. ERS-437 - Vila Flores a Ant\u00f4nio Prado<\/p>\n<p>15. ERS-640 - S\u00e3o Vicente do Sul a Ros\u00e1rio do Sul<\/p>\n<p><strong>Pontes<\/strong><\/p>\n<p>1. Ponte de Vista Alegre do Prata - ERS-441<\/p>\n<p>2. Ponte de Faxinal do Soturno - km 35 ERS-348<\/p>\n<p>3. Ponte do Arroio Capivari (Alegrete) - ERS-507<\/p>\n<p>4. Ponte de Feliz -VRS-843 (j\u00e1 anunciada, em fase de elabora\u00e7\u00e3o de projeto)<\/p>\n<p>5. Ponte de Itati - ERS-417 (j\u00e1 anunciada, em fase de elabora\u00e7\u00e3o de projeto)<\/p>\n<p>6. Ponte de Sinimbu - RSC-471 (j\u00e1 anunciada, em fase de elabora\u00e7\u00e3o de projeto)<\/p>\n<ul>\n<li><a href=\"https:\/\/estado.rs.gov.br\/upload\/arquivos\/202501\/2025-01-20-govrs-daer-obras-resiliencia-v5.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Apresenta\u00e7\u00e3o - Obras de resili\u00eancia clim\u00e1tica em rodovias e pontes<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom Selt e Tham\u00edris Mondin\/Secom | Edi\u00e7\u00e3o: Camila Cargnelutti\/Secom | Fotos: Maur\u00edcio Tonetto\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Foram assinados contratos que envolvem tr\u00eas pontes e 15 lotes de rodovias em diversas regi\u00f5es do Estado O governador Eduardo Leite anunciou, nesta segunda-feira (20\/1), o investimento de R$ 1,2 bilh\u00e3o em obras de resili\u00eancia clim\u00e1tica em estradas e pontes do Rio Grande do Sul afetadas pelas enchentes de 2024. Em solenidade no Pal\u00e1cio Piratini, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71239"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71239\/revisions"}],"predecessor-version":[{"id":71243,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71239\/revisions\/71243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71240"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}