{"id":71361,"date":"2025-01-27T12:15:11","date_gmt":"2025-01-27T15:15:11","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71361"},"modified":"2025-01-27T12:15:12","modified_gmt":"2025-01-27T15:15:12","slug":"entidades-da-carne-marcam-presenca-no-maior-churrasco-a-beira-mar-do-mundo","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/entidades-da-carne-marcam-presenca-no-maior-churrasco-a-beira-mar-do-mundo\/","title":{"rendered":"Entidades da carne marcam presen\u00e7a no maior churrasco a beira mar do mundo"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Cortes de b\u00fafalo, Hereford e Braford foram servidos no Paleta Atl\u00e2ntida em Xangri-L\u00e1 (RS)<\/em><\/p>\n<p>A 8\u00aa edi\u00e7\u00e3o do Paleta Atl\u00e2ntida, considerado o maior churrasco de beira de praia do mundo, mais uma vez teve a participa\u00e7\u00e3o de um grande p\u00fablico no evento que se estende num trecho de 4 quil\u00f4metros na beira da praia e re\u00fane assadores profissionais e amadores. A programa\u00e7\u00e3o inclui tamb\u00e9m shows, feiras, competi\u00e7\u00f5es esportivas e palestras.<\/p>\n<p>Um dos estandes mais concorridos foi o da Expointer e Secretaria da Agricultura onde se reuniram entidades como a Federa\u00e7\u00e3o Brasileira das Associa\u00e7\u00f5es de Criadores de Animais de Ra\u00e7a (Febrac) Associa\u00e7\u00e3o Ga\u00facha de Criadores de B\u00fafalos (Ascribu), Associa\u00e7\u00e3o Brasileira de Hereford e Braford (ABHB) e Conex\u00e3o Delta G. O p\u00fablico teve acesso a cortes de paleta de b\u00fafalo e de carnes Hereford e Braford.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-71363 aligncenter\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/31-1-400x272.jpg\" alt=\"\" width=\"400\" height=\"272\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/31-1-400x272.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/31-1-768x522.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/31-1-1536x1044.jpg 1536w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/31-1-2048x1393.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n<p>A presidente da Ascribu e vice-presidente da Febrac, Desire\u00e9 M\u00f6ller, avaliou como \u201cum grande sucesso\u201d a terceira participa\u00e7\u00e3o da Ascribu, que mais uma vez levou ao p\u00fablico a maciez e sucul\u00eancia da carne de b\u00fafalo ao Paleta Atl\u00e2ntida, bem como a segunda participa\u00e7\u00e3o da Febrac, onde foi poss\u00edvel mostrar a gen\u00e9tica de qualidade que se reflete na produ\u00e7\u00e3o de animais diferenciados que s\u00e3o colocados \u00e0 disposi\u00e7\u00e3o do consumidor. \u201c<em>A paleta de b\u00fafalo foi um grande sucesso, visto que a pe\u00e7a foi colocada na brasa \u00e0s oito horas da manh\u00e3 e cinco horas depois o corte estava esgotado<\/em>\u201d, revelou. Desire\u00e9 destacou ainda como positiva a participa\u00e7\u00e3o de entidades parceiras de produtores de prote\u00edna animal como Poll Dorset, Hereford, Braford, Devon, e outros parceiros como criadores de Cavalo Crioulo, Cavalo \u00c1rabe assim como representantes da Femers Melipolicultura Ga\u00facha, que cria produtos a base de mel das abelhas sem ferr\u00e3o.<\/p>\n<p>J\u00e1 a presidente da Conex\u00e3o Delta G e vice-presidente da ABHB, Clarissa Lopes Peixoto, qualificou o evento como espetacular e que superou as expectativas.<em> \u201cMuito al\u00e9m do que n\u00f3s esper\u00e1vamos, visto que decidimos participar nos \u00faltimos dias antes do evento\u201d<\/em>.<em> \"Para n\u00f3s \u00e9 muito gratificante estar aqui. Servimos um churrasco excelente, como n\u00e3o poderia ser diferente\u201d<\/em>, comemorou. Clarissa referiu a import\u00e2ncia das visitas recebidas e que al\u00e9m de degustarem e atestarem a qualidade das carnes Hereford e Braford tamb\u00e9m foram encontros de neg\u00f3cio, o chamado Network. <em>\u201cEsses contatos s\u00e3o fundamentais para expandirmos nossos neg\u00f3cios, mostrar o nosso trabalho e o melhoramento gen\u00e9tico que temos feito<\/em>\u201d, avaliou. Por fim, Clarissa revelou a expectativa de estar novamente no Paleta Atl\u00e2ntida em 2026 e que o evento seja ainda melhor.<\/p>\n<hr \/>\n<h6><strong>AgroEffective | Assessoria de Comunica\u00e7\u00e3o da Federa\u00e7\u00e3o Brasileira das Associa\u00e7\u00f5es de Criadores de Animais de Ra\u00e7a (Febrac) | Assessoria de Comunica\u00e7\u00e3o da Associa\u00e7\u00e3o Ga\u00facha de Criadores de B\u00fafalos (Ascribu) | Assessoria de Comunica\u00e7\u00e3o da Conex\u00e3o Delta G | Assessoria de Comunica\u00e7\u00e3o da Associa\u00e7\u00e3o Brasileira de Hereford e Braford (ABHB) |\u00a0Fotos: Nestor Tipa J\u00fanior\/AgroEffective | Texto: Artur Chagas\/AgroEffective<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cortes de b\u00fafalo, Hereford e Braford foram servidos no Paleta Atl\u00e2ntida em Xangri-L\u00e1 (RS) A 8\u00aa edi\u00e7\u00e3o do Paleta Atl\u00e2ntida, considerado o maior churrasco de beira de praia do mundo, mais uma vez teve a participa\u00e7\u00e3o de um grande p\u00fablico no evento que se estende num trecho de 4 quil\u00f4metros na beira da praia e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71361"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71361\/revisions"}],"predecessor-version":[{"id":71364,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71361\/revisions\/71364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71362"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}